{"id":2098,"date":"2021-04-15T17:59:00","date_gmt":"2021-04-15T14:59:00","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/"},"modified":"2021-04-15T17:59:08","modified_gmt":"2021-04-15T14:59:08","slug":"biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/","title":{"rendered":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones"},"content":{"rendered":"<p>Joe Biden, este mi\u00e9rcoles en la Casa Blanca.Andrew Harnik \/ POOL \/ EFELa Administraci\u00f3n que preside el dem\u00f3crata Joe Biden ha anunciado este jueves una amplia bater\u00eda de sanciones contra Rusia en represalia por su intromisi\u00f3n en intereses estadounidenses a trav\u00e9s del ciberespionaje. V\u00eda orden ejecutiva, las nuevas medidas de EE UU castigar\u00e1n, entre otros asuntos, la interferencia de Mosc\u00fa en las elecciones presidenciales de 2020 y el reciente ataque cibern\u00e9tico a la empresa SolarWinds, pero tambi\u00e9n la supuesta oferta de Mosc\u00fa a los talibanes para que atentaran contra tropas de EEUU en Afganist\u00e1n. El Departamento del Tesoro ha emitido otra directiva que proh\u00edbe a las instituciones financieras estadounidenses comprar deuda p\u00fablica del banco central ruso a partir del pr\u00f3ximo mes de junio.Las sanciones del Tesoro estadounidense, dirigidas a la l\u00ednea de flotaci\u00f3n de la econom\u00eda rusa, afectan a 16 entidades y 16 individuos e incluyen la expulsi\u00f3n de una decena de empleados de la Embajada rusa en Washington, funcionarios de inteligencia incluidos, por \u201cintentos dirigidos por el Gobierno ruso para influir en las elecciones presidenciales de EE UU de 2020 y otros actos de desinformaci\u00f3n e interferencia\u201d.En concreto, la Casa Blanca acusa formalmente al Servicio de Espionaje Exterior de Rusia (SVR) de haber perpetrado el ciberataque masivo que comenz\u00f3 en 2019 y penetr\u00f3 en los sistemas inform\u00e1ticos de la Administraci\u00f3n estadounidense y de grandes compa\u00f1\u00edas mediante un programa de SolarWinds. Hasta ahora, las especulaciones sobre la autor\u00eda del jaqueo se manten\u00edan en el terreno de las sospechas, pero ahora, por vez primera, Washington dice estar \u201ctotalmente seguro\u201d de la acci\u00f3n del SVR.Entre los individuos objeto de las sanciones figura un peso pesado del Kremlin, Alex\u00e9i Gromov, miembro de la Administraci\u00f3n Presidencial. \u201cPutin ha alimentado una red de fieles que mediante sus negocios il\u00edcitos han contribuido a las acciones para socavar las elecciones de 2020 y para darle a Rusia una cobertura plausible en su campa\u00f1a de desinformaci\u00f3n. Esta red incluye al primer subjefe de personal de la Administraci\u00f3n Presidencial, Alex\u00e9i Gromov\u201d, explica el comunicado del Tesoro.Estas duras medidas llegan despu\u00e9s de una conversaci\u00f3n telef\u00f3nica entre Biden y su hom\u00f3logo ruso, Vlad\u00edmir Putin, el pasado martes. El dem\u00f3crata advirti\u00f3 a Putin que \u201cactuar\u00e1 con firmeza\u201d en defensa de sus intereses nacionales y propuso un encuentro en un pa\u00eds tercero que, a la vista de la bater\u00eda de sanciones, pende de un hilo. La llamada fue la segunda que se ha hecho p\u00fablica desde que Biden lleg\u00f3 al poder el pasado 20 de enero. El presidente de EE UU tambi\u00e9n reclam\u00f3 al mandatario ruso que \u201crebaje las tensiones\u201d con Ucrania y le expres\u00f3 su \u201cpreocupaci\u00f3n\u201d por la movilizaci\u00f3n militar rusa en la frontera con ese pa\u00eds.En el comunicado de la Casa Blanca que anuncia la imposici\u00f3n de sanciones, Washington acusa tambi\u00e9n a Mosc\u00fa, en una referencia que parece apuntar directamente a la crisis en el este de Ucrania, de \u201csocavar la seguridad en pa\u00edses y regiones importantes para la seguridad nacional de Estados Unidos; y violar principios bien establecidos del derecho internacional, incluido el respeto por la integridad territorial de los Estados, [que] constituyen una amenaza inusual y extraordinaria para la seguridad nacional, la pol\u00edtica exterior y la econom\u00eda de Estados Unidos\u201d.Junto con el Reino Unido, Australia, Canad\u00e1 y la Uni\u00f3n Europea, Washington tambi\u00e9n sanciona a ocho personas y entidades en la \u00f3rbita del Kremlin por la ocupaci\u00f3n de la pen\u00ednsula de Crimea en 2014. \u201cLa comunidad transatl\u00e1ntica se mantiene unida para apoyar a Ucrania contra las provocaciones unilaterales rusas a lo largo de la L\u00ednea de Contacto en el este de Ucrania\u201d, explica el comunicado.Un reciente informe no clasificado del espionaje estadounidense asegura que Putin autoriz\u00f3 campa\u00f1as de influencia destinadas a da\u00f1ar la candidatura del presidente Biden durante las elecciones de 2020 e impulsar la del republicano Donald Trump, seg\u00fan la CBS. \u201cUn elemento clave de la estrategia de Mosc\u00fa en este ciclo electoral fue el uso de representantes vinculados a la inteligencia rusa para impulsar narrativas de influencia, incluidas acusaciones enga\u00f1osas o infundadas contra el presidente Biden\u201d, seg\u00fan el informe difundido por la Oficina del Director de Inteligencia Nacional.M\u00e1s informaci\u00f3nEl a\u00f1o pasado, los investigadores de ciberseguridad de Estados Unidos identificaron un pirateo de un programa inform\u00e1tico llamado SolarWinds, una intrusi\u00f3n que dio a los piratas acceso a 18.000 redes inform\u00e1ticas gubernamentales y privadas. El servicio de inteligencia estadounidense ha identificado a los piratas inform\u00e1ticos en Rusia como responsables del ataque, los cuales obtuvieron acceso a archivos digitales de varias agencias gubernamentales de EE UU, incluidos los Departamentos del Tesoro, Justicia y Estado. El Tesoro sanciona tambi\u00e9n a seis compa\u00f1\u00edas tecnol\u00f3gicas rusas, asociadas a los servicios de inteligencia, por sus \u201cactividades nocivas\u201d.Biden orden\u00f3 en su primer d\u00eda en el cargo una revisi\u00f3n de las relaciones con Rusia, inicialmente contra funcionarios rusos por el envenenamiento del l\u00edder opositor Alex\u00e9i Navalni. Biden elev\u00f3 la tensi\u00f3n cuando en una entrevista en televisi\u00f3n respondi\u00f3 afirmativamente a una pregunta que le planteaba si Putin es un asesino, en referencia al intento de acabar con el disidente. En el pliego de acusaciones que respaldan las sanciones anunciadas este jueves, la Casa Blanca incluye \u201cllevar a cabo actividades extraterritoriales dirigidas a disidentes o periodistas\u201d.Entre \u201clas acciones que ha emprendido el Gobierno ruso contra nuestra soberan\u00eda e intereses\u201d, indica la Casa Blanca, figura la supuesta oferta de Rusia a los talibanes para que atentaran contra tropas de EE UU en Afganist\u00e1n, desvelada el pasado a\u00f1o por el diario The New York Times. No obstante, \u201cdado lo delicado del asunto, que compromete la seguridad y el bienestar de nuestros soldados\u201d, se mantendr\u00e1n abiertos los canales diplom\u00e1ticos y de inteligencia para investigar lo sucedido. Esta semana el mandatario dem\u00f3crata ha anunciado la retirada de las tropas del pa\u00eds asi\u00e1tico, tras 20 a\u00f1os de despliegue.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-04-15\/biden-se-dispone-a-imponer-duras-sanciones-a-rusia-por-los-ciberataques-y-la-injerencia-en-las-elecciones.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joe Biden, este mi\u00e9rcoles en la Casa Blanca.Andrew Harnik \/ POOL \/ EFELa Administraci\u00f3n que preside el dem\u00f3crata Joe Biden ha anunciado este jueves una amplia bater\u00eda de sanciones contra Rusia en represalia por su intromisi\u00f3n en intereses estadounidenses a trav\u00e9s del ciberespionaje. V\u00eda orden ejecutiva, las nuevas medidas de EE UU castigar\u00e1n, entre otros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Joe Biden, este mi\u00e9rcoles en la Casa Blanca.Andrew Harnik \/ POOL \/ EFELa Administraci\u00f3n que preside el dem\u00f3crata Joe Biden ha anunciado este jueves una amplia bater\u00eda de sanciones contra Rusia en represalia por su intromisi\u00f3n en intereses estadounidenses a trav\u00e9s del ciberespionaje. V\u00eda orden ejecutiva, las nuevas medidas de EE UU castigar\u00e1n, entre otros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-15T14:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T14:59:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones\",\"datePublished\":\"2021-04-15T14:59:00+00:00\",\"dateModified\":\"2021-04-15T14:59:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/\"},\"wordCount\":1055,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/\",\"name\":\"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg\",\"datePublished\":\"2021-04-15T14:59:00+00:00\",\"dateModified\":\"2021-04-15T14:59:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/","og_locale":"es_ES","og_type":"article","og_title":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World","og_description":"Joe Biden, este mi\u00e9rcoles en la Casa Blanca.Andrew Harnik \/ POOL \/ EFELa Administraci\u00f3n que preside el dem\u00f3crata Joe Biden ha anunciado este jueves una amplia bater\u00eda de sanciones contra Rusia en represalia por su intromisi\u00f3n en intereses estadounidenses a trav\u00e9s del ciberespionaje. V\u00eda orden ejecutiva, las nuevas medidas de EE UU castigar\u00e1n, entre otros [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/","og_site_name":"Hot News in World","article_published_time":"2021-04-15T14:59:00+00:00","article_modified_time":"2021-04-15T14:59:08+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones","datePublished":"2021-04-15T14:59:00+00:00","dateModified":"2021-04-15T14:59:08+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/"},"wordCount":1055,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/","url":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/","name":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg","datePublished":"2021-04-15T14:59:00+00:00","dateModified":"2021-04-15T14:59:08+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Biden-impone-duras-sanciones-a-Moscu-por-los-ciberataques-y-scaled.jpg","width":2560,"height":1440,"caption":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/biden-impone-duras-sanciones-a-moscu-por-los-ciberataques-y-la-injerencia-en-las-elecciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Biden impone duras sanciones a Mosc\u00fa por los ciberataques y la injerencia en las elecciones"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2098"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2098\/revisions"}],"predecessor-version":[{"id":2100,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2098\/revisions\/2100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2099"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}