{"id":2113,"date":"2021-04-16T23:57:26","date_gmt":"2021-04-16T20:57:26","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/"},"modified":"2021-04-16T23:57:32","modified_gmt":"2021-04-16T20:57:32","slug":"madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/","title":{"rendered":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas"},"content":{"rendered":"<p>La presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, ha insistido este viernes en la pol\u00e9mica de la falta de vacunas que agita desde hace semanas, de la que culpa al presidente del Gobierno, Pedro S\u00e1nchez. \u201cNo sabemos cu\u00e1ntas dosis vamos a recibir por parte del Gobierno la semana que viene. Y, como no lleguen m\u00e1s, vamos a tener que a paralizar la vacunaci\u00f3n en los grandes centros\u201d, ha dicho la candidata del PP a la reelecci\u00f3n en los comicios auton\u00f3micos del 4-M. Una portavoz del Ministerio de Sanidad ha asegurado este viernes que no hay ning\u00fan problema con la llegada de vacunas para la semana que viene y que Madrid tendr\u00e1 las previstas: el lunes llegar\u00e1 una partida de Pfizer, el martes, otra de AstraZeneca, y a lo largo de la semana lo har\u00e1 un env\u00edo de Moderna. \u201cSi de m\u00ed dependiera la vacuna, el 100% de la gente en Madrid ya estar\u00eda protegida\u201d, ha subrayado la presidenta madrile\u00f1a, sin dejar muy claro a qu\u00e9 se refer\u00eda con esa frase. Un portavoz de Sanidad ha aclarado m\u00e1s tarde a lo que D\u00edaz Ayuso alud\u00eda: \u201cA que tenemos capacidad para aumentar el ritmo\u201d.Israel, el pa\u00eds del mundo con m\u00e1s poblaci\u00f3n vacunada no llega al 60% de poblaci\u00f3n vacunada y ning\u00fan pa\u00eds de la Uni\u00f3n Europea supera el 15%. En Espa\u00f1a, Madrid es una de las comunidades que menos poblaci\u00f3n ha inmunizado, tanto si se cuenta solo una dosis como la pauta completa, en ambos casos claramente por debajo de la media nacional. Mientras, la comunidad alcanza una incidencia acumulada de 372 casos por cada 100.000 habitantes en 14 d\u00edas y la presi\u00f3n crece en los hospitales, como ha admitido el viceconsejero de Salud P\u00fablica y plan covid-19, Antonio Zapatero, aunque ha indicado que ese par\u00e1metro a siete d\u00edas, \u201cque marca la tendencia, se est\u00e1 estabilizando y eso es una buena se\u00f1al\u201d.Aun as\u00ed, el viceconsejero ha reconocido que no prev\u00e9n que los datos mejoren durante las dos pr\u00f3ximas semanas: \u201cHay una leve tendencia ascendente en la incidencia acumulada [casos por cada 100.000 habitantes en los \u00faltimos 14 d\u00edas], algo que ocurre en Madrid y en el resto de Espa\u00f1a, pr\u00e1cticamente en todas las comunidades aut\u00f3nomas, consecuencia de los d\u00edas festivos de Semana Santa y el cierre perimetral. Somos conscientes de que las dos pr\u00f3ximas semanas esta tendencia seguir\u00e1\u201d. Mientras, la presidenta madrile\u00f1a ha reiterado en una entrevista en Tele 5 que en los pr\u00f3ximos d\u00edas van a bajar los contagios.Cerradas 17 zonas b\u00e1sicas de salud y tres municipiosIncidencia en las zonas b\u00e1sicas y en los municipios de MadridEn esa contradicci\u00f3n, la Comunidad de Madrid ha decidido no hacer ning\u00fan cambio en las restricciones pese a la subida de contagios, ingresos hospitalarios \u2014de forma m\u00e1s moderada\u2014 y ocupaci\u00f3n de las UCI que viene registr\u00e1ndose desde hace m\u00e1s de dos semanas. Este viernes hay 2.016 pacientes en planta y 508 en las unidades de cr\u00edticos \u2014<a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/SOMIAMA1\/status\/1382746057742897153?s=20\">533, seg\u00fan la Sociedad de Medicina Intensiva de Madrid<\/a> (Somiama), lo que supone estar por encima del 113% de su capacidad estructural, es decir, sin quir\u00f3fanos o unidades de reanimaci\u00f3n\u2014, seg\u00fan ha cifrado el viceconsejero en la rueda de prensa de la Consejer\u00eda de Sanidad de los viernes.La regi\u00f3n, con una elevada transmisi\u00f3n en la que hasta un 85% de las nuevas infecciones corresponden a la variante brit\u00e1nica, tiene activas las mismas medidas que hab\u00eda cuando la incidencia acumulada comenz\u00f3 a descender en febrero. A mediados de ese mes, cuando la incidencia acumulada a 14 d\u00edas estaba disparada hasta los 625 \u2014por encima del doble de lo que el ministerio marca como el m\u00e1s alto umbral de riesgo, 250\u2014, y cuando las unidades de cr\u00edticos registraban un 152% de su capacidad estructural, con 715 graves en sus camas, seg\u00fan los datos de Somiama, el Ejecutivo regional retras\u00f3 una hora el inicio del toque de queda, que pas\u00f3 de las 22.00 a las 23.00, y el cierre de establecimientos, que pod\u00edan empezar a abrir hasta las diez de la noche. Una \u201cflexibilizaci\u00f3n\u201d, lo llam\u00f3 Zapatero, que hab\u00eda comenzado una semana antes, ampliando los comensales de cuatro a seis en las terrazas.El Gobierno regional insiste en los perimetrajes por zonas b\u00e1sicas de salud como \u201cmedida quir\u00fargica\u201d \u2014\u00e1reas que corresponden a la poblaci\u00f3n que atienden los centros de salud y cuyos resultados tras meses de puesta en marcha no han demostrado ninguna efectividad\u2014; al tiempo que continuar\u00e1 con el m\u00e1ximo de seis personas en terraza y cuatro en el interior de la hosteler\u00eda, que jam\u00e1s ha cerrado; la obligatoriedad de la mascarilla para clientes cuando no est\u00e9n bebiendo o comiendo y de la ventilaci\u00f3n para los due\u00f1os de los establecimientos \u2014obligaci\u00f3n que comenz\u00f3 tambi\u00e9n a mediados de febrero, hasta entonces era solo una recomendaci\u00f3n \u2014; y los aforos al 50%. La apuesta ahora es la campa\u00f1a de vacunaci\u00f3n.1,6 millones de dosis inoculadas\u201cM\u00e1s del 8% de la poblaci\u00f3n ha recibido ya las dos dosis\u201d, ha informado Zapatero, que ha cifrado en 1,6 millones las dosis que se han inyectado hasta este jueves por la tarde. Ambulatorios, hospitales, WiZink Center, Wanda Metropolitano y Hospital Isabel Zendal son los espacios donde se est\u00e1 realizando la inmunizaci\u00f3n. Sin embargo, el Ejecutivo regional se plantea la posibilidad de cerrar la pr\u00f3xima semana los \u00faltimos tres lugares, los puntos de vacunaci\u00f3n masiva, si las \u00fanicas vacunas que les llegan son las 157.900 dosis de Pfizer que, hasta ahora, el Gobierno central les ha comunicado.Una portavoz del ministerio ha asegurado este viernes que no hay ning\u00fan problema con la llegada de vacunas para la semana que viene. \u201cEl martes les llega AstraZeneca y Moderna toca cada 15 d\u00edas, es decir, esta semana\u201d. Adem\u00e1s de esas entregas, la comunidad mantiene un stock esta semana de 29.000 dosis de Moderna, \u201cno llegar\u00eda a 3.000 de AstraZeneca y alrededor de 100.000 de Pfizer\u201d, ha enumerado la directora de Salud P\u00fablica.Este mi\u00e9rcoles, en el Consejo Interterritorial con el Ministerio de Sanidad y el resto de autonom\u00edas, el consejero de Madrid, Enrique Ruiz Escudero, hizo tres peticiones que no ser\u00edan factibles si se suspendiera la vacunaci\u00f3n en esos puntos masivos: ampliar el l\u00edmite por encima de los 69 a\u00f1os para la vacuna de AstraZeneca; permitir que, de manera voluntaria, los menores de 60 a\u00f1os puedan recibir AstraZeneca y Janssen, y estudiar la priorizaci\u00f3n de primeras dosis, alargando el plazo para inyectar la segunda. \u201cYa que hay evidencia cient\u00edfica de que con la primera dosis de Pfizer y Moderna se alcanza una inmunidad del 75%-80%, y nuestros t\u00e9cnicos apuestan por llegar a los 42 d\u00edas para las segundas dosis\u201d, ha explicado Zapatero.Mientras esa cuesti\u00f3n queda en el aire, Madrid mantendr\u00e1 la pauta normal, ambas dosis con 21 y 28 d\u00edas entre la primera y la segunda para la poblaci\u00f3n incluida en el grupo de riesgo 7, con Pfizer y Moderna. Adem\u00e1s, este martes se pondr\u00e1 en marcha un nuevo sistema de citaci\u00f3n electr\u00f3nica para vacunarse que consistir\u00e1 en la posibilidad de que los propios ciudadanos puedan llamar a su centro de salud \u201cpara establecer la cita en el tramo horario que les venga mejor\u201d, ha explicado Zapatero. Pero no para todos. Este modelo de citaci\u00f3n ser\u00e1 en los centros de salud para los mayores de 75 a\u00f1os y de 70 a 74 en cuatro hospitales: La Paz, Gregorio Mara\u00f1\u00f3n, 12 de Octubre y la Fundaci\u00f3n Jim\u00e9nez D\u00edaz.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/espana\/madrid\/2021-04-16\/madrid-mantiene-las-restricciones-y-advierte-de-un-posible-cierre-de-los-puntos-de-vacunacion-masiva.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, ha insistido este viernes en la pol\u00e9mica de la falta de vacunas que agita desde hace semanas, de la que culpa al presidente del Gobierno, Pedro S\u00e1nchez. \u201cNo sabemos cu\u00e1ntas dosis vamos a recibir por parte del Gobierno la semana que viene. Y, como no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"La presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, ha insistido este viernes en la pol\u00e9mica de la falta de vacunas que agita desde hace semanas, de la que culpa al presidente del Gobierno, Pedro S\u00e1nchez. \u201cNo sabemos cu\u00e1ntas dosis vamos a recibir por parte del Gobierno la semana que viene. Y, como no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T20:57:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-16T20:57:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas\",\"datePublished\":\"2021-04-16T20:57:26+00:00\",\"dateModified\":\"2021-04-16T20:57:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/\"},\"wordCount\":1324,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/\",\"name\":\"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg\",\"datePublished\":\"2021-04-16T20:57:26+00:00\",\"dateModified\":\"2021-04-16T20:57:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg\",\"caption\":\"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/","og_locale":"es_ES","og_type":"article","og_title":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World","og_description":"La presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, ha insistido este viernes en la pol\u00e9mica de la falta de vacunas que agita desde hace semanas, de la que culpa al presidente del Gobierno, Pedro S\u00e1nchez. \u201cNo sabemos cu\u00e1ntas dosis vamos a recibir por parte del Gobierno la semana que viene. Y, como no [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/","og_site_name":"Hot News in World","article_published_time":"2021-04-16T20:57:26+00:00","article_modified_time":"2021-04-16T20:57:32+00:00","og_image":[{"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas","datePublished":"2021-04-16T20:57:26+00:00","dateModified":"2021-04-16T20:57:32+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/"},"wordCount":1324,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/","url":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/","name":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg","datePublished":"2021-04-16T20:57:26+00:00","dateModified":"2021-04-16T20:57:32+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/Madrid-agita-la-polemica-de-la-falta-de-vacunas-y.jpg","caption":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/madrid-agita-la-polemica-de-la-falta-de-vacunas-y-culpa-a-sanchez-pese-a-que-la-semana-que-viene-llegaran-las-previstas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Madrid agita la pol\u00e9mica de la falta de vacunas y culpa a S\u00e1nchez pese a que la semana que viene llegar\u00e1n las previstas"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2113"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2113\/revisions"}],"predecessor-version":[{"id":2115,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2113\/revisions\/2115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}