{"id":2269,"date":"2021-04-30T03:49:31","date_gmt":"2021-04-30T00:49:31","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/"},"modified":"2021-04-30T03:49:34","modified_gmt":"2021-04-30T00:49:34","slug":"el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/","title":{"rendered":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga"},"content":{"rendered":"<p>El Real Madrid lo volvi\u00f3 a hacer. Abrazado a la \u00e9pica, el conjunto de Laso volvi\u00f3 a dejar grogui al Efes con otro arrebato febril en el tramo final del partido que le llev\u00f3 a una nueva remontada inveros\u00edmil despu\u00e9s de verse 16 puntos abajo (13 de desventaja en el minuto 33). Garuba, herc\u00faleo e incansable (24 puntos, 12 rebotes y 30 de valoraci\u00f3n), Carroll, certero como en sus grandes noches (20 puntos), y la pareja Abalde-Rudy, s\u00f3lidos e hiperactivos, lideraron otra haza\u00f1a madridista para empatar la eliminatoria de cuartos de la Euroliga (2-2).TODOS LOS PARTIDOS DE LA SERIEDispuesto a morir con las botas puestas, el Madrid jug\u00f3 el \u00faltimo cuarto con el coraz\u00f3n en la boca. Caminando por la cornisa, con Garuba exprimiendo su umbral de agon\u00eda, y con un car\u00e1cter irreductible, los de Laso volvieron a escapar de las catacumbas para igualar la eliminatoria y ganarse otro viaje a Turqu\u00eda. Perd\u00edan los blancos por 59-72 a 7m 20s del final y, en ese instante, comenzaron a escribir otra de sus leyendas de pasi\u00f3n. Otro parcial memorable hasta el 74-73 primero, a falta de 1m 49s, y de ah\u00ed al 82-76 final. Ning\u00fan equipo ha remontado un 2-0 en contra en este formato de cruces de la Euroliga, pero el Efes vuelve a Estambul con la cara demudada y la jindama en el cuerpo. Mientras, el Madrid sale del envite con su ideario competitivo hormigonado. \u201cEra otra final. Y nuestra mentalidad ha cambiado respecto a los dos primeros partidos\u201d, explic\u00f3 despu\u00e9s Carroll. \u201cEmpezamos a creer, a tener confianza, y recuperamos el esp\u00edritu de lucha\u201d, complet\u00f3 el escolta de Wyoming. \u201cSab\u00edamos que iba a ser dif\u00edcil, pero hemos demostrado un adn y un coraz\u00f3n que nos ha permitido forzar el quinto partido. Ah\u00ed estamos, a fuerza de seguir luchando. Estamos m\u00e1s cerca de ser campeones de Europa. Con lo lejos que parece y lo cerca que est\u00e1\u201d, ambicion\u00f3 Laso.Como si fuera la continuaci\u00f3n de los cinco minutos finales del tercer partido, el Madrid comenz\u00f3 el cuarto asalto de la eliminatoria barnizado de confianza. Aplicado e intenso en la defensa zonal que volvi\u00f3 a cortocircuitar al Efes. Con Garuba y Tyus activando las turbinas, con la potencia de Abalde, la gracilidad de Carroll y el nervio de Aloc\u00e9n poniendo firmeza y dinamismo al plan. Acertado y voraz, el conjunto blanco firm\u00f3 otros cinco minutos primorosos ante un rival desconcertado. As\u00ed lleg\u00f3 un contundente parcial de 17-0, con seis asistencias, tres robos y seis p\u00e9rdidas provocadas, con 11 puntos de Carroll y cinco de Garuba, con paladas de fe ante un enemigo titubeante. De nuevo sin Tavares, por tercer partido consecutivo, con Thompkins mermado, y con Felipe en lugar de Vukcevic en la rotaci\u00f3n, el Madrid afil\u00f3 el orgullo para estirar la batalla. Pero el Efes no tard\u00f3 en despertar y convirti\u00f3 el arre\u00f3n blanco en un espejismo.Los gritos de Ataman y los puntos de Simon reactivaron progresivamente a un Efes hipotenso, pero seguro de su talento. La paciencia y la irrupci\u00f3n de Larkin y Beaubois sirvieron al conjunto turco para enderezar el rumbo en un santiam\u00e9n. Pasada la efervescencia madridista el Efes descifr\u00f3 la defensa zonal, afin\u00f3 la punter\u00eda y encontr\u00f3 un cargamento de puntos que le rescat\u00f3 r\u00e1pidamente del div\u00e1n, con otro parcial de vuelta de 2-21, con ocho puntos de Larkin (19-21, m. 11). Fue el inicio de la tormenta turca.El chaparr\u00f3n de triples del Efes creci\u00f3 hasta un 8 de 10 en ese tramo (4 de 4 para Beaubois). La s\u00edstole madridista se qued\u00f3 muy corta ante la di\u00e1stole rival. El Madrid pas\u00f3 de surfear la ola a ser arrollado por ella. El quinto triple sin fallo de Beaubois (19 puntos y tres asistencias en menos de 15 minutos) y el primero de Micic dejaron el balance de la sacudida en un +16 para los suyos poco antes del viaje a los vestuarios (31-47, m. 19). La rotaci\u00f3n de p\u00edvots de Ataman consigui\u00f3 gripar durante un rato el incansable motor de Garuba y el Madrid fue perdiendo determinaci\u00f3n y precisi\u00f3n a partes iguales (10 p\u00e9rdidas al descanso; 16 al final). Pero mantuvo la fe.\u201dNo podemos esperar a que la Final Four venga a nosotros. Hay que ir a por ella\u201d, explic\u00f3 en la v\u00edspera Ataman, como espuela y reprimenda a los suyos por su pecado de suficiencia en el tercer episodio. La reanudaci\u00f3n med\u00eda la ambici\u00f3n del Efes para rematar la serie y la resiliencia madridista para seguir agarrado al clavo ardiendo que encontr\u00f3 en su \u00e9pico arrebato del martes. Y los de Laso, con el plan y el quinteto inicial, se ganaron otra vez el derecho a so\u00f1ar. Forzando de nuevo la m\u00e1quina, con ocho puntos de Garuba y siete de Carroll, los blancos tantearon el reenganche (51-55, m. 24). Al ver a los blancos por el retrovisor, volvi\u00f3 a acelerar el Efes (51-66). Durante unos instantes, cada equipo pareci\u00f3 competir contra s\u00ed mismo. El Madrid, exprimiendo sus fuerzas para dar sustento al coraje. Los de Ataman, despejando sus miedos para certificar su hambre de gloria. Nueve puntos de distancia entre sue\u00f1os antes de afrontar la recta de meta (57-66, m. 30). Tan lejos y tan cerca para unos y otros. Estir\u00f3 otro poco la cuerda el Efes (59-72, m. 33), pero triunf\u00f3 la memoria ganadora de los blancos, con un Garuba conmovedor en su entrega. El Madrid lo volvi\u00f3 a hacer. Un equipo capaz de reproducir su m\u00edstica incluso a puerta cerrada, que luchar\u00e1 hasta el final por hacerse un hueco en la Final Four de Colonia. All\u00ed donde nadie le esperaba despu\u00e9s de una temporada tortuosa y de los dos zarandeos iniciales en la eliminatoria. Pero habr\u00e1 quinto episodio en Estambul el pr\u00f3ximo martes 4 (19.30, DAZN).Puedes seguir a DEPORTES en Facebook y <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/elpais_deportes\">Twitter<\/a>, o apuntarte aqu\u00ed para recibir nuestra newsletter semanal.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/deportes\/2021-04-29\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Real Madrid lo volvi\u00f3 a hacer. Abrazado a la \u00e9pica, el conjunto de Laso volvi\u00f3 a dejar grogui al Efes con otro arrebato febril en el tramo final del partido que le llev\u00f3 a una nueva remontada inveros\u00edmil despu\u00e9s de verse 16 puntos abajo (13 de desventaja en el minuto 33). Garuba, herc\u00faleo e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"El Real Madrid lo volvi\u00f3 a hacer. Abrazado a la \u00e9pica, el conjunto de Laso volvi\u00f3 a dejar grogui al Efes con otro arrebato febril en el tramo final del partido que le llev\u00f3 a una nueva remontada inveros\u00edmil despu\u00e9s de verse 16 puntos abajo (13 de desventaja en el minuto 33). Garuba, herc\u00faleo e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T00:49:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T00:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1087\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga\",\"datePublished\":\"2021-04-30T00:49:31+00:00\",\"dateModified\":\"2021-04-30T00:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/\",\"name\":\"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg\",\"datePublished\":\"2021-04-30T00:49:31+00:00\",\"dateModified\":\"2021-04-30T00:49:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/04\\\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg\",\"width\":1500,\"height\":1087,\"caption\":\"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/","og_locale":"es_ES","og_type":"article","og_title":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World","og_description":"El Real Madrid lo volvi\u00f3 a hacer. Abrazado a la \u00e9pica, el conjunto de Laso volvi\u00f3 a dejar grogui al Efes con otro arrebato febril en el tramo final del partido que le llev\u00f3 a una nueva remontada inveros\u00edmil despu\u00e9s de verse 16 puntos abajo (13 de desventaja en el minuto 33). Garuba, herc\u00faleo e [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/","og_site_name":"Hot News in World","article_published_time":"2021-04-30T00:49:31+00:00","article_modified_time":"2021-04-30T00:49:34+00:00","og_image":[{"width":1500,"height":1087,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga","datePublished":"2021-04-30T00:49:31+00:00","dateModified":"2021-04-30T00:49:34+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/"},"wordCount":1009,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/","url":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/","name":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg","datePublished":"2021-04-30T00:49:31+00:00","dateModified":"2021-04-30T00:49:34+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/04\/El-Real-Madrid-abraza-de-nuevo-la-epica-en-la.jpg","width":1500,"height":1087,"caption":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/el-real-madrid-abraza-de-nuevo-la-epica-en-la-euroliga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Real Madrid abraza de nuevo la \u00e9pica en la Euroliga"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2269"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2269\/revisions"}],"predecessor-version":[{"id":2271,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2269\/revisions\/2271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2270"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}