{"id":2323,"date":"2021-05-04T16:35:42","date_gmt":"2021-05-04T13:35:42","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/"},"modified":"2021-05-04T16:35:47","modified_gmt":"2021-05-04T13:35:47","slug":"al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/","title":{"rendered":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico"},"content":{"rendered":"<p>Al menos 23 personas han muerto y m\u00e1s de 70 han resultado heridas tras derrumbarse la viga de un puente del metro de Ciudad de M\u00e9xico en la noche del lunes. Se trata de la mayor tragedia en la ciudad desde el terremoto de 2017. Alrededor de las 22.25 la estructura que soportaba uno de los tramos exteriores de la l\u00ednea 12 del metro se ha desplomado sobre una de las principales arterias al sureste de la capital. \u201cUna trabe [viga] se venci\u00f3 en el momento en el que iba pasando el tren\u201d, explic\u00f3 la jefa de Gobierno de la capital mexicana, Claudia Sheinbaum, desde el lugar del suceso hacia la medianoche. La ma\u00f1ana de este martes Sheinbaunm ha pedido desde la conferencia matutina del presidente evitar especulaciones y esperar el resultado del peritaje externo sobre el accidente. Andr\u00e9s Manuel L\u00f3pez Obrador ha prometido que la investigaci\u00f3n se llevar\u00e1 a cabo \u201csin miramientos de ninguna \u00edndole\u201d. El canciller, Marcelo Ebrard, responsable de la construcci\u00f3n de l\u00ednea 12 del metro durante su gesti\u00f3n como jefe de Gobierno de la ciudad (de 2006 a 2012), ha asegurado que se pondr\u00e1 \u201ca disposici\u00f3n de las autoridades\u201d. \u201cQuien act\u00faa con integridad no debe tenerle temor a nada\u201d, ha afirmado.La ca\u00edda del puente y de dos de los vagones del convoy sobre la carretera ha dejado atrapados a algunos veh\u00edculos y decenas de personas. El accidente se produjo en una ciudad que cuenta con uno de los metros m\u00e1s transitados del mundo: m\u00e1s de 5,5 millones de personas lo utilizan al d\u00eda como \u00fanica v\u00eda de transporte a sus casas y trabajos.El tren de la l\u00ednea 12 circulaba entre las estaciones de Olivos y Tezonco en el momento del accidente. Los vagones se precipitaron sobre los veh\u00edculos que pasaban por debajo del puente en la avenida Tl\u00e1huac, seg\u00fan las im\u00e1genes de las c\u00e1maras de seguridad p\u00fablicas, que captaron el momento del derrumbe. Los servicios de emergencia y personal de Protecci\u00f3n Civil, as\u00ed como miembros del Ej\u00e9rcito, se desplegaron en toda la zona, que fue acordonada ante el espanto de cientos de vecinos. En los \u00faltimos a\u00f1os, en diversas ocasiones, habitantes de la zona hab\u00edan denunciado la situaci\u00f3n de deterioro de algunas de las estructuras del metro en este punto de la ciudad tras el se\u00edsmo de 2017.Sheinbaum ha facilitado el balance de heridos que han tenido que ser ingresados: \u201cLamentablemente, hay 65 personas hospitalizadas. Siete est\u00e1n siendo intervenidas en quir\u00f3fano\u201d. Entre las v\u00edctimas hay menores de edad, seg\u00fan ha informado a los medios de comunicaci\u00f3n. Los hospitales del sur y sureste de la ciudad se hab\u00edan llenado de familiares buscando a sus hijos, esposos o hermanos en las listas que se fueron colgando a la puerta de algunos centros y compartido por redes sociales, pero no todos los heridos han sido identificados. La jefa del Gobierno ha se\u00f1alado: \u201cPor el momento, nuestra tarea principal es atender a las personas que est\u00e1n en los hospitales y a los familiares de las v\u00edctimas que lamentablemente fallecieron. La Fiscal\u00eda ha iniciado todas las investigaciones para poder conocer qu\u00e9 fue lo que ocurri\u00f3 en este incidente\u201d. A esa hora, el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, no se hab\u00eda manifestado sobre la peor tragedia de la capital en a\u00f1os.Ciudad de M\u00e9xico, una de las ciudades con m\u00e1s tr\u00e1fico de Am\u00e9rica Latina, tendr\u00e1 que lidiar con cortes en el transporte p\u00fablico y restricciones a la circulaci\u00f3n. Sheinbaum ha indicado: \u201cPermanece cerrada la l\u00ednea 12 del metro y operar\u00e1n 490 autobuses para cubrir el servicio\u201d.El derrumbe de un tramo de metro de Ciudad de M\u00e9xico, en im\u00e1genesUno de los momentos m\u00e1s angustiosos de la noche qued\u00f3 recogido en v\u00eddeo. En las im\u00e1genes, se pod\u00eda ver a un hombre atrapado en un coche rojo bajo los escombros del puente minutos despu\u00e9s del accidente. Las autoridades han asegurado que consiguieron rescatarlo con vida y que fue trasladado a un hospital. Hacia las dos de la madrugada, la informaci\u00f3n del Gobierno apuntaba a que no quedaban m\u00e1s supervivientes bajo los escombros, aunque los servicios de emergencia, apoyados por la Marina, estaban todav\u00eda comprobando que no hubiera nadie m\u00e1s atrapado. Las autoridades desplegaron una gr\u00faa para sostener el tren que qued\u00f3 en vilo al vencer la estructura del puente y permitir el trabajo de los rescatistas.Los heridos fueron trasladados a los principales hospitales de la zona, en Tl\u00e1huac e Iztapalapa, en el sur de la ciudad. La calle de ingreso al hospital Belisario Rold\u00e1n estaba completamente bloqueada por unas 50 ambulancias que llegaron al lugar con v\u00edctimas del accidente y por decenas de familiares buscando a los heridos. Mar\u00eda esperaba a las puertas del hospital novedades de su marido V\u00edctor, que volv\u00eda de trabajar en metro. Vio c\u00f3mo lo ingresaban en el centro en una camilla, con los pantalones rotos: \u201cHace una hora que no me dicen c\u00f3mo est\u00e1\u201d, cuenta la mujer llorando. La crisis a las puertas del hospital record\u00f3 a otras tr\u00e1gicas, como el terremoto de hace cuatro a\u00f1os.Sanitarios trasladan a un herido en el accidente. Hector Guerrero\u201c\u00a1R\u00f3mpelo con algo, g\u00fcey!\u201dY justo como hace cuatro a\u00f1os, los vecinos de la zona fueron los primeros que comenzaron a retirar los restos del puente de hormig\u00f3n para ayudar a los que estaban atrapados en los vagones. Las im\u00e1genes de un grupo de hombres abriendo con sus manos las puertas del metro recordaron el enorme ejemplo de solidaridad que dio M\u00e9xico al mundo tras la tragedia del sismo. \u201c\u00a1R\u00f3mpelo con algo, g\u00fcey!\u201d, gritaba un hombre que grababa a otros mientras forzaban la puerta para tratar de sacar a los heridos, minutos antes de que llegaran los equipos de rescate de la capital.A unos metros del siniestro, tres j\u00f3venes de la Brigada Rotario, una organizaci\u00f3n especializada en rescates desde hace m\u00e1s de 10 a\u00f1os, aguardaban frente a las vallas de acceso al lugar de la tragedia, pero las autoridades ya desplegadas en la zona les negaban el paso. \u201cLo que dicen es que ya hay riesgo de colapso en otra parte del puente\u201d, se\u00f1alaban. Al lugar acudi\u00f3 tambi\u00e9n un grupo de top\u00f3grafos forenses para evaluar los riesgos en la zona.Entre los heridos se encontraba Esmeralda Serrano, de 21 a\u00f1os, vecina del barrio. Sal\u00eda cojeando del per\u00edmetro policial, en pantal\u00f3n corto, con una venda en el muslo derecho y debajo una herida sangrante: \u201cYo andaba pasando por all\u00ed. Estaba saliendo de casa de unos amigos, iba a casa de mi mam\u00e1 y me cay\u00f3 una piedra bastante grande. Me hizo un hoyo en la pierna\u201d, contaba. Serrano recordaba mucho polvo. \u201cNo escuch\u00e9 nada, andaba con mis amigos. No s\u00e9 cu\u00e1nta gente quede ah\u00ed dentro. He escuchado que hab\u00eda dos beb\u00e9s cuando estuve ah\u00ed\u201d, a\u00f1ad\u00eda asustada.Claudia Sheinbaum ha asegurado que ya se ha abierto una investigaci\u00f3n para esclarecer el suceso y ha insistido en que se depurar\u00e1n responsabilidades. El secretario de Exteriores, Marcelo Ebrard, uno de los art\u00edfices de la l\u00ednea 12 del metro mientras fue jefe de Gobierno de la capital (de 2006 a 2012) ha lamentado el terrible accidente a trav\u00e9s de un mensaje en Twitter: \u201cLo ocurrido hoy es una terrible tragedia. Mi solidaridad a las v\u00edctimas y a sus familias\u201d. La ministra de Asuntos Exteriores de Espa\u00f1a, Arancha Gonz\u00e1lez Laya, ha trasladado este martes su \u201csolidaridad\u201d con los familiares de los fallecidos y afectados por la tragedia, a los que ha enviado \u201cun fuerte abrazo\u201d.Lo ocurrido hoy en el Metro es una terrible tragedia. Mi solidaridad a las v\u00edctimas y sus familias.Por supuesto deben investigarse causas y deslindarse responsabilidades. Me reitero a la entera disposici\u00f3n de las autoridades para contribuir en todo lo que sea necesario.\u2014 Marcelo Ebrard C. (@m_ebrard) <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/m_ebrard\/status\/1389443249815752704?ref_src=twsrc%5Etfw\">May 4, 2021<\/a><\/p>\n<p>La l\u00ednea 12, envuelta en esc\u00e1ndalosLa l\u00ednea 12 del metro, inaugurada en octubre de 2012, fue durante muchos meses motivo de orgullo de la izquierda mexicana, que presum\u00eda de una hist\u00f3rica inversi\u00f3n de 1.800 millones de d\u00f3lares y de que ofrec\u00eda servicio diario a casi medio mill\u00f3n de personas que antes no pod\u00edan cruzar r\u00e1pidamente una zona del sureste de la capital. Sin embargo, ya en 2014, se tuvo que suspender el servicio en 11 de las 20 estaciones que la conforman por \u201coscilaciones detectadas en las v\u00edas\u201d que pod\u00edan ocasionar un descarrilamiento.Durante la gesti\u00f3n del actual canciller, Marcelo Ebrard, entonces como dirigente del Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD), la construcci\u00f3n de esta l\u00ednea se vio envuelta en un esc\u00e1ndalo de corrupci\u00f3n que afect\u00f3 a m\u00e1s de 30 funcionarios. Inaugurada al filo de terminar su mandato, poco m\u00e1s de un a\u00f1o despu\u00e9s el funcionamiento fue suspendido por el nuevo alcalde, Miguel \u00c1ngel Mancera, aduciendo una serie de irregularidades y defectos que pon\u00edan en peligro a los pasajeros.La pol\u00e9mica supuso un duro golpe a la carrera de Ebrard. Su trayectoria ascendente se trunc\u00f3 a partir de aquello. En 2015, irrumpi\u00f3, altavoz en mano, en la C\u00e1mara de Diputados. Quer\u00eda hacerse escuchar en una sesi\u00f3n de la comisi\u00f3n parlamentaria que investigaba el uso de 26.000 millones de pesos de presupuesto, casi un 50% m\u00e1s del monto previsto, en una operaci\u00f3n en la que estuvieron involucradas grandes empresas como la mexicana ICA o la espa\u00f1ola CAF.La l\u00ednea 12 sigui\u00f3 siendo un quebradero de cabeza para los mandatarios hasta el Gobierno de Claudia Sheinbaum. Los vecinos de esta zona hab\u00edan alertado a las autoridades de que el temblor del 19 de septiembre de 2017 hab\u00eda afectado a la estructura del metro de forma visible, concretamente en el punto que se hundi\u00f3 este lunes, que en este tramo de la avenida Tl\u00e1huac circulaba a trav\u00e9s de un puente por el exterior. Las autoridades detectaron entonces un da\u00f1o en el coraz\u00f3n del puente: la columna 69, que sosten\u00eda uno de los tramos de la l\u00ednea, qued\u00f3 da\u00f1ada en la base, y el Sistema de Transporte Colectivo (SCT) orden\u00f3 su reparaci\u00f3n, para la que invirti\u00f3 tres meses de trabajo y 15 millones de pesos, seg\u00fan informaron las autoridades en enero de 2018.Im\u00e1genes de la ca\u00edda de un vag\u00f3n tras el desplome de un puente en la estaci\u00f3n de metro de Olivos. RSSuscr\u00edbase aqu\u00ed a la newsletter de EL PA\u00cdS M\u00e9xico y reciba todas las claves informativas de la actualidad de este pa\u00eds<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/mexico\/2021-05-04\/un-accidente-en-la-linea-12-de-metro-de-ciudad-de-mexico-deja-al-menos-50-heridos.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 23 personas han muerto y m\u00e1s de 70 han resultado heridas tras derrumbarse la viga de un puente del metro de Ciudad de M\u00e9xico en la noche del lunes. Se trata de la mayor tragedia en la ciudad desde el terremoto de 2017. Alrededor de las 22.25 la estructura que soportaba uno de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Al menos 23 personas han muerto y m\u00e1s de 70 han resultado heridas tras derrumbarse la viga de un puente del metro de Ciudad de M\u00e9xico en la noche del lunes. Se trata de la mayor tragedia en la ciudad desde el terremoto de 2017. Alrededor de las 22.25 la estructura que soportaba uno de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T13:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-04T13:35:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico\",\"datePublished\":\"2021-05-04T13:35:42+00:00\",\"dateModified\":\"2021-05-04T13:35:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/\"},\"wordCount\":1846,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/\",\"name\":\"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg\",\"datePublished\":\"2021-05-04T13:35:42+00:00\",\"dateModified\":\"2021-05-04T13:35:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World","og_description":"Al menos 23 personas han muerto y m\u00e1s de 70 han resultado heridas tras derrumbarse la viga de un puente del metro de Ciudad de M\u00e9xico en la noche del lunes. Se trata de la mayor tragedia en la ciudad desde el terremoto de 2017. Alrededor de las 22.25 la estructura que soportaba uno de [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/","og_site_name":"Hot News in World","article_published_time":"2021-05-04T13:35:42+00:00","article_modified_time":"2021-05-04T13:35:47+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico","datePublished":"2021-05-04T13:35:42+00:00","dateModified":"2021-05-04T13:35:47+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/"},"wordCount":1846,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/","url":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/","name":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg","datePublished":"2021-05-04T13:35:42+00:00","dateModified":"2021-05-04T13:35:47+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Al-menos-23-muertos-por-el-derrumbe-de-un-tramo.jpg","width":1200,"height":800,"caption":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-23-muertos-por-el-derrumbe-de-un-tramo-del-metro-de-ciudad-de-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Al menos 23 muertos por el derrumbe de un tramo del metro de Ciudad de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2323"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2323\/revisions"}],"predecessor-version":[{"id":2325,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2323\/revisions\/2325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2324"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}