{"id":2347,"date":"2021-05-06T17:10:23","date_gmt":"2021-05-06T14:10:23","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/"},"modified":"2021-05-06T17:10:32","modified_gmt":"2021-05-06T14:10:32","slug":"el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/","title":{"rendered":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma"},"content":{"rendered":"<p>Informadores del Ayuntamiento de Barcelona en la playa del Bogotell durante la presentaci\u00f3n del protocolo para el control del aforo de playas, este jueves.David Zorrakino  \/ Europa PressEl gabinete t\u00e9cnico de la Sala de lo Contencioso-Administrativo del Tribunal Supremo critica en un informe el decreto aprobado por el Gobierno que da a esta sala la \u00faltima palabra sobre las restricciones que puedan adoptar las comunidades para combatir el virus tras el estado de alarma. El escrito, de 12 p\u00e1ginas, desgrana dudas no solo procedimentales y de aplicaci\u00f3n de la reforma, tambi\u00e9n legales e incluso \u201cproblemas de constitucionalidad\u201d porque endosa a los tribunales decisiones pol\u00edticas. El texto advierte tambi\u00e9n de que si se multiplican los casos que lleguen al Supremo \u201cser\u00e1 muy dif\u00edcil cumplir\u201d el plazo de cinco d\u00edas que establece la norma aprobada por el Consejo de Ministros.M\u00e1s informaci\u00f3nEl informe elaborado por el gabinete t\u00e9cnico responde a la petici\u00f3n que le formul\u00f3 este mi\u00e9rcoles el presidente de la Sala de lo Contencioso, C\u00e9sar Tolosa, tras reunirse con los presidentes de las cuatro secciones de la sala. En el encuentro acordaron encargar un informe para disipar algunas dudas de aplicaci\u00f3n de la norma aprobada por el Consejo de Ministros y que entra en vigor el pr\u00f3ximo domingo. El gabinete t\u00e9cnico ha remitido este jueves a los magistrados de la sala un texto que presentan como una \u201cprimera nota de urgencia\u201d que podr\u00e1 ser \u201ccompletada o rectificada\u201d en los pr\u00f3ximos d\u00edas, cuando se haga una reflexi\u00f3n m\u00e1s sosegada.El informe se centra en cuestiones de car\u00e1cter puramente procesal, pero no esconde una cr\u00edtica de fondo al decreto del Gobierno. Entre otros aspectos, sugiere que el decreto del Gobierno presenta \u201cproblemas de constitucionalidad\u201d al situar a los tribunales \u201ccomo una suerte de copart\u00edcipes ejecutivos en el proceso de adopci\u00f3n de medidas administrativas, al modo de competencias administrativas compartidas\u201d. El texto advierte tambi\u00e9n de la \u201cposible insuficiencia o inadecuaci\u00f3n del rango de la norma empleada\u201d, el real decreto-ley, para regular una cuesti\u00f3n que, advierte el texto, \u201cincide en derechos fundamentales\u201d. Con todo, no entra en m\u00e1s detalles sobre los supuestos problemas de legalidad del decreto. \u201cAmbas cuestiones requieren de un estudio profundo que ahora no puede abordarse\u201d, explica el gabinete t\u00e9cnico en el informe.Donde s\u00ed se explaya es en el an\u00e1lisis sobre las dudas t\u00e9cnicas para aplicar la reforma legal. El texto se\u00f1ala que no queda claro si desaparece el tr\u00e1mite del recurso de reposici\u00f3n ante los tribunales superiores de justicia, un paso que ahora existe en los litigios contenciosos. El decreto estatal establece que este tr\u00e1mite \u201cno es requisito necesario\u201d, pero no dice \u2014\u201cy podr\u00eda haberlo dicho\u201d, apunta el gabinete t\u00e9cnico\u2014 que \u201cno proceder\u00e1\u201d este tipo de recurso. \u201cEl problema es que la norma, tan preocupada por establecer unos plazos procesales perentorios para este peculiar cauce procedimental, no fija un plazo espec\u00edfico ni para interponer ni para resolver ese posible recurso de reposici\u00f3n, que, se insiste, no excluye\u201d, se\u00f1ala el informe.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/sociedad\/2021-05-06\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informadores del Ayuntamiento de Barcelona en la playa del Bogotell durante la presentaci\u00f3n del protocolo para el control del aforo de playas, este jueves.David Zorrakino \/ Europa PressEl gabinete t\u00e9cnico de la Sala de lo Contencioso-Administrativo del Tribunal Supremo critica en un informe el decreto aprobado por el Gobierno que da a esta sala la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Informadores del Ayuntamiento de Barcelona en la playa del Bogotell durante la presentaci\u00f3n del protocolo para el control del aforo de playas, este jueves.David Zorrakino \/ Europa PressEl gabinete t\u00e9cnico de la Sala de lo Contencioso-Administrativo del Tribunal Supremo critica en un informe el decreto aprobado por el Gobierno que da a esta sala la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-06T14:10:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T14:10:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma\",\"datePublished\":\"2021-05-06T14:10:23+00:00\",\"dateModified\":\"2021-05-06T14:10:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/\"},\"wordCount\":555,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/\",\"name\":\"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg\",\"datePublished\":\"2021-05-06T14:10:23+00:00\",\"dateModified\":\"2021-05-06T14:10:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/","og_locale":"es_ES","og_type":"article","og_title":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World","og_description":"Informadores del Ayuntamiento de Barcelona en la playa del Bogotell durante la presentaci\u00f3n del protocolo para el control del aforo de playas, este jueves.David Zorrakino \/ Europa PressEl gabinete t\u00e9cnico de la Sala de lo Contencioso-Administrativo del Tribunal Supremo critica en un informe el decreto aprobado por el Gobierno que da a esta sala la [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/","og_site_name":"Hot News in World","article_published_time":"2021-05-06T14:10:23+00:00","article_modified_time":"2021-05-06T14:10:32+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma","datePublished":"2021-05-06T14:10:23+00:00","dateModified":"2021-05-06T14:10:32+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/"},"wordCount":555,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/","url":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/","name":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg","datePublished":"2021-05-06T14:10:23+00:00","dateModified":"2021-05-06T14:10:32+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Supremo-critica-en-un-informe-el-decreto-del-Gobierno-scaled.jpg","width":2560,"height":1707,"caption":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-critica-en-un-informe-el-decreto-del-gobierno-que-deja-en-sus-manos-las-restricciones-tras-el-estado-de-alarma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Supremo critica en un informe el decreto del Gobierno que deja en sus manos las restricciones tras el estado de alarma"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2347"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2347\/revisions"}],"predecessor-version":[{"id":2349,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2347\/revisions\/2349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2348"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}