{"id":2503,"date":"2021-05-19T21:43:48","date_gmt":"2021-05-19T18:43:48","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/"},"modified":"2021-05-19T21:43:52","modified_gmt":"2021-05-19T18:43:52","slug":"cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/","title":{"rendered":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas"},"content":{"rendered":"<p>Nuevos grupos de j\u00f3venes siguen intentando llegar a nado a las playas de Ceuta, pero cada vez nadan m\u00e1s lejos para evitar ser interceptados por la embarcaci\u00f3n de la Guardia Civil. Los agentes estaban a primera hora de la tarde de este mi\u00e9rcoles frente a un peque\u00f1o pe\u00f1\u00f3n a unos metros de la orilla observando a cuatro chicos que se hab\u00edan encaramado a la roca. Tambi\u00e9n este mi\u00e9rcoles, en torno a las 16.30, un grupo numeroso de personas logr\u00f3 entrar en suelo espa\u00f1ol aprovechando una neblina, pero tras esa llegada la afluencia de marroqu\u00edes ha cesado de nuevo.A la gran cifra de llegados desde el lunes \u2014entre 8.000 y 9.000 personas seg\u00fan una estimaci\u00f3n de las fuerzas de seguridad, pues no hay recuento oficial\u2014 hay que ir restando otra, creciente. Desde el mismo lunes y hasta las 13.00 de este mi\u00e9rcoles, 5.600 de quienes entraron irregularmente en la ciudad aut\u00f3noma han retornado a Marruecos.Aunque miles de esos retornos han sido, seg\u00fan el Ministerio del Interior, \u201crechazos en frontera\u201d, el eufemismo utilizado para las devoluciones en caliente, otros cientos \u2014cerca de 1.000 seg\u00fan fuentes militares en el terreno desde la madrugada de este martes\u2014, han emprendido la vuelta a casa voluntariamente. \u201cNo hay mayor disuasi\u00f3n para los que quieren a\u00fan entrar que ver a tanta gente volviendo\u201d, apunta una fuente de los cuerpos de seguridad. Ese millar incluye no solo a los reci\u00e9n llegados, sino tambi\u00e9n a las mujeres que dieron a luz en la ciudad y que quedaron atrapadas en el enclave espa\u00f1ol tras el cierre de fronteras dictado durante la pandemia. Este mi\u00e9rcoles han podido volver con sus beb\u00e9s a Marruecos.Al mismo tiempo, cientos de j\u00f3venes peregrinan este mi\u00e9rcoles hacia una puerta de la valla que conecta la playa del Tarajal con Fnideq (la antigua Castillejos) para volver a casa. Los chavales se lanzaron al mar entre el lunes y el martes con poco m\u00e1s que su tel\u00e9fono y unos cuantos dirhams en una bolsa. Bordearon el espig\u00f3n que separa Marruecos de Espa\u00f1a y pasaron horas deambulando por la calle. Tras uno o dos d\u00edas al raso, algunos sin comer, han decidido que el viaje se ha acabado. En la cola que organizan los militares para ordenar su salida, se repiten las mismas frases: \u201cEn Marruecos no hay nada\u201d, \u201cvine aqu\u00ed para buscarme la vida, pero tampoco hay nada\u201d, \u201cintent\u00e9 llegar a la Pen\u00ednsula, pero no lo consegu\u00ed\u201d.Fotogaler\u00eda: La crisis migratoria en CeutaCeuta vive en las \u00faltimas horas un movimiento inverso al que afront\u00f3 durante el lunes y el martes con la llegada de entre 8.000 y 9.000 personas, seg\u00fan los c\u00e1lculos de las fuerzas de seguridad. Desde el mismo lunes, 5.600 de quienes entraron irregularmente en la ciudad aut\u00f3noma han retornado. Miles de esos retornos han sido, seg\u00fan el Ministerio del Interior, \u201crechazos en frontera\u201d, el eufemismo utilizado para las devoluciones en caliente. Pero otros cientos, un n\u00famero indeterminado que no para de crecer desde el martes, han emprendido la vuelta a casa voluntariamente. \u201cNo hay mayor disuasi\u00f3n para los que quieren a\u00fan entrar que ver a tanta gente volviendo\u201d, apunta una fuente de los cuerpos de seguridad.Samira Ajbar, de 17 a\u00f1os, borde\u00f3 el espig\u00f3n junto a decenas chavales de su barrio la noche del domingo. Lo hizo tranquilamente, en chanclas y falda. No lo pens\u00f3 mucho, todos sus amigos se iban y ella se apunt\u00f3. \u201cEn Marruecos no hay nada, estamos destrozados\u201d, cuenta en la cola antes de acceder al puesto fronterizo. Cre\u00eda que al llegar a Ceuta como menor podr\u00eda quedarse en un centro de protecci\u00f3n, pero tras tres d\u00edas deambulando vio que no. \u201cEst\u00e1 todo lleno. Intentaron enga\u00f1arnos diciendo que podr\u00edamos ir al CETI [el Centro de Estancia Temporal para Inmigrantes], pero no nos dejaron entrar\u201d, afirma. Tras dos noches durmiendo al raso con sus amigos en los alrededores del puerto, vuelve a Fnideq (Castillejos).El grupo de militares que custodia el acceso este mi\u00e9rcoles lleva desde las 22.00 de este martes ordenando salidas de 20 en 20, pr\u00e1cticamente sin parar. Entre las 9.30 y las 10.00 han salido al menos 60 personas, la mayor\u00eda j\u00f3venes, pero tambi\u00e9n ni\u00f1os de unos 12 a\u00f1os y familias enteras. Los militares son ceut\u00edes y hablan dariya \u2015\u00e1rabe dialectal marroqu\u00ed\u2015 con los chavales que se acercan tranquilamente a la frontera con algunas bolsas con ropa y comida. Entre los que se colaron a nado aparecen tambi\u00e9n mujeres con maletas, trabajadoras transfronterizas que se vieron atrapadas en la ciudad tras el cierre del paso en marzo del a\u00f1o pasado y que, con esta apertura extraordinaria, han visto la oportunidad de volver a sus casas. Dos j\u00f3venes inmigrantes se protegen del fr\u00edo cerca de la playa de El Tarajal.Brais Lorenzo \/ EFEMohamed Tuitouijr, de 32 a\u00f1os, antes de la pandemia hab\u00eda intentado ya tres veces llegar a la Pen\u00ednsula \u2015una en patera y dos como poliz\u00f3n en un ferry\u2015 para encontrarse con su padre que vive en Madrid. No lo consigui\u00f3 y cuando se enter\u00f3 de que las fuerzas de seguridad marroqu\u00edes estar\u00edan de brazos cruzados vio de nuevo la oportunidad. \u201cLlevo desde que comenz\u00f3 la pandemia sin trabajar, en Marruecos estamos maltratados\u201d, cuenta. Se lanz\u00f3 al mar el lunes, con la esperanza de colarse despu\u00e9s en un barco rumbo a la Pen\u00ednsula. \u201cFui al puerto, pero me echaron y llevo desde el lunes durmiendo en la calle\u201d, explica. Los vecinos le ayudaron con ropa y comida porque con sus dirhams en el bolsillo no pudo comprarse ni una botella de agua.A pesar de los cientos de salidas, Ceuta no ha recuperado la normalidad. A\u00fan hay miles de personas en la ciudad, alojadas en casas, en las naves habilitadas para la emergencia, durmiendo bajo los puentes o deambulando por las calles. Este mi\u00e9rcoles algunos parques de Ceuta amanec\u00edan con decenas de personas en sus fuentes ase\u00e1ndose y los alrededores de las tiendas de alimentaci\u00f3n cercanas a la playa del Tarajal concentraban grupos de j\u00f3venes que a\u00fan no tienen muy claro qu\u00e9 har\u00e1n. Aun cuando la alarma y la indignaci\u00f3n de los vecinos que gener\u00f3 el aluvi\u00f3n de entradas en la ciudad, fuentes gubernamentales aseguran que no ha habido altercados relevantes o problemas de seguridad.Menores y respuesta marroqu\u00edEl Consejo Territorial de Servicios Sociales ha respaldado este mi\u00e9rcoles, en sesi\u00f3n extraordinaria motivada por la crisis migratoria que vive Ceuta, dar respuesta a la situaci\u00f3n por la que atraviesan los ni\u00f1os, ni\u00f1as y adolescentes que migran solos. Desde el Ejecutivo se ha propuesto a las comunidades que acojan a 200 menores ya tutelados por la ciudad aut\u00f3noma para dejar plaza a los reci\u00e9n llegados. Save The Children y la Plataforma de la Infancia han pedido este mi\u00e9rcoles que no se efect\u00faen \u201cdevoluciones en caliente\u201d de menores.En el \u00e1mbito pol\u00edtico marroqu\u00ed, a la \u00fanica excepci\u00f3n hasta ahora al silencio que guardan las autoridades \u2014la declaraci\u00f3n de la embajadora en Espa\u00f1a, Karima Benyaich, que este martes asegur\u00f3 que en las relaciones entre pa\u00edses hay actos que tienen consecuencias \u201cy se tienen que asumir\u201d, en velada referencia a la decisi\u00f3n de Espa\u00f1a de prestar atenci\u00f3n m\u00e9dica al l\u00edder del Frente Polisario, Brahim Gali\u2014 se une este mi\u00e9rcoles las palabras de un ministro del reino hachem\u00ed. Mustaf\u00e1 Ramid, ministro de Estado encargado de Derechos Humanos y Relaciones con el Parlamento se ha preguntado en Facebook \u201c\u00bfqu\u00e9 esperaba Espa\u00f1a de Marruecos, cuando vio a su vecino albergando a un responsable que tom\u00f3 las armas contra el reino?\u201d, la primera referencia expl\u00edcita al caso de Gali. En Francia, el Gobierno ha dicho seguir \u201ccon atenci\u00f3n\u201d la crisis abierta por la entrada de miles de migrantes en Ceuta y espera una \u201cvuelta r\u00e1pida a la normalidad\u201d en la ciudad aut\u00f3noma, aunque ha evitado criticar a Marruecos.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/espana\/2021-05-19\/cientos-de-marroquies-peregrinan-hasta-la-frontera-de-ceuta-para-volver-a-sus-casas.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevos grupos de j\u00f3venes siguen intentando llegar a nado a las playas de Ceuta, pero cada vez nadan m\u00e1s lejos para evitar ser interceptados por la embarcaci\u00f3n de la Guardia Civil. Los agentes estaban a primera hora de la tarde de este mi\u00e9rcoles frente a un peque\u00f1o pe\u00f1\u00f3n a unos metros de la orilla observando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Nuevos grupos de j\u00f3venes siguen intentando llegar a nado a las playas de Ceuta, pero cada vez nadan m\u00e1s lejos para evitar ser interceptados por la embarcaci\u00f3n de la Guardia Civil. Los agentes estaban a primera hora de la tarde de este mi\u00e9rcoles frente a un peque\u00f1o pe\u00f1\u00f3n a unos metros de la orilla observando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T18:43:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T18:43:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas\",\"datePublished\":\"2021-05-19T18:43:48+00:00\",\"dateModified\":\"2021-05-19T18:43:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/\"},\"wordCount\":1389,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/\",\"name\":\"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg\",\"datePublished\":\"2021-05-19T18:43:48+00:00\",\"dateModified\":\"2021-05-19T18:43:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World","og_description":"Nuevos grupos de j\u00f3venes siguen intentando llegar a nado a las playas de Ceuta, pero cada vez nadan m\u00e1s lejos para evitar ser interceptados por la embarcaci\u00f3n de la Guardia Civil. Los agentes estaban a primera hora de la tarde de este mi\u00e9rcoles frente a un peque\u00f1o pe\u00f1\u00f3n a unos metros de la orilla observando [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/","og_site_name":"Hot News in World","article_published_time":"2021-05-19T18:43:48+00:00","article_modified_time":"2021-05-19T18:43:52+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas","datePublished":"2021-05-19T18:43:48+00:00","dateModified":"2021-05-19T18:43:52+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/"},"wordCount":1389,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/","url":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/","name":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg","datePublished":"2021-05-19T18:43:48+00:00","dateModified":"2021-05-19T18:43:52+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Cientos-de-marroquies-peregrinan-desde-Ceuta-para-volver-a-su.jpg","width":1200,"height":800,"caption":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/cientos-de-marroquies-peregrinan-desde-ceuta-para-volver-a-su-pais-mientras-sigue-el-goteo-de-llegadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cientos de marroqu\u00edes peregrinan desde Ceuta para volver a su pa\u00eds mientras sigue el goteo de llegadas"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2503"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2503\/revisions"}],"predecessor-version":[{"id":2505,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2503\/revisions\/2505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2504"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}