{"id":2542,"date":"2021-05-23T04:51:34","date_gmt":"2021-05-23T01:51:34","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/"},"modified":"2021-05-23T04:51:43","modified_gmt":"2021-05-23T01:51:43","slug":"renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/","title":{"rendered":"Renuncia el negociador del Gobierno colombiano con los manifestantes"},"content":{"rendered":"<p>El Alto Comisionado para la Paz de Colombia, Miguel Ceballos (izquierda), durante una reuni\u00f3n con la Central Unitaria de Trabajadores, en Bogot\u00e1.Prensa Alto Comisionado para la  \/ Prensa Alto Comisionado para la Iv\u00e1n Duque ha perdido este s\u00e1bado a otro miembro de su gabinete en medio de las protestas que ya cumplen m\u00e1s de tres semanas y dejan medio centenar de muertos en Colombia. Esta vez fue el turno del Alto Comisionado para la Paz, Miguel Ceballos, hombre cercano al mandatario y quien durante la \u00faltima semana empez\u00f3 las negociaciones con el comit\u00e9 del paro. \u201cYo le coment\u00e9 al presidente de la Rep\u00fablica que iba a dejar el Gobierno desde diciembre del a\u00f1o pasado, concretamente el 22 de diciembre, y le reiter\u00e9 esa voluntad el d\u00eda 3 de mayo de este a\u00f1o, fecha en la cual formalic\u00e9 esa decisi\u00f3n de irme a partir del 26 de mayo, mencion\u00e1ndole al Presidente oficialmente que mi \u00faltimo d\u00eda en Palacio ser\u00eda el 25 de mayo\u201d, dijo en una entrevista al peri\u00f3dico El Tiempo. Es el tercer funcionario que renuncia en medio de las protestas, tras las dimisiones del ministro de Hacienda y la canciller.Y aunque asegur\u00f3 que su salida se deb\u00eda a razones personales, revel\u00f3 su molestia por una intromisi\u00f3n del expresidente \u00c1lvaro Uribe, padrino pol\u00edtico de Iv\u00e1n Duque, en las labores de su cargo. \u201cSiento una incomodidad con el expresidente Uribe. En dos ocasiones, desafortunadamente, no fui consultado por el expresidente por contactos que tuvieron \u00e9l y representantes suyos con el ELN.\u201d, dijo Ceballos en la entrevista.El Gobierno de Iv\u00e1n Duque cerr\u00f3 la posibilidad de una salida negociada con el Ej\u00e9rcito de Liberaci\u00f3n Nacional, la \u00faltima guerrilla activa en Colombia, desde que ese grupo atent\u00f3 contra una escuela de cadetes y dej\u00f3 22 muertos, en enero de 2019. P\u00fablicamente, Uribe ha sido un ac\u00e9rrimo opositor al di\u00e1logo, pero en los \u00faltimos d\u00edas se conoci\u00f3 que el expresidente particip\u00f3 de contactos con representantes de esa guerrilla. El Alto Comisionado no fue informado. \u201cEl expresidente Uribe me desconoci\u00f3\u201d, dijo en la entrevista. Posteriormente uno de los excombatientes con los que se reuni\u00f3 Uribe fue delegado como gestor de paz.El comisionado no solo manifest\u00f3 su molestia por esos contactos, sino que asegur\u00f3 que el pa\u00eds no pod\u00eda seguir entre las posiciones de \u00c1lvaro Uribe y el opositor y excandidato presidencial, Gustavo Petro. \u201cCreo que el pa\u00eds merece m\u00e1s equilibrio. Yo siento que ambos han sido irresponsables en presionar a este Gobierno y al Congreso para que la moneda se incline m\u00e1s hacia su lado\u201d, agreg\u00f3 Ceballos aunque insisti\u00f3 en que no se trata de que Uribe cogobierne.Las palabras de Ceballos se dan en un momento en que la relaci\u00f3n entre el expresidente y el mandatario pasa una tensi\u00f3n p\u00fablica. Uribe ha cuestionado algunas decisiones de su ahijado pol\u00edtico como la fallida reforma tributaria, el manejo de las protestas o su forma de comunicar. \u201cNo sumemos otro error: la demora para tomar decisiones\u201d, trin\u00f3 hace pocos d\u00edas. Miembros del partido de Gobierno temen que la mala imagen del presidente los arrastre para las elecciones del 2022.Uribe se expres\u00f3 a trav\u00e9s de su cuenta de Twitter: \u201cEl doctor Miguel Ceballos es una muy buena persona, qu\u00e9 le voy a contestar yo que tengo tantos enemigos malas personas\u201d, public\u00f3 el exmandatario. Por el momento, el presidente Iv\u00e1n Duque no se ha pronunciado sobre la renuncia de Ceballos y tampoco es claro qui\u00e9n continuar\u00e1 a la cabeza de las negociaciones con el comit\u00e9 del paro. Suscr\u00edbase aqu\u00ed a la newsletter de EL PA\u00cdS Am\u00e9rica y reciba todas las claves informativas de la actualidad de la regi\u00f3n<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-05-23\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Alto Comisionado para la Paz de Colombia, Miguel Ceballos (izquierda), durante una reuni\u00f3n con la Central Unitaria de Trabajadores, en Bogot\u00e1.Prensa Alto Comisionado para la \/ Prensa Alto Comisionado para la Iv\u00e1n Duque ha perdido este s\u00e1bado a otro miembro de su gabinete en medio de las protestas que ya cumplen m\u00e1s de tres [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"El Alto Comisionado para la Paz de Colombia, Miguel Ceballos (izquierda), durante una reuni\u00f3n con la Central Unitaria de Trabajadores, en Bogot\u00e1.Prensa Alto Comisionado para la \/ Prensa Alto Comisionado para la Iv\u00e1n Duque ha perdido este s\u00e1bado a otro miembro de su gabinete en medio de las protestas que ya cumplen m\u00e1s de tres [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-23T01:51:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-23T01:51:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Renuncia el negociador del Gobierno colombiano con los manifestantes\",\"datePublished\":\"2021-05-23T01:51:34+00:00\",\"dateModified\":\"2021-05-23T01:51:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/\"},\"wordCount\":647,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/\",\"name\":\"Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg\",\"datePublished\":\"2021-05-23T01:51:34+00:00\",\"dateModified\":\"2021-05-23T01:51:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Renuncia el negociador del Gobierno colombiano con los manifestantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renuncia el negociador del Gobierno colombiano con los manifestantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/","og_locale":"es_ES","og_type":"article","og_title":"Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World","og_description":"El Alto Comisionado para la Paz de Colombia, Miguel Ceballos (izquierda), durante una reuni\u00f3n con la Central Unitaria de Trabajadores, en Bogot\u00e1.Prensa Alto Comisionado para la \/ Prensa Alto Comisionado para la Iv\u00e1n Duque ha perdido este s\u00e1bado a otro miembro de su gabinete en medio de las protestas que ya cumplen m\u00e1s de tres [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/","og_site_name":"Hot News in World","article_published_time":"2021-05-23T01:51:34+00:00","article_modified_time":"2021-05-23T01:51:43+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Renuncia el negociador del Gobierno colombiano con los manifestantes","datePublished":"2021-05-23T01:51:34+00:00","dateModified":"2021-05-23T01:51:43+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/"},"wordCount":647,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/","url":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/","name":"Renuncia el negociador del Gobierno colombiano con los manifestantes - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg","datePublished":"2021-05-23T01:51:34+00:00","dateModified":"2021-05-23T01:51:43+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/Renuncia-el-negociador-del-Gobierno-colombiano-con-los-manifestantes-scaled.jpg","width":2560,"height":1707,"caption":"Renuncia el negociador del Gobierno colombiano con los manifestantes"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/renuncia-el-negociador-del-gobierno-colombiano-con-los-manifestantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Renuncia el negociador del Gobierno colombiano con los manifestantes"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"predecessor-version":[{"id":2544,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2542\/revisions\/2544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2543"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}