{"id":2563,"date":"2021-05-24T22:34:40","date_gmt":"2021-05-24T19:34:40","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/"},"modified":"2021-05-24T22:34:43","modified_gmt":"2021-05-24T19:34:43","slug":"el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/","title":{"rendered":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren"},"content":{"rendered":"<p>La pr\u00f3rroga de los ERTE sigue encallada. Gobierno y agentes sociales salieron de la reuni\u00f3n que mantuvieron este lunes con las mismas diferencias con las que entraron. Esto es, mientras que Seguridad Social planea, adem\u00e1s de la ampliaci\u00f3n hasta el 30 de septiembre, un reajuste de las ayudas que estimule la salida del ERTE de los trabajadores y penalizar a los que se mantienen, sindicatos y patronales mantienen que el esquema actual debe permanecer. Seg\u00fan detallan fuentes presentes en las negociaciones sigue existiendo margen para el acuerdo, pero la aprobaci\u00f3n de la pr\u00f3rroga en el Consejo de Ministros de este martes queda en el aire.A pesar de que todas las partes se hab\u00edan dado el fin de semana de margen para revisar los pormenores de la \u00faltima propuesta del Gobierno, y de que se establecer\u00edan contactos para limar asperezas esos dos d\u00edas, el desacuerdo se mantuvo durante toda la jornada de este lunes. El epicentro del problema sigue siendo el mismo: el tama\u00f1o de las exoneraciones. El ministro de Inclusi\u00f3n, Seguridad Social y Migraciones, Jos\u00e9 Luis Escriv\u00e1, que ya hab\u00eda defendido esta misma postura en las renovaciones precedentes, pretender alterar el estadio actual y ampliar las dirigidas a rescatar trabajadores del ERTE, y rebajar, progresivamente, las de aquellos que permanecen en \u00e9l.Esta \u201cinflexibilidad\u201d, tal y como la describen los defensores de mantener el sistema actual, sigue resultando un obst\u00e1culo para extender el uso de una herramienta de la que dependen cerca de 600.000 personas seg\u00fan los \u00faltimos datos de Seguridad Social. Hasta tal punto, de que ninguna de las partes consultadas ha confirmado si la pr\u00f3rroga ser\u00e1 aprobada este martes, sin acuerdo, durante el Consejo de Ministros, el \u00faltimo previsto antes de que venza el plazo actual de los ERTE, estipulado para el 31 de mayo. \u201cSer\u00eda muy mala idea tanto que se llevase a cabo su aprobaci\u00f3n de manera unilateral, como que se pospusiera para un Consejo de Ministros extraordinario previo a la conclusi\u00f3n del periodo estipulado\u201d, reconoce una fuente sindical.Este diferencia de opiniones no evita, sin embargo, que las apelaciones al di\u00e1logo sigan presentes. Que tan solo resten cinco d\u00edas para que concluya el plazo supone un margen de tiempo suficiente para las partes a la hora de alcanzar un acuerdo que recupere la senda del consenso social que ha guiado las anteriores pr\u00f3rrogas. \u201cAunque tenemos un acuerdo con el texto, existe un fleco no menor con las exoneraciones. No hay ninguna justificaci\u00f3n para que el acuerdo total no se lleve a cabo. Las partes concernientes al Ministerio de Trabajo est\u00e1n resueltas y solo falta el compromiso de Seguridad Social. De no ser as\u00ed alguien deber\u00e1 asumir su responsabilidad\u201d, apunta Mari Cruz Vicente, secretaria de Acci\u00f3n Sindical de CCOO.La figura de los ERTE, que est\u00e1n sosteniendo a miles de empresas durante la pandemia, hab\u00eda generado una concatenaci\u00f3n de acuerdos entre Gobierno y agentes sociales que fue motivo de satisfacci\u00f3n en todas ellas. De ah\u00ed que la extensi\u00f3n de estos no haya estado nunca discutida. S\u00ed, en cambio, en la vertiente de las exoneraciones. Otro peque\u00f1o escollo ten\u00eda ver con el acceso de los fijos discontinuos a los ERTE, \u201calgo que se ha ajustado para que nadie se quede fuera\u201d, dicen las fuentes consultadas.\u201cMercadeo\u201dEsta incapacidad de alcanzar un acuerdo gener\u00f3 que el presidente de la CEOE, Antonio Garamendi, tildara de \u201cmercadeo\u201d la negociaci\u00f3n. \u201cEs incomprensible que se nos est\u00e9n presentando ofertas y no ofertas, esto no es un mercado. Es una negociaci\u00f3n seria\u201d, critic\u00f3 Garamendi en un evento en la Casa de Am\u00e9rica. Desde la patronal no entienden que junto con la ampliaci\u00f3n de cuatro meses tenga que producirse una alteraci\u00f3n del esquema actual de exoneraciones, teniendo en cuenta que la pandemia sigue castigando a empresas y trabajadores. \u201cUna pr\u00f3rroga es una pr\u00f3rroga, son 20 minutos m\u00e1s con las mismas reglas de juego y con el mismo bal\u00f3n, no con otras reglas y otro bal\u00f3n\u201d, a\u00f1adi\u00f3.El esquema actual de los ERTE establece exoneraciones de cuotas para los sectores ultraprotegidos y empresas de su cadena de valor del 85% para empresas con menos de 50 trabajadores y del 75% para las que tienen m\u00e1s de 50, tanto para empleados reincorporados como para suspendidos. En los ERTE por impedimento de actividad, las exoneraciones son del 100% para empresas con menos de 50 trabajadores y del 90% para las que tienen m\u00e1s de 50 , mientras que en los ERTE de limitaci\u00f3n de actividad las exenciones son decrecientes hasta mayo de 2021. Para empresas de menos de 50 trabajadores, Estas fueron del 100% en febrero, del 90% en marzo y del 85% en abril y ser\u00e1n del 80% en mayo. Para las que tengan m\u00e1s de 50 empleados, estos porcentajes son del 90%, del 80%, del 75% y del 70%.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/economia\/2021-05-24\/escriva-no-logra-pactar-con-los-agentes-sociales-la-prorroga-de-los-erte-a-cinco-dias-de-que-expire.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pr\u00f3rroga de los ERTE sigue encallada. Gobierno y agentes sociales salieron de la reuni\u00f3n que mantuvieron este lunes con las mismas diferencias con las que entraron. Esto es, mientras que Seguridad Social planea, adem\u00e1s de la ampliaci\u00f3n hasta el 30 de septiembre, un reajuste de las ayudas que estimule la salida del ERTE de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"La pr\u00f3rroga de los ERTE sigue encallada. Gobierno y agentes sociales salieron de la reuni\u00f3n que mantuvieron este lunes con las mismas diferencias con las que entraron. Esto es, mientras que Seguridad Social planea, adem\u00e1s de la ampliaci\u00f3n hasta el 30 de septiembre, un reajuste de las ayudas que estimule la salida del ERTE de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T19:34:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-24T19:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren\",\"datePublished\":\"2021-05-24T19:34:40+00:00\",\"dateModified\":\"2021-05-24T19:34:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/\"},\"wordCount\":844,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/\",\"name\":\"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg\",\"datePublished\":\"2021-05-24T19:34:40+00:00\",\"dateModified\":\"2021-05-24T19:34:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg\",\"width\":900,\"height\":506,\"caption\":\"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World","og_description":"La pr\u00f3rroga de los ERTE sigue encallada. Gobierno y agentes sociales salieron de la reuni\u00f3n que mantuvieron este lunes con las mismas diferencias con las que entraron. Esto es, mientras que Seguridad Social planea, adem\u00e1s de la ampliaci\u00f3n hasta el 30 de septiembre, un reajuste de las ayudas que estimule la salida del ERTE de [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/","og_site_name":"Hot News in World","article_published_time":"2021-05-24T19:34:40+00:00","article_modified_time":"2021-05-24T19:34:43+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren","datePublished":"2021-05-24T19:34:40+00:00","dateModified":"2021-05-24T19:34:43+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/"},"wordCount":844,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/","url":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/","name":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg","datePublished":"2021-05-24T19:34:40+00:00","dateModified":"2021-05-24T19:34:43+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Gobierno-no-logra-el-acuerdo-de-los-agentes-sociales.jpg","width":900,"height":506,"caption":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/el-gobierno-no-logra-el-acuerdo-de-los-agentes-sociales-para-prorrogar-los-erte-a-cinco-dias-de-que-expiren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Gobierno no logra el acuerdo de los agentes sociales para pr\u00f3rrogar los ERTE a cinco d\u00edas de que expiren"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2563"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2563\/revisions"}],"predecessor-version":[{"id":2565,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2563\/revisions\/2565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2564"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}