{"id":2584,"date":"2021-05-26T18:10:28","date_gmt":"2021-05-26T15:10:28","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/"},"modified":"2021-05-26T18:10:32","modified_gmt":"2021-05-26T15:10:32","slug":"la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/","title":{"rendered":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas"},"content":{"rendered":"<p>Una trabajadora ayuda a una paciente de la residencia de mayores Vitalia Canillejas, donde se ejercitan terapias para ganar autonom\u00eda frente a las secuelas del aislamiento.David Fern\u00e1ndez \/ EFECada pelda\u00f1o que se asciende en la escala del aislamiento supone la p\u00e9rdida de una funcionalidad f\u00edsica cotidiana. Se empieza por la propensi\u00f3n a las ca\u00eddas, la incapacidad de dar paseos largos o la imposibilidad de llevar la bolsa de la compra y se termina sin poder cerrar una ventana o levantarse. El final es la dependencia absoluta. Un estudio publicado en American Journal of Preventive Medicine ha analizado durante nueve a\u00f1os a 12.427 personas para establecer la relaci\u00f3n directa entre el aislamiento progresivo y las incapacidades que va generando. \u201cLa soledad es la nueva pandemia\u201d, afirma Jes\u00fas del Pozo-Cruz, uno de los autores e investigador principal del grupo internacional Epidemiology of Physical Activity and Fitness Across Lifespan (EPAFit), de la Universidad de Sevilla (US).M\u00e1s informaci\u00f3nEl aislamiento no es una consecuencia de la covid, aunque esta haya puesto el foco en esta circunstancia vital por su imposici\u00f3n. Su extensi\u00f3n y sus consecuencias se han analizado ampliamente y sus efectos en la salud f\u00edsica y mental han sido protagonistas este mi\u00e9rcoles del 23 Congreso Europeo de Endocrinolog\u00eda. Seg\u00fan Chiara Simeoli, investigadora de la Universidad de N\u00e1poles, \u201cla soledad es un factor de estr\u00e9s psicol\u00f3gico significativo que causa efectos severos en la salud mental, a\u00fan m\u00e1s en las personas con condiciones preexistentes\u201d.Un ejemplo de esas condiciones previas es la diabetes. Un estudio de la endocrin\u00f3loga Liana Jashi presentado en el congreso europeo confirma que, entre estos pacientes, el aislamiento supone un menor acceso a la atenci\u00f3n m\u00e9dica y un aumento de peso as\u00ed como del consumo de cigarrillos y de alcohol. La actividad f\u00edsica disminuye en este colectivo un 29,8% \u201cy el ejercicio es vital para prevenir m\u00e1s problemas f\u00edsicos y psicol\u00f3gicos\u201d, seg\u00fan la m\u00e9dica.El aislamiento afecta a todos. Aunque se agrava con el envejecimiento, los mayores de 50 a\u00f1os empiezan a tener problemas y tambi\u00e9n los j\u00f3venesJes\u00fas Del Pozo-Cruz, investigador de la Universidad de SevillaEl estudio de Del Pozo-Cruz, en el que han participado investigadores de Dinamarca y Australia, se centra precisamente en esa disminuci\u00f3n de la actividad para establecer una relaci\u00f3n bidireccional entre el aislamiento y la p\u00e9rdida de funcionalidades f\u00edsicas: ambas son causa y efecto. El trabajo, a partir de 54.860 observaciones de personas al a\u00f1o durante casi una d\u00e9cada, es el primero que se extiende m\u00e1s all\u00e1 de una comunidad concreta y que prescinde de otros condicionantes socioecon\u00f3micos, como la educaci\u00f3n o el nivel de renta. \u201cEl aislamiento afecta a todos. Aunque se agrava con el envejecimiento, los mayores de 50 a\u00f1os empiezan a tener problemas y tambi\u00e9n los j\u00f3venes, que lo sufren igual y en los que tiene los mismos efectos, aunque estos \u00faltimos tienen m\u00e1s capacidad de reacci\u00f3n\u201d, explica el investigador de la US.Relaci\u00f3n entre la bater\u00eda de rendimiento f\u00edsico (columna izquierda) y el \u00edndice de aislamiento social (abajo). La gr\u00e1fica muestra que, a menor soledad (valores entre 0 y 1), mayor capacidad f\u00edsica (sobre 9). \/ J. Del P-C.El estudio tuvo en cuenta un \u00cdndice de Aislamiento Social con seis escalas. Cero representa el menor nivel de soledad y llega hasta el sexto pelda\u00f1o conforme se van perdiendo, por fallecimiento o alejamiento, relaciones sociales, personas con las que se convive y familiares cercanos. El otro lado del espejo es la bater\u00eda de rendimiento f\u00edsico, que eval\u00faa de cero a 12 las capacidades, siendo cero la dependencia total y 12 la mejor condici\u00f3n.Estad\u00edsticamente, el estudio reflej\u00f3 que cada aumento de una unidad en el \u00cdndice de Aislamiento Social result\u00f3 en una disminuci\u00f3n promedio de 0,27 unidades en la bater\u00eda de rendimiento f\u00edsico, una relaci\u00f3n que aumenta con la edad. Del Pozo-Cruz resume: \u201cEn t\u00e9rminos generales, por cada punto que se gana en el \u00cdndice de Aislamiento se pierde una funci\u00f3n f\u00edsica que lleva a la fragilidad y a la dependencia\u201d.Las personas que est\u00e1n socialmente aisladas tienen m\u00e1s riesgo de mortalidad prematura y son m\u00e1s propensas a presentar problemas de salud mental y desarrollar demenciaLa cadena es m\u00e1s larga. El propio estudio afirma que \u201clas personas que est\u00e1n socialmente aisladas tienen m\u00e1s riesgo de mortalidad prematura y son m\u00e1s propensas a presentar problemas de salud mental y desarrollar demencia\u201d. A esa predisposici\u00f3n se suman las comorbilidades (coexistencia de dos o m\u00e1s enfermedades en un mismo individuo, generalmente relacionadas), que conforman el c\u00f3ctel completo de factores asociados. Seg\u00fan la investigaci\u00f3n: \u201cEs probable que las consecuencias de estar aislado se compongan con estas vulnerabilidades relacionadas con la edad, generando un efecto negativo m\u00e1s fuerte de la soledad en el funcionamiento f\u00edsico entre los mayores. Este escenario es consistente con hallazgos emp\u00edricos anteriores\u201d.En el lado opuesto se encuentran los adultos mayores socialmente integrados y que, por esta condici\u00f3n, pueden ser m\u00e1s propensos a participar en actividades f\u00edsicas y evitar el sedentarismo, lo que a su vez provoca mejoras en su funcionalidad.\u201cLas conexiones sociales promueven otros comportamientos positivos (por ejemplo, una dieta saludable), lo que potencialmente desacelera los declives f\u00edsicos asociados con el envejecimiento\u201d, concluye el estudio.En Espa\u00f1a, el 36,8% de las personas de m\u00e1s de 65 a\u00f1os vive en hogares unipersonales. Entre la poblaci\u00f3n de mayor edad, el 56% de los hombres y el 72% de las mujeres refieren sentir alg\u00fan tipo de soledadLa investigaci\u00f3n, que admite que se dan limitaciones marcadas por el origen de los datos a partir de respuestas personales, que pueden incluir sesgos, y por las dificultades de identificar estimaciones inequ\u00edvocamente causales, considera sin embargo que es lo suficientemente \u201crobusto\u201d y que se suma a la creciente evidencia sobre las consecuencias negativas del aislamiento social. En este sentido, Del Pozo-Cruz reclama intervenciones de salud p\u00fablica hacia las personas en riesgo de aislamiento, con programas de desarrollo de habilidades, contacto personal programado y actividades con animales. \u201cEs necesario promover ejercicios f\u00edsicos en grupo y, si estos est\u00e1n dirigidos por profesionales, mejor\u201d, afirma.Un estudio publicado en Science direct sobre la importancia de tener en cuenta el aislamiento en los sistemas de atenci\u00f3n primaria se\u00f1ala que, en Espa\u00f1a, el 36,8% de las personas de m\u00e1s de 65 a\u00f1os vive en hogares unipersonales. Entre la poblaci\u00f3n de mayor edad, el 56% de los hombres y el 72% de las mujeres refieren sentir alg\u00fan tipo de soledad, una proporci\u00f3n que aumenta al ritmo del envejecimiento.Este estudio coincide con los mencionados: la soledad incrementa el sedentarismo, el tabaquismo, el consumo excesivo de alcohol y la alimentaci\u00f3n inadecuada. Tambi\u00e9n afecta a la cantidad y la calidad del sue\u00f1o. La explicaci\u00f3n fisiopatol\u00f3gica se fundamenta en que el aislamiento perjudica no solo los h\u00e1bitos saludables, sino tambi\u00e9n las regulaciones biol\u00f3gicas de los sistemas endocrino, cardiovascular, inmune e inflamatorio; la presi\u00f3n arterial y la actividad adrenocortical del eje hipot\u00e1lamo-hipofisario.Puedes seguir a MATERIA en Facebook,<a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/materia_ciencia\"> Twitter<\/a> e Instagram, o apuntarte aqu\u00ed para recibir nuestra newsletter semanal.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/ciencia\/2021-05-26\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una trabajadora ayuda a una paciente de la residencia de mayores Vitalia Canillejas, donde se ejercitan terapias para ganar autonom\u00eda frente a las secuelas del aislamiento.David Fern\u00e1ndez \/ EFECada pelda\u00f1o que se asciende en la escala del aislamiento supone la p\u00e9rdida de una funcionalidad f\u00edsica cotidiana. Se empieza por la propensi\u00f3n a las ca\u00eddas, la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Una trabajadora ayuda a una paciente de la residencia de mayores Vitalia Canillejas, donde se ejercitan terapias para ganar autonom\u00eda frente a las secuelas del aislamiento.David Fern\u00e1ndez \/ EFECada pelda\u00f1o que se asciende en la escala del aislamiento supone la p\u00e9rdida de una funcionalidad f\u00edsica cotidiana. Se empieza por la propensi\u00f3n a las ca\u00eddas, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-26T15:10:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-26T15:10:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas\",\"datePublished\":\"2021-05-26T15:10:28+00:00\",\"dateModified\":\"2021-05-26T15:10:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/\"},\"wordCount\":1258,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/\",\"name\":\"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg\",\"datePublished\":\"2021-05-26T15:10:28+00:00\",\"dateModified\":\"2021-05-26T15:10:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg\",\"width\":1706,\"height\":1280,\"caption\":\"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/","og_locale":"es_ES","og_type":"article","og_title":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World","og_description":"Una trabajadora ayuda a una paciente de la residencia de mayores Vitalia Canillejas, donde se ejercitan terapias para ganar autonom\u00eda frente a las secuelas del aislamiento.David Fern\u00e1ndez \/ EFECada pelda\u00f1o que se asciende en la escala del aislamiento supone la p\u00e9rdida de una funcionalidad f\u00edsica cotidiana. Se empieza por la propensi\u00f3n a las ca\u00eddas, la [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/","og_site_name":"Hot News in World","article_published_time":"2021-05-26T15:10:28+00:00","article_modified_time":"2021-05-26T15:10:32+00:00","og_image":[{"width":1706,"height":1280,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas","datePublished":"2021-05-26T15:10:28+00:00","dateModified":"2021-05-26T15:10:32+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/"},"wordCount":1258,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/","url":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/","name":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg","datePublished":"2021-05-26T15:10:28+00:00","dateModified":"2021-05-26T15:10:32+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/La-soledad-lleva-a-la-perdida-de-habilidades-para-tareas.jpg","width":1706,"height":1280,"caption":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/la-soledad-lleva-a-la-perdida-de-habilidades-para-tareas-cotidianas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"La soledad lleva a la p\u00e9rdida de habilidades para tareas cotidianas"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2584"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2584\/revisions"}],"predecessor-version":[{"id":2586,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2584\/revisions\/2586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2585"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}