{"id":2623,"date":"2021-05-30T00:53:34","date_gmt":"2021-05-29T21:53:34","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/"},"modified":"2021-05-30T00:53:41","modified_gmt":"2021-05-29T21:53:41","slug":"el-chelsea-se-come-al-city","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/","title":{"rendered":"El Chelsea se come al City"},"content":{"rendered":"<p>Londres ya tiene su segunda Copa de Europa. Las dos se las debe al Chelsea, triunfal en Oporto \u2014por fin, por suerte, con gente en las gradas\u2014 ante un Manchester City al que desti\u00f1\u00f3 por completo. Un gol en la mochila y todas las cerraduras del mundo le bastaron a los de Tuchel para anular una a una las muchas individualidades del conjunto de Guardiola. El Chelsea, equipo gregario como pocos, dej\u00f3 en la cuneta a un rival negado de principio a fin. Por encima de los De Bruyne, Mahrez, Foden, la final tuvo una etiqueta, la de Kant\u00e9, que no es uno solo sino todo un equipo en s\u00ed mismo. \u00c9l es el espinazo del Chelsea, un jugador tan silencioso como eficaz, c\u00f3smico. Un futbolista total que elude el espumoso mundo de las celebridades. Sobre \u00e9l gravit\u00f3 el nuevo campe\u00f3n de Europa. Otro \u00e9xito de la escuela alemana de t\u00e9cnicos. Tres consecutivos han cantado la gloria: J\u00fcrgen Klopp, Hansi Flick y Thomas Tuchel.M\u00c1S INFORMACI\u00d3NAudaz como ha sido siempre, Guardiola lanz\u00f3 su \u00f3rdago a lo grande incluso en el d\u00eda cumbre en la historia del City. Por mucha final que fuera hab\u00eda que afrontarla a lo Guardiola. \u00bfUn medio centro tap\u00f3n? Nada de nada. Al banquillo Rodri y Fernandinho. \u00bfUn ariete? Nada de nada, en la grada Ag\u00fcero y Gabriel Jes\u00fas. A cambio, un consorcio de talento m\u00e1s talento: De Bruyne, Bernardo Silva, Mahrez, G\u00fcndogan, Foden, Sterling&#8230; Ocurri\u00f3 que todos fueron nadie. Todos chatos. Enfrente, un Chelsea mejor estructurado, firme, con colmillo y m\u00e1s directo. El City, moroso, de monserga con la pelota. El Chelsea, directo, at\u00f3mico, pese a que Werner no es un chacal. Ni mucho menos. Suyas fueron las primeras ocasiones. El alem\u00e1n iba de chasco en chasco, lo mismo pegaba una patada al aire que se anudaba la cabeza y los pies en el rancho de Ederson. Werner, h\u00e1bil para el desmarque, no rima con el gol ni ante una zaga tan p\u00e1nfila como la del City, con Stones y Ruben Dias muy dispersos. Y sin un camarada con mand\u00edbula por delante. Al Chelsea le va el rock; al City, los violines. No los tuvo en Oporto, tan monaguillo con el bal\u00f3n como sin \u00e9l.Sin avisos en el corral de Mendy, el equipo de Tuchel viv\u00eda a lo suyo. Ni agua al adversario en cada asalto y sin demora al ataque. As\u00ed lleg\u00f3 el gol. Un saque de Mendy, un pase cl\u00ednico de Mount y suficiente para que Havertz se plantara en un duelo esgrimista con Ederson. \u00bfLos centrales del City? De merienda. Havertz dej\u00f3 en la cuneta al portero brasile\u00f1o y dio un pase triunfal a la red. Pese a Werner, pero con Kant\u00e9 \u2014nunca se sabe si hay un solo Kant\u00e9 u once kant\u00e9s, recorri\u00f3 12 kil\u00f3metros\u2014, el Chelsea al frente. Ni siquiera not\u00f3 alguna sacudida con la lesi\u00f3n de Thiago Silva antes del descanso. Para el cuadro de Tuchel un 0-1 es una goleada. Pese a tanto ilustrado, abajo el City, que no encontr\u00f3 quien fuera a su rescate. M\u00e1s a\u00fan cuando de vuelta del intermedio De Bruyne choc\u00f3 con un muro de hormig\u00f3n. Eso es R\u00fcdiger, un alem\u00e1n de puro acero que le dej\u00f3 el ojo izquierdo a la virul\u00e9.Sin remedio, rectific\u00f3 Guardiola. Un nueve, Gabriel Jes\u00fas, por el maltrecho De Bruyne. Un medio centro con pico y pala, Fernandinho, por el anodino Bernardo Silva, lo que le permiti\u00f3 adelantar a G\u00fcndogan, al que este curso le ha ido como nunca flirtear con el gol. No hubo manera, nadie desequilibraba en el conjunto de Guardiola, esta vez ni siquiera pinturero. Ni un tirito p\u00e1rvulo a la meta de Mendy. S\u00f3lido el Chelsea, abrasivo al defender y cl\u00ednico para alertar. Apenas hab\u00eda soltado riendas en el segundo acto cuando Havertz cit\u00f3 a Pulisic con el gol, pero al estadounidense se le fue el remate por un dedillo.Ag\u00f3nico, recurri\u00f3 Guardiola al Kun Ag\u00fcero. De un inicio sin arietes a un final con dos. Ni se inmut\u00f3 el Chelsea, equipo que se arropa como boinas verdes. En su trinchera nadie concede un resquicio, todos pican piedra, todos a destajo. Una desesperaci\u00f3n para el City, sin juego, sin recursos, sin remates&#8230; No ser\u00e1 el Chelsea un equipo versallesco, pero tiene un sello: a su paso cualquier adversario parece menor, logra que nadie sea quien es. No lo fue el City, que por no tener no tuvo ni fogueo. En Oporto, Guardiola fue Guardiola, siempre bizarro, pero se impuso el m\u00e9todo Tuchel y el Chelsea, con el navarro Azpilicueta al frente, se coron\u00f3 por segunda vez estupendamente enjuiciado por Mateu Lahoz. Al City, tan becario en Europa, le toca esperar. Muy crudo este Chelsea.Puedes seguir a EL PA\u00cdS DEPORTES en Facebook y <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/elpais_deportes\">Twitter<\/a>, o apuntarte aqu\u00ed para recibir nuestra newsletter semanal.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/deportes\/2021-05-29\/el-chelsea-se-come-al-city.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Londres ya tiene su segunda Copa de Europa. Las dos se las debe al Chelsea, triunfal en Oporto \u2014por fin, por suerte, con gente en las gradas\u2014 ante un Manchester City al que desti\u00f1\u00f3 por completo. Un gol en la mochila y todas las cerraduras del mundo le bastaron a los de Tuchel para anular [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Chelsea se come al City - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Chelsea se come al City - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Londres ya tiene su segunda Copa de Europa. Las dos se las debe al Chelsea, triunfal en Oporto \u2014por fin, por suerte, con gente en las gradas\u2014 ante un Manchester City al que desti\u00f1\u00f3 por completo. Un gol en la mochila y todas las cerraduras del mundo le bastaron a los de Tuchel para anular [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-29T21:53:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-29T21:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1878\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"El Chelsea se come al City\",\"datePublished\":\"2021-05-29T21:53:34+00:00\",\"dateModified\":\"2021-05-29T21:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/\"},\"wordCount\":847,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Chelsea-se-come-al-City-scaled.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/\",\"name\":\"El Chelsea se come al City - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Chelsea-se-come-al-City-scaled.jpg\",\"datePublished\":\"2021-05-29T21:53:34+00:00\",\"dateModified\":\"2021-05-29T21:53:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Chelsea-se-come-al-City-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/05\\\/El-Chelsea-se-come-al-City-scaled.jpg\",\"width\":2560,\"height\":1878,\"caption\":\"El Chelsea se come al City\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-chelsea-se-come-al-city\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Chelsea se come al City\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Chelsea se come al City - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/","og_locale":"es_ES","og_type":"article","og_title":"El Chelsea se come al City - Hot News in World","og_description":"Londres ya tiene su segunda Copa de Europa. Las dos se las debe al Chelsea, triunfal en Oporto \u2014por fin, por suerte, con gente en las gradas\u2014 ante un Manchester City al que desti\u00f1\u00f3 por completo. Un gol en la mochila y todas las cerraduras del mundo le bastaron a los de Tuchel para anular [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/","og_site_name":"Hot News in World","article_published_time":"2021-05-29T21:53:34+00:00","article_modified_time":"2021-05-29T21:53:41+00:00","og_image":[{"width":2560,"height":1878,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"El Chelsea se come al City","datePublished":"2021-05-29T21:53:34+00:00","dateModified":"2021-05-29T21:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/"},"wordCount":847,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/","url":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/","name":"El Chelsea se come al City - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg","datePublished":"2021-05-29T21:53:34+00:00","dateModified":"2021-05-29T21:53:41+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/05\/El-Chelsea-se-come-al-City-scaled.jpg","width":2560,"height":1878,"caption":"El Chelsea se come al City"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/el-chelsea-se-come-al-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Chelsea se come al City"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2623"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2623\/revisions"}],"predecessor-version":[{"id":2625,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2623\/revisions\/2625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2624"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}