{"id":2698,"date":"2021-06-05T07:34:24","date_gmt":"2021-06-05T04:34:24","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/"},"modified":"2021-06-05T07:34:29","modified_gmt":"2021-06-05T04:34:29","slug":"el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/","title":{"rendered":"El Supremo mantiene las limitaciones de venta de publicidad  a Mediaset que le impuso la CNMC"},"content":{"rendered":"<p>Paolo Vasile, consejero delegado de Mediaset Espa\u00f1a . EFEEl Tribunal Supremo ha desestimado el recurso interpuesto por Mediaset y Publiespa\u00f1a contra la decisi\u00f3n de la Audiencia Nacional de mantener la obligaci\u00f3n de cese de las conductas consideradas anticompetitivas en la forma de comercializaci\u00f3n de la publicidad que le impuso la Comisi\u00f3n Nacional del Mercado y la Competencia (CNMC).La Audiencia, en un auto de fecha 4 de septiembre de 2020, admiti\u00f3 suspender el pago de la sanci\u00f3n de 38,2 millones de euros que le impuso en 2019 la CNMC tanto a Mediaset como a Atresmedia, por la forma de comercializar la publicidad, que restring\u00eda el acceso al mercado de operadores de televisi\u00f3n menores, pero le instaba a cesar en esas pr\u00e1cticas.M\u00e1s informaci\u00f3nLas conductas anticompetitivas son la imposici\u00f3n de cuotas m\u00ednimas de contrataci\u00f3n de publicidad televisiva a los anunciantes; el establecimiento de un sistema de comercializaci\u00f3n conjunta que vincula la venta de la publicidad en televisi\u00f3n a la contrataci\u00f3n por los anunciantes de paquetes de canales, y la pr\u00e1ctica de simulcast o pauta \u00fanica, que supone la transmisi\u00f3n simult\u00e1nea de la publicidad en los distintos canales de la cadena, siguiendo la pauta del que tiene m\u00e1s audiencia; asi como la fijaci\u00f3n de un sistema de retribuci\u00f3n por extraprimas a las agencias de medios.Mediaset Espa\u00f1a justific\u00f3 su solicitud de suspensi\u00f3n de la resoluci\u00f3n recurrida en la apariencia de \u201cbuen derecho\u201d de su defensa, en cuanto que, seg\u00fan la compa\u00f1\u00eda, dicha resoluci\u00f3n infringe el principio de tipicidad al estar imputando una infracci\u00f3n no tipificada legalmente y al no haberse probado los presuntos efectos anticompetitivos de las conductas analizadas;JurisprudenciaEl grupo propietario de Telecinco y Cuatro recordaba la jurisprudencia relativa a la posibilidad de suspender la ejecutividad de actos de contenido negativo en atenci\u00f3n a sus aspectos \u201cpositivos\u201d. Y alegaba que, lejos de que la CNMC le impusiera una simple \u201cobligaci\u00f3n de no hacer\u201d, la orden de cesaci\u00f3n y adaptaci\u00f3n contiene tanto un mandato de no hacer como un mandato positivo, tendente a adaptar la pol\u00edtica comercial a lo dispuesto en la resoluci\u00f3n recurrida, y es de la materializaci\u00f3n de dichas medidas de adaptaci\u00f3n de la que se derivan los graves perjuicios irreparables, seg\u00fan Mediaset.Asimismo, denunciaba la infracci\u00f3n de las normas comunitarias y de la jurisprudencia del Tribunal Supremo que proscribe la resoluci\u00f3n de una solicitud de medidas cautelares que prejuzgue el fallo del recurso principal, que es lo que, a su juicio, aqu\u00ed ha ocurrido, pues la Audiencia Nacional ha asumido que los hechos y supuestos efectos de las pr\u00e1cticas investigadas se han prolongado hasta la actualidad, a pesar de que el an\u00e1lisis de los supuestos efectos anticompetitivos contenidos en la resoluci\u00f3n \u00fanicamente abarca hasta 2017, seg\u00fan Mediaset.No obstante, el Tribunal Supremo estima que las cuestiones planteadas y las alegaciones desplegadas por Mediaset \u201cdeben tildarse de manifiestamente carentes de inter\u00e9s casacional y ello por cuanto las cuestiones planteadas por la parte recurrente se ci\u00f1en a los aspectos m\u00e1s casu\u00edsticos del litigio, sin superar este limitado marco, ni suscitar, problemas hermen\u00e9uticos extrapolables a otros casos\u201dEn efecto, el auto que se pretende recurrir en casaci\u00f3n no se limita a afirmar que \u201cla resoluci\u00f3n sancionadora impone el cese de unas conductas de la actora, es decir, una obligaci\u00f3n de no hacer cuya suspensi\u00f3n le permitir\u00eda continuar realizando aquello que se ha calificado como pr\u00e1cticas anticompetitivas, anticipando la Sala el juicio sobre el fondo del asunto\u201d, sino que la raz\u00f3n fundamental de decidir del auto, para desestimar la petici\u00f3n de suspensi\u00f3n de la orden de cese de la realizaci\u00f3n en el futuro de las conductas por las que se sanciona, es la ponderaci\u00f3n de los intereses en conflicto, sin que considere que a la recurrente le ampare la presunci\u00f3n de buen derecho.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/economia\/2021-06-05\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paolo Vasile, consejero delegado de Mediaset Espa\u00f1a . EFEEl Tribunal Supremo ha desestimado el recurso interpuesto por Mediaset y Publiespa\u00f1a contra la decisi\u00f3n de la Audiencia Nacional de mantener la obligaci\u00f3n de cese de las conductas consideradas anticompetitivas en la forma de comercializaci\u00f3n de la publicidad que le impuso la Comisi\u00f3n Nacional del Mercado y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Paolo Vasile, consejero delegado de Mediaset Espa\u00f1a . EFEEl Tribunal Supremo ha desestimado el recurso interpuesto por Mediaset y Publiespa\u00f1a contra la decisi\u00f3n de la Audiencia Nacional de mantener la obligaci\u00f3n de cese de las conductas consideradas anticompetitivas en la forma de comercializaci\u00f3n de la publicidad que le impuso la Comisi\u00f3n Nacional del Mercado y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-05T04:34:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-05T04:34:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC\",\"datePublished\":\"2021-06-05T04:34:24+00:00\",\"dateModified\":\"2021-06-05T04:34:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/\"},\"wordCount\":695,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/\",\"name\":\"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg\",\"datePublished\":\"2021-06-05T04:34:24+00:00\",\"dateModified\":\"2021-06-05T04:34:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg\",\"width\":980,\"height\":620,\"caption\":\"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/","og_locale":"es_ES","og_type":"article","og_title":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World","og_description":"Paolo Vasile, consejero delegado de Mediaset Espa\u00f1a . EFEEl Tribunal Supremo ha desestimado el recurso interpuesto por Mediaset y Publiespa\u00f1a contra la decisi\u00f3n de la Audiencia Nacional de mantener la obligaci\u00f3n de cese de las conductas consideradas anticompetitivas en la forma de comercializaci\u00f3n de la publicidad que le impuso la Comisi\u00f3n Nacional del Mercado y [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/","og_site_name":"Hot News in World","article_published_time":"2021-06-05T04:34:24+00:00","article_modified_time":"2021-06-05T04:34:29+00:00","og_image":[{"width":980,"height":620,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC","datePublished":"2021-06-05T04:34:24+00:00","dateModified":"2021-06-05T04:34:29+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/"},"wordCount":695,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/","url":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/","name":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg","datePublished":"2021-06-05T04:34:24+00:00","dateModified":"2021-06-05T04:34:29+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/El-Supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a.jpg","width":980,"height":620,"caption":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/el-supremo-mantiene-las-limitaciones-de-venta-de-publicidad-a-mediaset-que-le-impuso-la-cnmc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Supremo mantiene las limitaciones de venta de publicidad a Mediaset que le impuso la CNMC"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2698"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2698\/revisions"}],"predecessor-version":[{"id":2700,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2698\/revisions\/2700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2699"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}