{"id":2704,"date":"2021-06-05T19:49:55","date_gmt":"2021-06-05T16:49:55","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/"},"modified":"2021-06-05T19:49:57","modified_gmt":"2021-06-05T16:49:57","slug":"vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/","title":{"rendered":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d"},"content":{"rendered":"<p>Susa Plaza es una modista y dise\u00f1adora que ha vivido y trabajado siempre en la casa donde nacieron sus hermanas, en pleno barrio del Carmen de Valencia. El 16 de mayo recibi\u00f3 una \u201ccarta extorsionadora\u201d en el que el nuevo propietario del edificio desde hace febrero de este a\u00f1o le instaba a abandonar la vivienda de manera casi inmediata. \u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u2033, explica Susa, junto a otros de los seis vecinos alquilados, afectados por la medida que han puesto en manos de sus abogados. \u201cQue si no nos march\u00e1bamos, proceder\u00edan a llamar a los bomberos para que sean ellos los que nos desalojen, dice la carta, sin certificado y sin nada. Ahora, yo de aqu\u00ed no me muevo\u201d, a\u00f1ade.M\u00e1s informaci\u00f3n\u201cNo nos han dado ninguna oportunidad de negociar, de hablar. A algunos vecinos les han ofrecido 18.000 euros o 28.000 euros; a otros, 3.000 euros, seg\u00fan el tipo de alquiler. De renta antigua solo hab\u00eda una vecina que se ha marchado\u201d, comenta Salvador Mateu, de 52 a\u00f1os. \u201cA m\u00ed me subieron un 20% el alquiler hace un a\u00f1o y medio y tengo derecho a continuar en mi casa\u201d, a\u00f1ade el escen\u00f3grafo que lleva 16 a\u00f1os viviendo en el edificio.La raz\u00f3n que da el nuevo propietario para el desalojo es la necesidad de reformar y rehabilitar el inmueble de cuatro plantas. Su situaci\u00f3n puede poner en peligro a los inquilinos, que ocupan seis de la nueve viviendas, seg\u00fan se les transmiti\u00f3 a los vecinos. Adem\u00e1s, se tiene que instalar un ascensor por el hueco de la escalera. Para ello, necesitan quitar puertas de entradas y ganar espacio de las viviendas, seg\u00fan los propietarios.Los vecinos invitan a los periodistas a observar el \u201cenorme hueco\u201d de la escalera, donde aseguran que \u201ccabe un ascensor incluso dos\u201d, y a comprobar el estado de la finca que se pretende desalojar por la v\u00eda de urgencia, seg\u00fan adelant\u00f3 el Levante EMV. Si fueran necesarias las obras se podr\u00edan pactar y hablar, argumentan los vecinos que se han dirigido al Ayuntamiento de Valencia y no tienen constancia de ninguna petici\u00f3n en este sentido formulada para la finca ubicada en la calle de Sogueros, muy cerca de un solar municipal con un cartel oxidado de Aumsa que anuncia desde hace a\u00f1os una promoci\u00f3n de vivienda p\u00fablica.El propietario anterior avis\u00f3 a los inquilinos hace m\u00e1s de un a\u00f1o de que hab\u00eda vendido el edificio y de que no variaban las condiciones de alquiler con la nueva empresa. Pero del nuevo propietario, \u201cun fondo buitre\u201d que no pueden identificar porque los representa un despacho de abogados, y del que solo conocen las amenazas y el dinero que ofrecen para marcharse. Desconocen si quieren dedicar el edificio a apartamentos tur\u00edsticos.Vecinos de la calle Sogueros de Valencia, en el portal del edificio.El Ayuntamiento pretende establecer una moratoria con el objetivo de \u201cparalizar movimientos especulativos de fondos buitre y grandes corporaciones que para desarrollar su actividad expulsan al vecindario de los barrios\u201d, seg\u00fan manifest\u00f3 hace dos meses la concejal de Vivienda del Ayuntamiento de Val\u00e8ncia, Isabel Lozano, de Comprom\u00eds, a prop\u00f3sito de otro intento de desalojo en la cercana calle del Turia. La forma de actuar en Turia fue la misma que en la calle Sogueros.La directora genera de Emergencia Habitacional de la Generalitat, Pura Peris, se\u00f1al\u00f3 el viernes a este peri\u00f3dico que la Consejer\u00eda de Vivienda, que dirige el vicepresidente valenciano Rub\u00e9n Mart\u00ednez Dalmau, de Unides Podem, est\u00e1 recopilando toda la informaci\u00f3n sobre la situaci\u00f3n del inmueble. \u201cHemos quedado el lunes con los vecinos para asesorarlos y estudiar la situaci\u00f3n. Tenemos que ver si el edificio entra en los par\u00e1metros que permiten adquirirlo a la Generalitat a trav\u00e9s del decreto del tanteo y el retracto, entre otras cuestiones. En definitiva, vamos a estudiar bien el expediente y hacer lo que est\u00e9 en nuestra mano para buscar soluciones\u201d, explic\u00f3.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/espana\/comunidad-valenciana\/2021-06-05\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Susa Plaza es una modista y dise\u00f1adora que ha vivido y trabajado siempre en la casa donde nacieron sus hermanas, en pleno barrio del Carmen de Valencia. El 16 de mayo recibi\u00f3 una \u201ccarta extorsionadora\u201d en el que el nuevo propietario del edificio desde hace febrero de este a\u00f1o le instaba a abandonar la vivienda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Susa Plaza es una modista y dise\u00f1adora que ha vivido y trabajado siempre en la casa donde nacieron sus hermanas, en pleno barrio del Carmen de Valencia. El 16 de mayo recibi\u00f3 una \u201ccarta extorsionadora\u201d en el que el nuevo propietario del edificio desde hace febrero de este a\u00f1o le instaba a abandonar la vivienda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-05T16:49:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-05T16:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"589\" \/>\n\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d\",\"datePublished\":\"2021-06-05T16:49:55+00:00\",\"dateModified\":\"2021-06-05T16:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/\"},\"wordCount\":707,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/\",\"name\":\"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG\",\"datePublished\":\"2021-06-05T16:49:55+00:00\",\"dateModified\":\"2021-06-05T16:49:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG\",\"width\":589,\"height\":331,\"caption\":\"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World","og_description":"Susa Plaza es una modista y dise\u00f1adora que ha vivido y trabajado siempre en la casa donde nacieron sus hermanas, en pleno barrio del Carmen de Valencia. El 16 de mayo recibi\u00f3 una \u201ccarta extorsionadora\u201d en el que el nuevo propietario del edificio desde hace febrero de este a\u00f1o le instaba a abandonar la vivienda [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/","og_site_name":"Hot News in World","article_published_time":"2021-06-05T16:49:55+00:00","article_modified_time":"2021-06-05T16:49:57+00:00","og_image":[{"width":589,"height":331,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d","datePublished":"2021-06-05T16:49:55+00:00","dateModified":"2021-06-05T16:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/"},"wordCount":707,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/","url":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/","name":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG","datePublished":"2021-06-05T16:49:55+00:00","dateModified":"2021-06-05T16:49:57+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa.JPG","width":589,"height":331,"caption":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/vinieron-y-nos-dijeron-que-teniamos-que-dejar-nuestra-casa-en-10-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cVinieron y nos dijeron que ten\u00edamos que dejar nuestra casa en 10 d\u00edas\u201d"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2704"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2704\/revisions"}],"predecessor-version":[{"id":2706,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2704\/revisions\/2706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2705"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}