{"id":2728,"date":"2021-06-07T20:09:54","date_gmt":"2021-06-07T17:09:54","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/"},"modified":"2021-06-07T20:10:05","modified_gmt":"2021-06-07T17:10:05","slug":"pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/","title":{"rendered":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa"},"content":{"rendered":"<p>El maestro rural Pedro Castillo acaba de adelantar por primera vez en el conteo oficial a su rival, la derechista Keiko Fujimori. La candidata de Fuerza Per\u00fa llev\u00f3 la delantera durante las 12 primeras horas de c\u00f3mputo al contarse primero las casillas m\u00e1s cercanas a Lima, la capital, y las de las otras grandes ciudades del pa\u00eds. Castillo, de izquierdas, fue ganando fuerza a medida que el escrutinio se extendi\u00f3 a las zonas m\u00e1s remotas de Per\u00fa, hasta colocarse en primer lugar cerca del mediod\u00eda. Con el 94.059 % del escrutinio, Castillo tiene el 50.076% de los votos, por el 49.924% de Fujimori. Solo les separan 25.000 votos.El conteo est\u00e1 resultando tan ag\u00f3nico como la campa\u00f1a. Se va a decidir por unos cuantos miles de votos. La ventaja de Castillo, sin embargo, todav\u00eda no es definitiva. El voto del exterior (750.000 peruanos pod\u00edan ejercerlo) avanza lentamente, y vistos los primeros resultados va a ser favorable a Fujimori. En un margen tan estrecho cualquier voto puede ser determinante.\u201cVengo del Per\u00fa profundo\u201d, as\u00ed arranca Castillo sus m\u00edtines. Y puede que all\u00ed haya fraguado su victoria. Fujimori arranc\u00f3 con una ventaja de 600.000 votos al inicio del c\u00f3mputo que Castillo ha ido recortando a medida que se alejaba el escrutinio de las grandes urbes.Los dos sondeos que se dieron a conocer este domingo, despu\u00e9s del cierre de urnas, ya lo anunciaban y arrojaban un empate t\u00e9cnico. La candidata conservadora Keiko Fujimori logr\u00f3 una ligera ventaja en una encuesta a pie de urna (50,3% frente al 49,7%), mientras que el izquierdista Pedro Castillo se impuso por muy poco en el conteo r\u00e1pido (50,2% frente el 48,8%) publicado horas despu\u00e9s.Pedro Castillo y Keiko Fujimori, la noche de este domingo tras conocerse los primeros sondeos. En v\u00eddeo, declaraciones de los candidatos. LUKA GONZALES \/ AFP\/EFEFujimori recibi\u00f3 los resultados de los sondeos en Lima, en la capital, en la ciudad. Pedro Castillo en Tacabamba, en la sierra, en el mundo rural. Dos sitios distintos desde donde observar el pa\u00eds. Eso se ha notado en los resultados de las regiones, seg\u00fan los sondeos. En los lugares donde ha ganado uno u otro lo ha hecho con holgura. En alg\u00fan caso rozando el 90% de los votos.M\u00e1s informaci\u00f3nEl primer sondeo que daba esa peque\u00f1a diferencia a favor de la candidata de derechas tiene un margen de error del 3%, y estaba elaborado con entrevistas a 30.000 electores. En el segundo, el conteo r\u00e1pido, su margen de error es menor, del 1%, porque se hace con planillas de mesas elegidas que sean representativas. Aunque los m\u00e1rgenes son muy estrechos y el conteo oficial podr\u00eda alargarse durante d\u00edas, en uno y otro lugar celebraron con euforia cuando las encuestas les dieron vencedores por apenas unas d\u00e9cimas.Los Fujimori se abrazaron al conocer la encuesta a pie de urna. \u201cRecibimos con alegr\u00eda los resultados, pero al ver el margen, es fundamental mantener la prudencia. Y eso lo digo para todos los peruanos\u201d, dijo la candidata. Y entonces utiliz\u00f3 el mismo tono de concordia de las \u00faltimas semanas, con el que ha atra\u00eddo a un buen n\u00famero de antifujimoristas: \u201cAc\u00e1 lo que se tiene que buscar es la unidad de todos los peruanos. Desde ya invoco a la prudencia, a la calma, a la paz. A los que votaron y no votaron por nosotros\u201d.Ese primer flash inquiet\u00f3 a Castillo, que hizo p\u00fablica una carta dirigida a la autoridad electoral en la que exig\u00eda una revisi\u00f3n de todas las actas. De lado y lado se estuvo insinuando a lo largo de la jornada que podr\u00eda haber un pucherazo. \u201cConvoco al pueblo peruano de todos los rincones del pa\u00eds a asistir en paz a las calles para estar vigilantes en la defensa de la democracia. <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/ADefenderElVoto?src=hashtag_click\">#ADefenderElVoto<\/a>\u201d, escribi\u00f3 el maestro en un tuit. Ese primer sondeo, aunque suger\u00eda un empate t\u00e9cnico, hab\u00eda dejado fr\u00edos a sus seguidores. El segundo los llen\u00f3 de alegr\u00eda. En la plaza de Tacabamba, desde donde sigui\u00f3 la jornada el candidato, la gente comenz\u00f3 a gritar \u201c\u00a1s\u00ed se puede!\u201d.En Lima, los seguidores de ambos aspirantes tomaron las calles. Se encontraron en la plaza Bolognesi, un lugar cercano a los locales de los dos partidos, y se produjeron peque\u00f1os incidentes. La polic\u00eda trat\u00f3 de evitar los enfrentamientos y los invit\u00f3 a irse a casa, cerca de la medianoche. No se respet\u00f3 el toque de queda, que estaba previsto para las once de la noche.La campa\u00f1a ha dividido el pa\u00eds en dos corrientes. La tensi\u00f3n ha sido m\u00e1xima. Castillo, ganador de la primera vuelta (con 2,7 millones de votos, el 19%), lider\u00f3 durante los primeros 15 d\u00edas los sondeos, pero Fujimori remont\u00f3 en el \u00faltimo tramo. Se suele decir que en Per\u00fa nunca gana el favorito. La hija de Alberto Fujimori (1,9 millones de votos en la primera ronda, el 13%), el aut\u00f3crata que gobern\u00f3 el pa\u00eds entre 1992 y 2000, ha estado hiperpresente desde que lograra pasar a segunda vuelta. A cualquier hora que se encendiera el televisor aparec\u00eda en pantalla vestida con la camiseta de la selecci\u00f3n peruana, su uniforme de campa\u00f1a. Paneles por todo el pa\u00eds lanzaron mensajes a su favor de forma indirecta (aunque muy obvia) para burlar la ley electoral.Su principal arma ha sido alentar el miedo a una posible llegada de Castillo, que representa, para ella y la clase dirigente peruana que la ha apoyado sin matices, una aventura hacia el comunismo y el estatismo econ\u00f3mico. Fujimori, de 46 a\u00f1os, puede ser presidenta en el momento que menos capital pol\u00edtico atesora. Sus \u00faltimos cinco a\u00f1os de obstrucci\u00f3n en el Congreso maltrataron su imagen. La acusaci\u00f3n de un fiscal contra ella por lavado de dinero en el caso Odebrecht tampoco ayuda. Sin embargo, la oposici\u00f3n de una buena parte de la naci\u00f3n a lo que representa Castillo la ha aupado en las encuestas. Antifujimoristas hist\u00f3ricos como el escritor Mario Vargas Llosa la han apoyado.El perfil de Castillo, un sindicalista de izquierda radical, ha sido mucho m\u00e1s bajo que el de su oponente, en parte por decisi\u00f3n propia. El profesor, de 51 a\u00f1os, apenas ha ofrecido entrevistas. En los m\u00edtines se ha quejado de que no se estaba respetando la neutralidad que se le presupone a algunos sectores de la sociedad. Su mayor esfuerzo en el tramo final lo ha gastado en tratar de alejarse de Vladimir Cerr\u00f3n, el presidente de partido Per\u00fa Libre, al que est\u00e1 adscrito, m\u00e1s como invitado que como militante real. Cerr\u00f3n es un izquierdista dogm\u00e1tico y cercano a Cuba y Venezuela. En el \u00faltimo debate insisti\u00f3 en que respetar\u00e1 la propiedad privada y la econom\u00eda de mercado, pese a lo que diga su adversaria. Castillo ha tratado de atraer a \u00faltima hora a un votante m\u00e1s centrado y urbanita, que pod\u00eda tener la tentaci\u00f3n de votar a Fujimori como mal menor.Suscr\u00edbase aqu\u00ed a la newsletter de EL PA\u00cdS Am\u00e9rica y reciba todas las claves informativas de la actualidad de la regi\u00f3n.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-06-07\/la-encuesta-a-pie-de-urna-confirma-la-tendencia-al-alza-de-fujimori-en-las-elecciones-de-peru.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El maestro rural Pedro Castillo acaba de adelantar por primera vez en el conteo oficial a su rival, la derechista Keiko Fujimori. La candidata de Fuerza Per\u00fa llev\u00f3 la delantera durante las 12 primeras horas de c\u00f3mputo al contarse primero las casillas m\u00e1s cercanas a Lima, la capital, y las de las otras grandes ciudades [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"El maestro rural Pedro Castillo acaba de adelantar por primera vez en el conteo oficial a su rival, la derechista Keiko Fujimori. La candidata de Fuerza Per\u00fa llev\u00f3 la delantera durante las 12 primeras horas de c\u00f3mputo al contarse primero las casillas m\u00e1s cercanas a Lima, la capital, y las de las otras grandes ciudades [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T17:09:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T17:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa\",\"datePublished\":\"2021-06-07T17:09:54+00:00\",\"dateModified\":\"2021-06-07T17:10:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/\"},\"wordCount\":1229,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/\",\"name\":\"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg\",\"datePublished\":\"2021-06-07T17:09:54+00:00\",\"dateModified\":\"2021-06-07T17:10:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/","og_locale":"es_ES","og_type":"article","og_title":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World","og_description":"El maestro rural Pedro Castillo acaba de adelantar por primera vez en el conteo oficial a su rival, la derechista Keiko Fujimori. La candidata de Fuerza Per\u00fa llev\u00f3 la delantera durante las 12 primeras horas de c\u00f3mputo al contarse primero las casillas m\u00e1s cercanas a Lima, la capital, y las de las otras grandes ciudades [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/","og_site_name":"Hot News in World","article_published_time":"2021-06-07T17:09:54+00:00","article_modified_time":"2021-06-07T17:10:05+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa","datePublished":"2021-06-07T17:09:54+00:00","dateModified":"2021-06-07T17:10:05+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/"},"wordCount":1229,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/","url":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/","name":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg","datePublished":"2021-06-07T17:09:54+00:00","dateModified":"2021-06-07T17:10:05+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Pedro-Castillo-toma-la-delantera-y-aventaja-a-Keiko-Fujimori-scaled.jpg","width":2560,"height":1707,"caption":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/pedro-castillo-toma-la-delantera-y-aventaja-a-keiko-fujimori-con-el-50-07-de-los-votos-en-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pedro Castillo toma la delantera y aventaja a Keiko Fujimori con el 50.07% de los votos en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2728"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2728\/revisions"}],"predecessor-version":[{"id":2730,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2728\/revisions\/2730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2729"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}