{"id":2743,"date":"2021-06-09T03:39:16","date_gmt":"2021-06-09T00:39:16","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/"},"modified":"2021-06-09T03:39:25","modified_gmt":"2021-06-09T00:39:25","slug":"la-bretana-global-de-johnson-arranca-con-mal-pie","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/","title":{"rendered":"La Breta\u00f1a Global de Johnson arranca con mal pie"},"content":{"rendered":"<p>Boris Johnson ha comenzado a aplicar el manual de instrucciones del Brexit y a muchos brit\u00e1nicos no les gusta la imagen que les devuelve el espejo. El recorte del 0,7% al 0,5% de la ayuda internacional al desarrollo, en contra de la obligaci\u00f3n impuesta por la ley de 2015, ha provocado una rebeli\u00f3n sin precedentes entre muchos conservadores. La excusa es la pandemia y el enorme gasto p\u00fablico interno que ha sido necesario para paliar sus efectos. La consecuencia: cuando este viernes comience en Cornualles la cumbre del G-7, el Reino Unido ser\u00e1 la \u00fanica de las econom\u00edas ricas que recorta en ayuda exterior. La Breta\u00f1a Global que Johnson prometi\u00f3 despu\u00e9s de la salida de la UE ser\u00e1 as\u00ed, a ojos de muchos cr\u00edticos, un pa\u00eds m\u00e1s ego\u00edsta y con menos influencia internacional.\u201cNo es moralmente defendible aliviar nuestra carga financiera a costa de algunas de las personas m\u00e1s pobres y m\u00e1s vulnerables del mundo\u201d, ha dicho el ex primer ministro conservador, John Major. Los cinco \u00faltimos jefes de Gobierno anteriores a Johnson -el propio Major, Tony Blair, Gordon Brown, David Cameron y Theresa May- han unido sus voces en contra de una decisi\u00f3n que consideran un golpe irreversible a la imagen del Reino Unido. Junto a ellos, todos los partidos de la oposici\u00f3n, las principales asociaciones humanitarias, y hasta una docena de congresistas estadounidenses dem\u00f3cratas, que han exigido a Joe Biden que se pronuncie contra esos recortes, justo cuando Washington eleva considerablemente su partida presupuestaria.M\u00e1s informaci\u00f3nUn grupo de rebeldes del Partido Conservador, liderados por el exministro para el Desarrollo Internacional, Andrew Mitchell, han forzado este martes un debate en la C\u00e1mara de los Comunes sobre la presunta ilegalidad de la decisi\u00f3n. Han contado con la complicidad del speaker (presidente) del Parlamento brit\u00e1nico, Lindsay Hole, el primer indignado ante los intentos del Gobierno de impedir que los diputados trataran el asunto. Ha sido un \u201cdebate de emergencia\u201d, y el Gobierno ha evitado que hubiera votaci\u00f3n final, pero la mayor\u00eda de intervenciones han sacado los colores al Johnson liberal e internacionalista que presume de defender las causas justas. \u201cMe present\u00e9 a unas elecciones en las que el programa de mi partido se compromet\u00eda a mantener con orgullo la promesa del 0,7%\u201d, ha dicho la ex primera ministra May con notable irritaci\u00f3n en su rostro. \u201cNo nos escuchan en el resto del mundo porque seamos el Reino Unido, sino por nuestros hechos, y por c\u00f3mo llevamos a la pr\u00e1ctica nuestros principios. El da\u00f1o a nuestra reputaci\u00f3n de esta medida nos har\u00e1 m\u00e1s d\u00e9biles a la hora de argumentar cualquier causa\u201d.La ayuda brit\u00e1nica al desarrollo exterior seguir\u00e1 siendo una de las m\u00e1s elevadas de las naciones desarrolladas, pero el recorte previsto, cerca de 5.200 millones de euros, se traduce en un dr\u00e1stico descenso de la partida destinada a la escolarizaci\u00f3n de ni\u00f1as, purificaci\u00f3n de aguas o combate contra el tr\u00e1fico de esclavos en naciones como Somalia, Siria, Yemen o Afganist\u00e1n. La desaparici\u00f3n de un departamento concreto destinado al Desarrollo Internacional, la integraci\u00f3n de su presupuesto en el del Ministerio de Asuntos Exteriores, y el incremento de la ayuda la vacunaci\u00f3n internacional, ha agotado los recursos para otros proyectos que requieren de la misma o mayor urgencia.A la espera de los tribunalesEl Gobierno de Johnson asegura que su decisi\u00f3n es coyuntural, y que regresar\u00e1 al 0,7% en cuanto la econom\u00eda lo permita. La Ley de Objetivo de Ayuda Internacional, aprobada en 2015, contempla en su texto una excepci\u00f3n: \u201clas circunstancias econ\u00f3micas, y en particular, un cambio sustancial en el producto interior bruto\u201d. Pero es una excepci\u00f3n jur\u00eddicamente discutible, puesto que se refiere a la posibilidad de que el objetivo no se pueda cumplir, no al hecho de que se cambie de modo deliberado. M\u00e1s a\u00fan, Downing Street se ha resistido incluso al compromiso de revertir la medida el a\u00f1o que viene, a pesar de que el Banco de Inglaterra ha anunciado -y el Gobierno de Johnson cuenta con ello- que la econom\u00eda volver\u00e1 a crecer con fuerza en la segunda mitad de 2021. Todo apunta a que la \u00faltima palabra ser\u00e1 la de los tribunales brit\u00e1nicos.M\u00e1s all\u00e1 de la obstinaci\u00f3n del ministro de Econom\u00eda, Rishi Sunak, por cuadrar las cuentas, hay una raz\u00f3n pol\u00edtica por la que Johnson persiste en su empe\u00f1o. Los votantes tradicionalmente de izquierdas en el llamado \u201cmuro rojo\u201d del norte de Inglaterra, los mismos que respaldaron el Brexit y que se han pasado ahora a las filas de un Partido Conservador mucho m\u00e1s nacionalista y populista, respaldan la decisi\u00f3n. Seg\u00fan la \u00faltima encuesta de YouGov, un 54% de los ciudadanos, frente a un 28%, cree que \u201cel Gobierno acierta al reducir la ayuda exterior\u201d.\u201cEsta decisi\u00f3n es inmoral para el mundo y muy poco pr\u00e1ctica para el Reino Unido\u201dDavid Davis, diputado conservadorEl problema de esas encuestas, sin embargo, radica en la simplicidad de su pregunta. Lo explicaba parad\u00f3jicamente el diputado conservador David Davis, uno de los m\u00e1s rabiosos defensores de la salida del Reino Unido de la UE que, sin embargo, se ha aliado en esta ocasi\u00f3n con los rebeldes: \u201cPor supuesto prefieren que el dinero se gaste en los colegios brit\u00e1nicos antes que en los de otro pa\u00eds\u201d, ha dicho Davis. \u201cPero cuando pones sobre la mesa la verdadera cuesti\u00f3n es cuando surge la honestidad brit\u00e1nica. Cuando preguntas si desean que los ni\u00f1os mueran por culpa del agua contaminada, un 76% se muestra en contra. Esta decisi\u00f3n es inmoral para el mundo y muy poco pr\u00e1ctica para el Reino Unido\u201d.Despu\u00e9s de m\u00e1s de un a\u00f1o de pandemia y de confinamiento forzoso, durante el que Johnson apenas ha podido hacer otra cosa que proclamar con discursos y gestos su visi\u00f3n de un nuevo Reino Unido \u201clibre de las cadenas de la UE\u201d y abierto al mundo, su mejor oportunidad de brillar iba a llegar este fin de semana. La cumbre del G-7 en Cornualles, que comienza el viernes, era el primer encuentro en persona de los l\u00edderes de las naciones m\u00e1s ricas del mundo. Y la primera visita a Europa del nuevo presidente estadounidense, Joe Biden. Su mensaje de solidaridad global, su esfuerzo renovado para combatir el cambio clim\u00e1tico, su apuesta por extender las vacunas a todos los continentes, se han visto precedidos por un enorme tir\u00f3n de orejas del Parlamento, que ha acusado al primer ministro de mostrar el lado m\u00e1s feo de la Breta\u00f1a Global que el Brexit iba a traer consigo.Un tir\u00f3n de orejas por Irlanda del Norte A Joe Biden nunca le gust\u00f3 el Brexit. Pero m\u00e1s all\u00e1 de esa realidad ya irreversible, el presidente estadounidense, de ra\u00edces irlandesas, considera fundamental el mantenimiento del Protocolo de Irlanda del Norte que trajo consigo el Acuerdo de Retirada del Reino Unido de la UE. Es la garant\u00eda, cree Washington, para preservar la paz alcanzada en la regi\u00f3n con los Acuerdos de Viernes Santo. Biden llega esta semana a territorio brit\u00e1nico justo cuando la tensi\u00f3n entre Londres y Bruselas por este asunto est\u00e1 a su nivel m\u00e1s alto. David Frost, el negociador de Johnson para asuntos europeos, y el vicepresidente de la Comisi\u00f3n Europea, Maros Sefcovic, se re\u00fanen este mi\u00e9rcoles en la capital del Reino Unido para intentar desencallar una situaci\u00f3n muy delicada. Frost exige a la UE m\u00e1s flexibilidad para revisar un protocolo que ha impuesto serias trabas burocr\u00e1ticas al comercio entre Irlanda del Norte y Gran Breta\u00f1a. Y que ha encendido los \u00e1nimos de las fuerzas unionistas en la regi\u00f3n. Sefcovic ha advertido, en las p\u00e1ginas del diario brit\u00e1nico The Daily Telegraph, de que \u201csi el Reino Unido toma m\u00e1s medidas unilaterales en las pr\u00f3ximas semanas [el Gobierno de Johnson ha decidido ignorar los controles acordados], la UE no ser\u00e1 t\u00edmida en reaccionar de un modo r\u00e1pido y firme\u201d. En el pasado, el equipo de Biden ya ha sugerido que una falta de cumplimiento por parte de Londres, de sus compromisos sobre Irlanda del Norte, ser\u00eda un obst\u00e1culo muy serio para la conclusi\u00f3n de un acuerdo comercial entre Estados Unidos y el Reino Unido. Justo el principal objetivo que se marc\u00f3 el Gobierno conservador para demostrar que la aventura del Brexit hab\u00eda merecido la pena.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-06-08\/la-bretana-global-de-johnson-arranca-con-mal-pie.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boris Johnson ha comenzado a aplicar el manual de instrucciones del Brexit y a muchos brit\u00e1nicos no les gusta la imagen que les devuelve el espejo. El recorte del 0,7% al 0,5% de la ayuda internacional al desarrollo, en contra de la obligaci\u00f3n impuesta por la ley de 2015, ha provocado una rebeli\u00f3n sin precedentes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Boris Johnson ha comenzado a aplicar el manual de instrucciones del Brexit y a muchos brit\u00e1nicos no les gusta la imagen que les devuelve el espejo. El recorte del 0,7% al 0,5% de la ayuda internacional al desarrollo, en contra de la obligaci\u00f3n impuesta por la ley de 2015, ha provocado una rebeli\u00f3n sin precedentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T00:39:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T00:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"La Breta\u00f1a Global de Johnson arranca con mal pie\",\"datePublished\":\"2021-06-09T00:39:16+00:00\",\"dateModified\":\"2021-06-09T00:39:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/\"},\"wordCount\":1466,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/\",\"name\":\"La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg\",\"datePublished\":\"2021-06-09T00:39:16+00:00\",\"dateModified\":\"2021-06-09T00:39:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg\",\"width\":2560,\"height\":1683,\"caption\":\"La Breta\u00f1a Global de Johnson arranca con mal pie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-bretana-global-de-johnson-arranca-con-mal-pie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Breta\u00f1a Global de Johnson arranca con mal pie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/","og_locale":"es_ES","og_type":"article","og_title":"La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World","og_description":"Boris Johnson ha comenzado a aplicar el manual de instrucciones del Brexit y a muchos brit\u00e1nicos no les gusta la imagen que les devuelve el espejo. El recorte del 0,7% al 0,5% de la ayuda internacional al desarrollo, en contra de la obligaci\u00f3n impuesta por la ley de 2015, ha provocado una rebeli\u00f3n sin precedentes [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/","og_site_name":"Hot News in World","article_published_time":"2021-06-09T00:39:16+00:00","article_modified_time":"2021-06-09T00:39:25+00:00","og_image":[{"width":2560,"height":1683,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"La Breta\u00f1a Global de Johnson arranca con mal pie","datePublished":"2021-06-09T00:39:16+00:00","dateModified":"2021-06-09T00:39:25+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/"},"wordCount":1466,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/","url":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/","name":"La Breta\u00f1a Global de Johnson arranca con mal pie - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg","datePublished":"2021-06-09T00:39:16+00:00","dateModified":"2021-06-09T00:39:25+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-Bretana-Global-de-Johnson-arranca-con-mal-pie-scaled.jpg","width":2560,"height":1683,"caption":"La Breta\u00f1a Global de Johnson arranca con mal pie"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/la-bretana-global-de-johnson-arranca-con-mal-pie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Breta\u00f1a Global de Johnson arranca con mal pie"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2743"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2743\/revisions"}],"predecessor-version":[{"id":2745,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2743\/revisions\/2745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2744"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}