{"id":2755,"date":"2021-06-10T03:58:03","date_gmt":"2021-06-10T00:58:03","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/"},"modified":"2021-06-10T03:58:06","modified_gmt":"2021-06-10T00:58:06","slug":"placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/","title":{"rendered":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles"},"content":{"rendered":"<p>No hab\u00eda terminado de entrar Pl\u00e1cido Domingo en el escenario del Auditorio Nacional cuando el p\u00fablico estall\u00f3 en aplausos. Era la bienvenida que el p\u00fablico madrile\u00f1o ha brindado este mi\u00e9rcoles al cantante despu\u00e9s de un a\u00f1o y medio de ausencia en los escenarios espa\u00f1oles por las acusaciones de acoso sexual vertidas contra \u00e9l por una veintena de mujeres en Estados Unidos. M\u00e1s de tres minutos de v\u00edtores y piropos variados: \u201c\u00a1Bravo!\u201d, \u201c\u00a1Eres el m\u00e1s grande!\u201d. Tan intensa era la ovaci\u00f3n que el resto de los m\u00fasicos que iban a salir a cantar despu\u00e9s, entre ellos la soprano Ainhoa Arteta y la veterana bailarina y concertista de casta\u00f1uelas Lucero Tena, salieron de sus camerinos para sumarse al aplauso, lo que hizo que el artista acabara con l\u00e1grimas en los ojos. La emoci\u00f3n fue aumentando a medida que avanzaba el recital, de modo que al final desbordaba: cinco bises tuvo que cantar el tenor para calmar las ansias de los espectadores.M\u00e1s informaci\u00f3nYa a la entrada del Auditorio Nacional se respiraban las ganas que ten\u00edan esos espectadores de reencontrarse con Domingo. Un p\u00fablico de todas las edades, pero mayoritariamente femenino, entre ellas la presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, que declar\u00f3: \u201cEs un orgullo tenerle entre nosotros. Uno de los mejores tenores y uno de los mayores embajadores que ha tenido Espa\u00f1a. Es un orgullo tenerle en Espa\u00f1a\u201d. El concierto, organizado por la Fundaci\u00f3n Excelentia en beneficio de Cruz Roja Responde para ayudar a las personas m\u00e1s vulnerables afectadas por la pandemia, hab\u00eda despertado mucha expectaci\u00f3n desde que se anunci\u00f3 hace un mes y apenas quedaron sin vender algunas butacas sueltas de las 1.620 puestas a la venta, por las medidas anticovid, de las 2.340 que tiene la Sala Sinf\u00f3nica del Auditorio Nacional, con precios que oscilaban entre 55 y 175 euros.El concierto comenz\u00f3 con una pieza instrumental, el preludio de la Carmen de Bizet, interpretado por la Orquesta Cl\u00e1sica Santa Cecilia con Josep Caball\u00e9 Domenech a la batuta. Y justo despu\u00e9s sali\u00f3 Domingo para interpretar Nemico della patria?! (Enemigo de la patria), el aria principal del bar\u00edtono de la \u00f3pera Andr\u00e9a Ch\u00e9nier, de Umberto Giordano. Al terminar, otra ovaci\u00f3n.Despu\u00e9s sonaron m\u00e1s arias y d\u00faos de Verdi, Donizzeti, Fern\u00e1ndez Caballero o Ger\u00f3nimo Gim\u00e9nez, en las voces de Ainhoa Arteta, Mar\u00eda Jos\u00e9 Siri, Jorge de Le\u00f3n, Virginia Tola, Marina Monz\u00f3, Nicholas Brownlee y el propio Domingo (cant\u00f3 cinco de las 16 obras que formaban el programa), la guitarra de Pablo Sainz Villegas y las casta\u00f1uelas de Lucero Tena, que tambi\u00e9n desat\u00f3 una entusiasta ovaci\u00f3n entre el p\u00fablico.El cierre del concierto, como se ve\u00eda venir, fue apote\u00f3sico. Domingo cant\u00f3 lo que estaba previsto en el programa, un aria de El d\u00fao de la africana, la zarzuela m\u00e1s conocida de Manuel Fern\u00e1ndez Caballero. Pero al terminar, el p\u00fablico dej\u00f3 claro que ese no pod\u00eda ser el final. Y empezaron a sucederse los bises: cinco de \u00e9l y otro de Jorge de Le\u00f3n. Los de Domingo: la romanza Luch\u00e9 la fe por el triunfo, de la zarzuela Luisa Fernanda; una pieza de la opereta La viuda alegre, con Ainhoa Arteta; el pasodoble La morena de mi copla, el bolero B\u00e9same mucho y la canci\u00f3n napolitana Non ti scordar di me. El ambiente era de fiesta total.Ensayo del concierto de Pl\u00e1cido Domingo en el Auditorio Nacional.Jos\u00e9 Luis R. Cort\u00e9sDomingo no ha querido hacer ninguna declaraci\u00f3n a la prensa en Madrid. Cuando se anunci\u00f3 este concierto, se limit\u00f3 a divulgar un breve mensaje a trav\u00e9s de su agencia de comunicaci\u00f3n: \u201cEstoy muy feliz de volver a Madrid. Para m\u00ed ser\u00e1 una gran emoci\u00f3n cantar a mi gente. La m\u00fasica nos une y se funde en el coraz\u00f3n del proyecto solidario Cruz Roja Responde\u201d. Ainhoa Arteta, que desde el primer momento sali\u00f3 en defensa del tenor tras las acusaciones, tambi\u00e9n hizo una corta declaraci\u00f3n tras conocerse su participaci\u00f3n en el recital de Madrid: \u201cSiempre es un motivo de satisfacci\u00f3n dedicar una velada especial cuyo prop\u00f3sito es la generosidad. Cantar con Pl\u00e1cido siempre ha sido un gran placer y un honor y ser\u00e9 muy feliz all\u00ed\u201d. La soprano cantar\u00e1 tambi\u00e9n en el siguiente concierto que dar\u00e1 el tenor en Espa\u00f1a, previsto para el 18 de agosto dentro del festival Starlite de Marbella, descrito por los organizadores como \u201cuna gran fiesta en su honor\u201d.La \u00faltima vez que Domingo actu\u00f3 en Espa\u00f1a fue en diciembre de 2019 en Les Arts de Valencia, cuando particip\u00f3 en la \u00f3pera Nabucco, donde encarnaba al rey que da nombre a esta obra de Verdi. Esta actuaci\u00f3n se produjo poco despu\u00e9s de que se conocieran las acusaciones. En un primer momento, Domingo calific\u00f3 de falsos estos casos de acoso y, en distintas entrevistas y pa\u00edses, afirm\u00f3 que nunca hab\u00eda abusado de nadie, pero despu\u00e9s de la investigaci\u00f3n del sindicato de m\u00fasicos de \u00f3pera de EE UU, que concluy\u00f3 que hab\u00eda abusado de su poder y acosado a las denunciantes, pidi\u00f3 perd\u00f3n por \u201cel dolor\u201d que les pudo causar y asumi\u00f3 \u201ctoda la responsabilidad\u201d de sus acciones. El esc\u00e1ndalo, en plena campa\u00f1a del #MeToo, provoc\u00f3 su dimisi\u00f3n como director de la \u00d3pera de Los \u00c1ngeles y la cancelaci\u00f3n de la mayor\u00eda de las actuaciones en todo el mundo que ten\u00eda ya firmadas. Domingo no ha vuelto a trabajar en Estados Unidos, aunque s\u00ed en otros pa\u00edses europeos.El cantante, que el pasado enero cumpli\u00f3 80 a\u00f1os, ha pasado casi toda la pandemia en Acapulco (M\u00e9xico). All\u00ed tuvo que ser hospitalizado tras contagiarse de covid-19, de la que se recuper\u00f3 despu\u00e9s poco a poco en su domicilio familiar. Su mujer tambi\u00e9n contrajo la enfermedad. Hace unos meses ha vuelto a Europa, seg\u00fan informa un responsable de su equipo de prensa.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/cultura\/2021-06-09\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hab\u00eda terminado de entrar Pl\u00e1cido Domingo en el escenario del Auditorio Nacional cuando el p\u00fablico estall\u00f3 en aplausos. Era la bienvenida que el p\u00fablico madrile\u00f1o ha brindado este mi\u00e9rcoles al cantante despu\u00e9s de un a\u00f1o y medio de ausencia en los escenarios espa\u00f1oles por las acusaciones de acoso sexual vertidas contra \u00e9l por una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"No hab\u00eda terminado de entrar Pl\u00e1cido Domingo en el escenario del Auditorio Nacional cuando el p\u00fablico estall\u00f3 en aplausos. Era la bienvenida que el p\u00fablico madrile\u00f1o ha brindado este mi\u00e9rcoles al cantante despu\u00e9s de un a\u00f1o y medio de ausencia en los escenarios espa\u00f1oles por las acusaciones de acoso sexual vertidas contra \u00e9l por una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-10T00:58:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-10T00:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles\",\"datePublished\":\"2021-06-10T00:58:03+00:00\",\"dateModified\":\"2021-06-10T00:58:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/\"},\"wordCount\":1054,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/\",\"name\":\"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg\",\"datePublished\":\"2021-06-10T00:58:03+00:00\",\"dateModified\":\"2021-06-10T00:58:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg\",\"caption\":\"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/","og_locale":"es_ES","og_type":"article","og_title":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World","og_description":"No hab\u00eda terminado de entrar Pl\u00e1cido Domingo en el escenario del Auditorio Nacional cuando el p\u00fablico estall\u00f3 en aplausos. Era la bienvenida que el p\u00fablico madrile\u00f1o ha brindado este mi\u00e9rcoles al cantante despu\u00e9s de un a\u00f1o y medio de ausencia en los escenarios espa\u00f1oles por las acusaciones de acoso sexual vertidas contra \u00e9l por una [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/","og_site_name":"Hot News in World","article_published_time":"2021-06-10T00:58:03+00:00","article_modified_time":"2021-06-10T00:58:06+00:00","og_image":[{"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles","datePublished":"2021-06-10T00:58:03+00:00","dateModified":"2021-06-10T00:58:06+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/"},"wordCount":1054,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/","url":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/","name":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg","datePublished":"2021-06-10T00:58:03+00:00","dateModified":"2021-06-10T00:58:06+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Placido-Domingo-arranca-cinco-bises-en-su-regreso-a-los.jpg","caption":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/placido-domingo-arranca-cinco-bises-en-su-regreso-a-los-escenarios-espanoles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pl\u00e1cido Domingo arranca cinco bises en su regreso a los escenarios espa\u00f1oles"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2755"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2755\/revisions"}],"predecessor-version":[{"id":2757,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2755\/revisions\/2757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2756"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}