{"id":2773,"date":"2021-06-11T16:05:48","date_gmt":"2021-06-11T13:05:48","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/"},"modified":"2021-06-11T16:05:55","modified_gmt":"2021-06-11T13:05:55","slug":"la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/","title":{"rendered":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar"},"content":{"rendered":"<p>Los equipos de la Guardia Civil prosiguen este viernes la b\u00fasqueda el cad\u00e1ver de Anna, de un a\u00f1o, y de su padre, Tom\u00e1s Gimeno, de 37, en una zona submarina acotada de pocos metros de la costa tinerfe\u00f1a. El cuerpo de la hermana mayor, Olivia, de seis a\u00f1os, fue hallado el mi\u00e9rcoles a 1.000 metros de profundidad a tres millas n\u00e1uticas (unos 5,5 kil\u00f3metros) de tierra firme dentro de una bolsa de deporte atada al ancla de la embarcaci\u00f3n de Gimeno. A los tres se les hab\u00eda perdido el rastro el 27 de abril, cuando el padre no volvi\u00f3 a casa de su expareja con sus hijas como estaba previsto. La noticia del hallazgo del cuerpo, que corrobora lo que la polic\u00eda sospech\u00f3 desde un principio, esto es, que las dos ni\u00f1as secuestradas por su padre est\u00e1n muertas, ha sumido a las islas en la estupefacci\u00f3n, la indignaci\u00f3n y la repulsa. En varios organismos oficiales se est\u00e1n celebrando manifestaciones de rechazo a la violencia machista.Mientras, el director del Instituto de Medicina Legal y Ciencias Forenses de Santa Cruz de Tenerife, Jes\u00fas Vega, ha manifestado que la autopsia al cad\u00e1ver de Olivia se iniciar\u00e1 en los pr\u00f3ximos d\u00edas. \u201cHay que llevar a cabo antes unas cuantas pruebas y an\u00e1lisis. Va a llevar tiempo. Esta va a ser una autopsia complicada\u201d, a\u00f1adi\u00f3. El examen del cad\u00e1ver tratar\u00e1 de resolver algunas de las muchas dudas que a\u00fan ensombrecen este caso, como las causas de la muerte.Al lado de la bolsa de deporte en el que se encontraba el cad\u00e1ver de Anna, el robot del buque de la Guardia Civil \u00c1ngeles Alvari\u00f1o, propiedad del Instituto Espa\u00f1ol de Oceanograf\u00eda, hall\u00f3 una segunda bolsa vac\u00eda y es a ese \u00e1rea acotada a la que se ha reducido la b\u00fasqueda, informa Patricia Ortega Dolz. La noche de su desaparici\u00f3n, Gimeno fue visto cargando en su embarcaci\u00f3n de recreo seis bultos. Esta embarcaci\u00f3n, de seis metros de eslora, sin ancla, fue encontrada navegando a la deriva el 28 de abril, despu\u00e9s de que la madre de las ni\u00f1as, Beatriz Zimmermann, denunciase a la Guardia Civil que su expareja no hab\u00eda regresado con sus hijas y que, adem\u00e1s, le hab\u00eda asegurado por tel\u00e9fono que no las volver\u00eda a ver con vida. En la embarcaci\u00f3n de recreo hab\u00eda rastros de sangre del padre. El delegado del Gobierno en Canarias, Anselmo Pestana, asegur\u00f3 hoy que el buque proseguir\u00e1 con los trabajos de b\u00fasqueda al menos hasta el lunes, tras dos pr\u00f3rrogas.El buque oceanogr\u00e1fico \u00c1ngeles Alvari\u00f1o contin\u00faa la b\u00fasqueda de la peque\u00f1a Anna y de su padre a escasos kil\u00f3metros de la costa de Santa Cruz de Tenerife, este viernes.Miguel Barreto \/ EFEMientras prosiguen las labores de b\u00fasqueda, se multiplican las manifestaciones de rechazo en Canarias. El presidente del Gobierno, \u00c1ngel V\u00edctor Torres, y el del Parlamento de Canarias, Gustavo Matos, han participado este mediod\u00eda en una concentraci\u00f3n en la sede de Presidencia en Las Palmas de Gran Canaria, al igual que los representantes de los cabildos insulares y los principales ayuntamientos del archipi\u00e9lago.El defensor del pueblo en funciones, Francisco Fern\u00e1ndez Marug\u00e1n, ha asegurado en su cuenta de Twitter que \u201ctodas las administraciones y la sociedad deben trabajar juntas para proteger a las v\u00edctimas de violencia machista y a sus hijas e hijos\u201d. El Colegio Alem\u00e1n de Santa Cruz de Tenerife, donde estudiaba Olivia y estudi\u00f3 la madre, va a guardar este viernes un minuto de silencio por su asesinato.Anna y Olivia constituyen la \u00faltima muestra de una forma de violencia machista, a\u00fan poco conocida socialmente, la denominada violencia vicaria, que consiste en causar da\u00f1o a la madre a trav\u00e9s de los hijos. Desde 2013, a\u00f1o en que comienzan a formar parte de los datos oficiales, 41 menores han sido asesinados, seis de ellos en las islas Canarias incluyendo a Olivia y, presumiblemente, a Anna. En todos los casos excepto tres, los asesinos eran los padres biol\u00f3gicos. En estos otros asesinatos, los autores eran pareja o expareja de las madres.La delegada del Gobierno contra la Violencia de G\u00e9nero, Victoria Rosell, ha indicado que es previsible que contin\u00fae el repunte de violencia machista y ha pedido a todos los ayuntamientos, comunidades aut\u00f3nomas y colectivos de mujeres que est\u00e9n alerta en verano para proteger a las v\u00edctimas y sus hijos ante el menor indicio de maltrato.Por ello, el movimiento feminista ha convocado para este viernes a las 22.00 concentraciones en todos los ayuntamientos espa\u00f1oles en se\u00f1al de repulsa a los cr\u00edmenes machistas. La concentraci\u00f3n se est\u00e1 promoviendo bajo los lemas #SiTocanAUnaNosTocanATodas, #LoVamosATirar y #NiUnaMenos.B\u00fasqueda 24 horas al d\u00edaEsta es la primera vez que el buque del IEO participa en una misi\u00f3n de estas caracter\u00edsticas, dado que su labor generalmente se ci\u00f1e a la investigaci\u00f3n cient\u00edfica de los fondos marinos. En un primer momento, seg\u00fan el calendario asignado por el Instituto Oceanogr\u00e1fico Espa\u00f1ol, se calcul\u00f3 que el buque realizar\u00eda labores de b\u00fasqueda hasta el 9 de junio, el pasado mi\u00e9rcoles, pero el hallazgo de una funda n\u00f3rdica y una bombona de ox\u00edgeno ese d\u00eda llev\u00f3 a los investigadores a mantener el barco en la zona.Durante 24 horas al d\u00eda, los aparatos del buque radiograf\u00edan el abrupto fondo marino canario con una Ecosonda Multihaz EM 710 y bajo la supervisi\u00f3n de dos agentes de la Polic\u00eda Judicial de la Guardia Civil. El funcionamiento de estas ecosondas se basa en el tiempo que tarda una onda ac\u00fastica en recorrer la distancia entre el punto de partida y el fondo del mar y su retorno al punto inicial. De esta forma simult\u00e1neamente una gran cantidad de ondas ac\u00fasticas que a su regreso se convierten en impulsos el\u00e9ctricos y permiten dibujar un mapa del fondo. Este proceso se puede repetir hasta 100 veces por segundo.Olivia y Anna.SOS DesaparecidosEl tel\u00e9fono 016 atiende a las v\u00edctimas de violencia machista las 24 horas y en 51 idiomas. No deja rastro en la factura, pero hay que borrarlo del registro de llamadas. Los menores tambi\u00e9n pueden dirigirse al tel\u00e9fono de la Fundaci\u00f3n ANAR 900 20 20 10 y los ciudadanos testigos de alguna agresi\u00f3n, al 112.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/sociedad\/2021-06-11\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-mar.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los equipos de la Guardia Civil prosiguen este viernes la b\u00fasqueda el cad\u00e1ver de Anna, de un a\u00f1o, y de su padre, Tom\u00e1s Gimeno, de 37, en una zona submarina acotada de pocos metros de la costa tinerfe\u00f1a. El cuerpo de la hermana mayor, Olivia, de seis a\u00f1os, fue hallado el mi\u00e9rcoles a 1.000 metros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2774,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Los equipos de la Guardia Civil prosiguen este viernes la b\u00fasqueda el cad\u00e1ver de Anna, de un a\u00f1o, y de su padre, Tom\u00e1s Gimeno, de 37, en una zona submarina acotada de pocos metros de la costa tinerfe\u00f1a. El cuerpo de la hermana mayor, Olivia, de seis a\u00f1os, fue hallado el mi\u00e9rcoles a 1.000 metros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T13:05:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T13:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar\",\"datePublished\":\"2021-06-11T13:05:48+00:00\",\"dateModified\":\"2021-06-11T13:05:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/\"},\"wordCount\":1120,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/\",\"name\":\"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg\",\"datePublished\":\"2021-06-11T13:05:48+00:00\",\"dateModified\":\"2021-06-11T13:05:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/","og_locale":"es_ES","og_type":"article","og_title":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World","og_description":"Los equipos de la Guardia Civil prosiguen este viernes la b\u00fasqueda el cad\u00e1ver de Anna, de un a\u00f1o, y de su padre, Tom\u00e1s Gimeno, de 37, en una zona submarina acotada de pocos metros de la costa tinerfe\u00f1a. El cuerpo de la hermana mayor, Olivia, de seis a\u00f1os, fue hallado el mi\u00e9rcoles a 1.000 metros [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/","og_site_name":"Hot News in World","article_published_time":"2021-06-11T13:05:48+00:00","article_modified_time":"2021-06-11T13:05:55+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar","datePublished":"2021-06-11T13:05:48+00:00","dateModified":"2021-06-11T13:05:55+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/"},"wordCount":1120,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/","url":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/","name":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg","datePublished":"2021-06-11T13:05:48+00:00","dateModified":"2021-06-11T13:05:55+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-busqueda-de-la-hermana-de-Olivia-se-centra-en-scaled.jpg","width":2560,"height":1440,"caption":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/la-busqueda-de-la-hermana-de-olivia-se-centra-en-un-area-de-escasos-metros-en-el-fondo-del-mar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"La b\u00fasqueda de la hermana de Olivia se centra en un \u00e1rea de escasos metros en el fondo del mar"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2773"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2773\/revisions"}],"predecessor-version":[{"id":2775,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2773\/revisions\/2775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2774"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}