{"id":2793,"date":"2021-06-13T08:52:41","date_gmt":"2021-06-13T05:52:41","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/"},"modified":"2021-06-13T08:52:50","modified_gmt":"2021-06-13T05:52:50","slug":"la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/","title":{"rendered":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras"},"content":{"rendered":"<p>Una enfermera de un hospital de Yaba, en Nigeria, recibe la primera dosis de la vacuna contra la covid-19 el pasado mes de marzo.Sunday Alamba \/ APUn vecino de Pretoria (Sud\u00e1frica) se queja en en la emisora Radio Power del ritmo de inmunizaci\u00f3n en \u00c1frica. \u201cEs una verg\u00fcenza. Primero lo que tardaron en vacunar al personal m\u00e9dico, luego la lentitud con los mayores de 60 a\u00f1os y, ahora, con la vuelta presencial a la escuela tras las vacaciones, a\u00fan no han empezado con los profesores\u201d, critica. Sud\u00e1frica es el pa\u00eds m\u00e1s rico de \u00c1frica y solo un 0,8% de su poblaci\u00f3n est\u00e1 inmunizada, una muestra de lo que ocurre en todo el continente, que enfrenta la tercera ola de la pandemia.M\u00e1s informaci\u00f3nEl director de los Centros de Control de Enfermedades en \u00c1frica, John Nkengansong, aseguraba esta semana a los medios: \u201cEs extremadamente preocupante y en ocasiones frustrante\u201d. Las cifras confirman sus palabras. Con un incremento de un 13% de los casos en el \u00faltimo mes en todo el continente, hay pa\u00edses como la Rep\u00fablica Democr\u00e1tica del Congo, Uganda o la propia Sud\u00e1frica, donde la pandemia sigue disparada. En al menos 13 pa\u00edses, entre ellos Kenia, o Nigeria, se ha detectado la variante delta (la india) y el temor a un brote explosivo va en aumento. En este contexto, mientras en Europa y Estados Unidos las tasas de vacunaci\u00f3n superan con creces el 20%, en \u00c1frica ronda el 0,6%, con menos de 10 millones de personas que han sido inmunizadas.C\u00e9lestin Traor\u00e9, responsable de vacunaci\u00f3n de Unicef para \u00c1frica occidental y central, apunta al acaparamiento de las vacunas por parte de los pa\u00edses ricos como parte del problema. \u201cHay una escasez en el mundo y los pa\u00edses en desarrollo, como los africanos, no cuentan con la financiaci\u00f3n suficiente para adquirirlas\u201d, asegura. Otro desaf\u00edo es la debilidad de los sistemas de salud que no disponen de suficientes frigor\u00edficos, energ\u00eda el\u00e9ctrica, protocolos adaptados o formaci\u00f3n para sus campa\u00f1as. \u201cA ello hay que sumar los graves problemas de inseguridad a los que se enfrentan numerosos pa\u00edses, sobre todo en el Sahel, donde hay 5,4 millones de personas desplazadas por la violencia\u201d, a\u00f1ade el doctor Traor\u00e9.El respetado epidemi\u00f3logo sudafricano Salim Abdool Karim pone cifras al desequilibrio. \u201cSomos 7.500 millones de personas en el mundo y hay 1.800 millones de vacunas. Esto significa que una de cada cinco personas tiene acceso a las mismas, mientras que la realidad en \u00c1frica es que tenemos una para cada 50 personas. Es una desigualdad tremenda e injusta\u201d. En Chad comenzaron a vacunar el pasado 4 de junio, seis meses despu\u00e9s de que comenzara la inmunizaci\u00f3n en Europa, y en Tanzania, Eritrea o Burundi no se ha administrado ni una sola dosis.Para tratar de reducir la brecha de vacunaci\u00f3n entre los pa\u00edses ricos y los pa\u00edses en desarrollo surgi\u00f3 Covax, una iniciativa p\u00fablico-privada impulsada desde los comienzos de la pandemia por la Organizaci\u00f3n Mundial de la Salud (OMS), la Alianza por las Vacunas Gavi, Unicef y otros organismos internacionales, que se ha marcado como objetivo que el 20% de la poblaci\u00f3n de las naciones con menos recursos est\u00e9 vacunada a finales del presente a\u00f1o. Todos los pa\u00edses africanos se sumaron a este proyecto. Sin embargo, a la escasez mundial de dosis agravada por la compra abusiva de los pa\u00edses desarrollados se ha a\u00f1adido otro inconveniente: 190 millones de vacunas comprometidas por el Instituto Serum de la India para Covax tuvieron que destinarse a su propia poblaci\u00f3n ante la explosi\u00f3n de casos en este pa\u00eds.\u201cA\u00fan podemos conseguirlo, pero el escenario es incierto\u201d, asegura Blanca Carazo, responsable de programas internacionales de Unicef-Espa\u00f1a. Buena parte del futuro de Covax y, por tanto, de una vacunaci\u00f3n m\u00e1s justa en el mundo, se juega en la cumbre del G-7 de este fin de semana en Cornualles. \u201cLas promesas de estos pa\u00edses de compartir una parte de sus vacunas es fundamental para responder a este inquietante desequilibrio\u201d, remacha Traor\u00e9, \u201cpero es crucial actuar con rapidez y que otros pa\u00edses les sigan\u201d. El presidente estadounidense Joe Biden anunci\u00f3 el pasado jueves que donar\u00eda 500 millones de dosis para los pa\u00edses m\u00e1s pobres, mientras que el primer ministro brit\u00e1nico, Boris Johnson, adelant\u00f3 que su Gobierno ceder\u00eda otros 100 millones con el objetivo de que el total de la donaci\u00f3n procedente del G-7 alcanzara los 1.000 millones.Estas decisiones est\u00e1n \u201cen el lado correcto de la historia\u201d, seg\u00fan Nkengansong, pero para Amnist\u00eda Internacional se trata de \u201cuna gota en el oc\u00e9ano\u201d, asegur\u00f3 su secretaria general, Agn\u00e8s Callamard, a trav\u00e9s de un comunicado. Seg\u00fan sus c\u00e1lculos y de mantenerse el ritmo actual, los pa\u00edses pobres no vacunar\u00e1n a su poblaci\u00f3n hasta 2078.Por su parte, la OMS estima que solo siete pa\u00edses africanos van a alcanzar el 10% de su poblaci\u00f3n vacunada en septiembre, muy lejos de la inmunidad de grupo deseada, y que hacen falta al menos 225 millones de dosis m\u00e1s a corto plazo. La directora en \u00c1frica de este organismo, Matshidiso Moeti, revel\u00f3 esta semana en conferencia de prensa que \u201ces una cuesti\u00f3n de vida o muerte. Los pa\u00edses que puedan, deben compartir sus vacunas. A medida que nos acercamos a los cinco millones de casos en \u00c1frica y empieza una tercera ola, muchas de las personas m\u00e1s vulnerables siguen peligrosamente expuestas a la covid-19\u201d.Jo Barnes, del Departamento de Salud Global de la Facultad de Medicina de la Universidad Stellenbosh en Ciudad del Cabo, explica que a la falta de dosis, se suman los problemas de log\u00edstica. \u201cSud\u00e1frica tiene un n\u00famero elevado de indigentes y muchos viven en zonas rurales e inaccesibles. Incluso en las ciudades y pueblos hay suburbios informales con poblaci\u00f3n variante a la que es dif\u00edcil alcanzar. Tambi\u00e9n hay personas pobres sin acceso a un m\u00f3vil para registrarse en la base de datos para vacunarse\u201d, se\u00f1ala.Pero \u00c1frica es muy grande y en ella conviven diferentes realidades. A la sombra de un \u00e1rbol en el patio principal del centro de salud Gaspard C\u00e1mara de Dakar, la capital de Senegal, medio centenar de personas, casi todos de edad avanzada, aguardan con paciencia su turno para vacunarse. Para la mayor\u00eda de ellos es su segunda dosis. \u201cEstoy impaciente\u201d, apunta Ndeye Balde, \u201cse cuentan muchas historias sobre las vacunas, pero yo no estar\u00e9 tranquila hasta que me la ponga. La gente dice muchas tonter\u00edas\u201d, asegura. No hay tramos de edad ni es necesario pedir cita: basta con presentarse y pinchazo al canto. \u201c\u00bfAstraZeneca o la china?\u201d, pregunta la enfermera.Hasta Senegal han llegado 1,1 millones de dosis y se ha administrado casi la mitad. Pero es Marruecos quien lidera las estad\u00edsticas de vacunaci\u00f3n, con el 99% de sus 15,4 millones de vacunas ya inyectadas. Casi 7 millones est\u00e1n totalmente inmunizados. Fruto de este intenso trabajo, el primer ministro marroqu\u00ed, Saad\u00edn el Otmani, aseguraba este viernes que la situaci\u00f3n epidemiol\u00f3gica \u201cest\u00e1 bajo control\u201d y a\u00f1adi\u00f3 que se ha evitado lo peor. No se puede decir lo mismo del resto del continente. En \u00c1frica central, por ejemplo, los casos aumentaron un 116% en el \u00faltimo mes.Las consecuencias del enorme retraso en la vacunaci\u00f3n pueden ser devastadoras para \u00c1frica. Seg\u00fan Traor\u00e9, \u201cla exacerbaci\u00f3n del impacto sanitario y socioecon\u00f3mico de la pandemia y que la normalizaci\u00f3n del funcionamiento de ciertos servicios llegue m\u00e1s tarde. Esto va a afectar a la sanidad, donde la inmunizaci\u00f3n de rutina se ha visto perturbada o incluso interrumpida, pero tambi\u00e9n a la educaci\u00f3n, donde m\u00e1s de 128 millones de ni\u00f1os solo en \u00c1frica occidental y central se han quedado sin clases o han tenido problemas para continuar con sus estudios. Por no hablar de la p\u00e9rdida de ingresos y la ca\u00edda del estado nutricional de los menores\u201d. Y tambi\u00e9n de sus familias. \u201cSi el virus se sigue propagando, m\u00e1s duro ser\u00e1 este impacto a largo plazo\u201d.Dejar atr\u00e1s a \u00c1frica no es solo un problema moral, como ha repetido decenas de veces el director general de la OMS, Tedros Adhanom Ghebreyesus, sino un riesgo para el mundo. Coincide con \u00e9l el epidemi\u00f3logo Salim Abdool Karim: \u201cMe gusta pensar que hay una conciencia de que si no controlamos la expansi\u00f3n del virus de forma global y se vacuna solo a Europa, nos encontraremos en una situaci\u00f3n en la que la expansi\u00f3n desenfrenada del virus en ciertas partes del mundo llevar\u00e1 a nuevas variantes, y estas se convertir\u00e1n en un desaf\u00edo para las vacunas. En realidad, aunque sea por propio inter\u00e9s, hay que dar m\u00e1s vacunas a \u00c1frica\u201d.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/sociedad\/2021-06-13\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una enfermera de un hospital de Yaba, en Nigeria, recibe la primera dosis de la vacuna contra la covid-19 el pasado mes de marzo.Sunday Alamba \/ APUn vecino de Pretoria (Sud\u00e1frica) se queja en en la emisora Radio Power del ritmo de inmunizaci\u00f3n en \u00c1frica. \u201cEs una verg\u00fcenza. Primero lo que tardaron en vacunar al [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Una enfermera de un hospital de Yaba, en Nigeria, recibe la primera dosis de la vacuna contra la covid-19 el pasado mes de marzo.Sunday Alamba \/ APUn vecino de Pretoria (Sud\u00e1frica) se queja en en la emisora Radio Power del ritmo de inmunizaci\u00f3n en \u00c1frica. \u201cEs una verg\u00fcenza. Primero lo que tardaron en vacunar al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-13T05:52:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-13T05:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras\",\"datePublished\":\"2021-06-13T05:52:41+00:00\",\"dateModified\":\"2021-06-13T05:52:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/\"},\"wordCount\":1511,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/\",\"name\":\"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg\",\"datePublished\":\"2021-06-13T05:52:41+00:00\",\"dateModified\":\"2021-06-13T05:52:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/","og_locale":"es_ES","og_type":"article","og_title":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World","og_description":"Una enfermera de un hospital de Yaba, en Nigeria, recibe la primera dosis de la vacuna contra la covid-19 el pasado mes de marzo.Sunday Alamba \/ APUn vecino de Pretoria (Sud\u00e1frica) se queja en en la emisora Radio Power del ritmo de inmunizaci\u00f3n en \u00c1frica. \u201cEs una verg\u00fcenza. Primero lo que tardaron en vacunar al [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/","og_site_name":"Hot News in World","article_published_time":"2021-06-13T05:52:41+00:00","article_modified_time":"2021-06-13T05:52:50+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras","datePublished":"2021-06-13T05:52:41+00:00","dateModified":"2021-06-13T05:52:50+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/"},"wordCount":1511,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/","url":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/","name":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg","datePublished":"2021-06-13T05:52:41+00:00","dateModified":"2021-06-13T05:52:50+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/La-falta-de-vacunas-en-Africa-un-retraso-de-consecuencias-scaled.jpg","width":2560,"height":1707,"caption":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/la-falta-de-vacunas-en-africa-un-retraso-de-consecuencias-devastadoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"La falta de vacunas en \u00c1frica, un retraso de consecuencias devastadoras"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2793"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2793\/revisions"}],"predecessor-version":[{"id":2795,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2793\/revisions\/2795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2794"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}