{"id":2799,"date":"2021-06-13T20:53:47","date_gmt":"2021-06-13T17:53:47","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/"},"modified":"2021-06-13T20:53:51","modified_gmt":"2021-06-13T17:53:51","slug":"los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/","title":{"rendered":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022"},"content":{"rendered":"<p>Los l\u00edderes de las principales potencias mundiales se han comprometido a donar de aqu\u00ed hasta finales de 2022 mil millones de dosis de vacunas para los pa\u00edses en desarrollo. As\u00ed lo ha anunciado el primer ministro brit\u00e1nico, Boris Johnson, este domingo en rueda de prensa al t\u00e9rmino de la cumbre celebrada en Cornualles. \u201cHace una semana, ped\u00ed a mis colegas del G-7 ayuda para preparar y distribuir las dosis que se necesitan para vacunar a todo el mundo a finales de 2022. Hemos comprometido la entrega a los pa\u00edses pobres de alrededor de mil millones de vacunas, bien a trav\u00e9s de Covax, o bien a trav\u00e9s de la donaci\u00f3n directa de los distintos pa\u00edses\u201d, anunciaba el mandatario.La donaci\u00f3n de las vacunas tiene como objetivo promover una recuperaci\u00f3n sostenible y justa en la salida de una pandemia que a\u00fan no ha concluido. Los jefes de Gobierno y Estado que han acudido a Cornualles admiten que la cifra de dosis comprometidas se queda corta, si se atiende a los c\u00e1lculos de la Organizaci\u00f3n Mundial de la Salud, que estima necesarios 11.000 millones de dosis para inmunizar al 60% de la poblaci\u00f3n global, pero se comprometen a ir aumentando m\u00e1s adelante las cantidades. De la reuni\u00f3n ha quedado fuera el debate sobre la liberalizaci\u00f3n de las patentes de las vacunas, como impuls\u00f3 en un principio la Administraci\u00f3n estadounidense. Las reticencias de pa\u00edses como el Reino Unido o Alemania, con gigantes farmac\u00e9uticos implicados, han derivado el debate hacia otras soluciones. \u201cCreo que lo m\u00e1s inteligente, y el modo correcto de enfocar este asunto, es facilitando la fabricaci\u00f3n de las dosis en otras partes del mundo, especialmente en \u00c1frica, y distribuyendo las vacunas a precio de coste, como se ha comprometido AstraZeneca\u201d, explicaba Boris Johnson en su comparecencia ante los medios.M\u00e1s informaci\u00f3nEn conjunto, la cumbre del G-7 de Cornualles ha concluido con un pu\u00f1ado de importantes promesas, entre otras las de las vacunas, y con mucho trabajo por delante para concretar algunas de ellas. Pero sobre todo, en su primera reuni\u00f3n presencial en casi dos a\u00f1os, por culpa precisamente de la pandemia, los l\u00edderes de las naciones m\u00e1s avanzadas han querido dar al encuentro un tono hist\u00f3rico, transmitir al mundo la idea de que las democracias liberales est\u00e1n dispuestas a liderar la salida de la crisis del coronavirus, sin cometer los errores que cometieron en la anterior crisis del 2008: \u201cApoyaremos a nuestras econom\u00edas el tiempo que resulte necesario (\u2026) Promoveremos el crecimiento futuro con planes para crear empleo, invertir en infraestructuras, impulsar la innovaci\u00f3n, apoyar a las personas, y buscar un equilibrio para que nadie, al margen de edad, etnia o g\u00e9nero, se quede atr\u00e1s\u201d, anuncia un largo comunicado que demuestra que, los trabajos desarrollados durante tres d\u00edas en la costa oeste de Inglaterra, han sido intensos, y que han tra\u00eddo consigo un acto de contrici\u00f3n. \u201cNo ocurri\u00f3 as\u00ed durante las pasadas crisis globales, y estamos decididos a que esta vez sea diferente\u201d, han anunciado los l\u00edderes del G-7. Un mea culpa in\u00e9dito entre los l\u00edderes mundiales.La reuni\u00f3n ha sido tambi\u00e9n la puesta en escena internacional del nuevo presidente de EE UU, Joe Biden, dispuesto a borrar de la memoria colectiva los \u00faltimos cuatro a\u00f1os de su predecesor, Donald Trump, y los destrozos que dej\u00f3 a su paso. \u201cHe trasladado a todos mis colegas del G-7 que Estados Unidos est\u00e1 dispuesto a cumplir con su parte. Estados Unidos ha vuelto a la mesa de negociaci\u00f3n\u201d, ha repetido dos veces, en una rueda de prensa en el aeropuerto de Newquay, antes de dirigirse junto a su esposa al castillo de Windsor, donde le esperaba Isabel II, para tomar el t\u00e9.El gran desaf\u00edo al que se enfrentan las democracias liberales, ha debatido el G-7, son los reg\u00edmenes autoritarios como China o Rusia, que ofrecen al mundo respuestas alejadas de los valores y principios defendidos por Occidente. Biden ha logrado que el resto de l\u00edderes respalden su iniciativa de lanzar un proyecto multibillonario (de hasta 40 billones de d\u00f3lares) en infraestructuras por todo el mundo con el objetivo de contrarrestar la llamada \u201cnueva ruta de la seda\u201d promovida por el Gobierno de Pek\u00edn. A trav\u00e9s de la asociaci\u00f3n de la inversi\u00f3n p\u00fablica y privada, la cumbre de Cornualles quiere presentar, con l\u00edneas de ferrocarril en \u00c1frica o estaciones e\u00f3licas en Asia, un plan sostenible que impulse las nuevas tecnolog\u00edas verdes, con el objetivo de responder a la enorme influencia alcanzada por Pek\u00edn durante los \u00faltimos a\u00f1os con sus alianzas en Asia, \u00c1frica o Latinoam\u00e9rica. Biden ha logrado adem\u00e1s que el resto de l\u00edderes endurezcan su tono respecto a la amenaza china, aunque ha tenido que aceptar, en el comunicado final, el equilibrio que le solicitaban sus socios, para no romper todos los puentes con Pek\u00edn. \u201cSeguiremos las consultas para dar una respuesta colectiva al desaf\u00edo de pr\u00e1cticas contrarias al libre mercado y que socavan las operaciones de una econom\u00eda global justa y transparente\u201d, dice el texto, \u201cpero buscaremos la cooperaci\u00f3n en asuntos de inter\u00e9s mutuo como la lucha contra el cambio clim\u00e1tico\u201d. A cambio, el presidente estadounidense ha logrado la condena expl\u00edcita de los siete a los abusos de derechos humanos que tiene lugar en la regi\u00f3n de Xinjiang, y la defensa de la libertad y autonom\u00eda de Hong Kong.El G-7 se ha impuesto deberes hist\u00f3ricos. Algunos tan concretos como la puesta en marcha de tipo m\u00ednimo del impuesto de Sociedades de \u201cal menos el 15%\u201d que ponga coto a la evasi\u00f3n fiscal de los gigantes tecnol\u00f3gicos y la carrera a la baja en la imposici\u00f3n a las empresas, y otros m\u00e1s pendientes de desarrollo como el compromiso de alcanzar para 2050 las \u201cemisiones cero\u201d de gases efecto invernadero. Ese debate quedar\u00e1 pendiente de avance para la COP26, que se celebrar\u00e1 tambi\u00e9n en Glasgow, en territorio brit\u00e1nico, el pr\u00f3ximo mes de noviembre. La sesi\u00f3n de clausura de la cumbre de Cornualles ha contado con la participaci\u00f3n del naturalista David Attenborough. \u201cNuestro planeta se est\u00e1 calentando r\u00e1pidamente. Es algo innegable y fuera de toda duda. Nuestras sociedades y naciones presentan desigualdades (\u2026) Las decisiones que tomen durante esta d\u00e9cada las naciones m\u00e1s avanzadas del planeta ser\u00e1n las m\u00e1s importantes de la historia\u201d, ha dicho a los l\u00edderes de la cumbre.Tres d\u00edas en los que Johnson quer\u00eda que todo saliera perfecto, para presentar al mundo el Reino Unido surgido del Brexit, y que han quedado ensombrecidos, sin embargo, por la enorme tensi\u00f3n desplegada en torno a Irlanda del Norte y el acuerdo de salida de la Uni\u00f3n Europea.Lea el comunicado completo de la cumbre del G-7 abajo. Si no puede verlo, pinche aqu\u00ed.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-06-13\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los l\u00edderes de las principales potencias mundiales se han comprometido a donar de aqu\u00ed hasta finales de 2022 mil millones de dosis de vacunas para los pa\u00edses en desarrollo. As\u00ed lo ha anunciado el primer ministro brit\u00e1nico, Boris Johnson, este domingo en rueda de prensa al t\u00e9rmino de la cumbre celebrada en Cornualles. \u201cHace una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Los l\u00edderes de las principales potencias mundiales se han comprometido a donar de aqu\u00ed hasta finales de 2022 mil millones de dosis de vacunas para los pa\u00edses en desarrollo. As\u00ed lo ha anunciado el primer ministro brit\u00e1nico, Boris Johnson, este domingo en rueda de prensa al t\u00e9rmino de la cumbre celebrada en Cornualles. \u201cHace una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-13T17:53:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-13T17:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022\",\"datePublished\":\"2021-06-13T17:53:47+00:00\",\"dateModified\":\"2021-06-13T17:53:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/\"},\"wordCount\":1204,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/\",\"name\":\"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg\",\"datePublished\":\"2021-06-13T17:53:47+00:00\",\"dateModified\":\"2021-06-13T17:53:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg\",\"width\":980,\"height\":506,\"caption\":\"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World","og_description":"Los l\u00edderes de las principales potencias mundiales se han comprometido a donar de aqu\u00ed hasta finales de 2022 mil millones de dosis de vacunas para los pa\u00edses en desarrollo. As\u00ed lo ha anunciado el primer ministro brit\u00e1nico, Boris Johnson, este domingo en rueda de prensa al t\u00e9rmino de la cumbre celebrada en Cornualles. \u201cHace una [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/","og_site_name":"Hot News in World","article_published_time":"2021-06-13T17:53:47+00:00","article_modified_time":"2021-06-13T17:53:51+00:00","og_image":[{"width":980,"height":506,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022","datePublished":"2021-06-13T17:53:47+00:00","dateModified":"2021-06-13T17:53:51+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/"},"wordCount":1204,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/","url":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/","name":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022 - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg","datePublished":"2021-06-13T17:53:47+00:00","dateModified":"2021-06-13T17:53:51+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Los-lideres-del-G-7-se-comprometen-a-donar-mil-millones.jpg","width":980,"height":506,"caption":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/los-lideres-del-g-7-se-comprometen-a-donar-mil-millones-de-vacunas-contra-la-covid-para-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los l\u00edderes del G-7 se comprometen a donar mil millones de vacunas contra la covid para 2022"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2799"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2799\/revisions"}],"predecessor-version":[{"id":2801,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2799\/revisions\/2801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2800"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}