{"id":2802,"date":"2021-06-14T04:24:14","date_gmt":"2021-06-14T01:24:14","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/"},"modified":"2021-06-14T04:24:21","modified_gmt":"2021-06-14T01:24:21","slug":"con-19-grandes-djokovic-redobla-su-amenaza","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/","title":{"rendered":"Con 19 grandes, Djokovic redobla su amenaza"},"content":{"rendered":"<p>Brazos en cruz y dedo \u00edndice al cielo, el ilusionista de las mil y una vidas atrapa la recompensa que redondea un plan perfecto. Pese a que Stefanos Tsitsipas se ha revuelto como una mangosta, Novak Djokovic cierra con una volea, celebra la remontada (6-7(6), 2-6, 6-3, 6-2 y 6-4) y saborea su segundo trofeo en Par\u00eds, donde el debate hist\u00f3rico entre \u00e9l, Rafael Nadal y Roger Federer \u201455 de los 64 \u00faltimos grandes entre los tres\u2014 vive un episodio que lo pone todo patas arriba. El serbio, 34 a\u00f1os, eleva su segundo major de la temporada y colecciona ya 19, de modo que figura a un solo pelda\u00f1o del suizo y el espa\u00f1ol, con el litigio masculino m\u00e1s comprimido que nunca.M\u00e1s informaci\u00f3nHan transcurrido 4h 11m de final, la cuarta m\u00e1s extensa en el Bois de Boulogne, que no presenciaba una a cinco sets desde 2004; entonces, Gast\u00f3n Gaudio bati\u00f3 a Guillermo Coria. Le flanquean Bj\u00f6rn Borg y Jim Courier, departe en franc\u00e9s y los libros le se\u00f1alan como el primer tenista en la Era Abierta (desde 1968) que logra reunir los cuatro grandes al menos dos veces; previos al profesionalismo relucen los australianos Rod Laver y Roy Emerson, pero Djokovic, 84 t\u00edtulos, vuela hacia otra dimensi\u00f3n diferente. Abraza la Copa de los Mosqueteros con mimo mientras Tsitsipas, bravo en la batalla y hundido en el parlamento, le reconoce y dice que volver\u00e1. Lo har\u00e1.Pese al cosquilleo l\u00f3gico que produce pisar por primera vez la final de un grande, doble falta como punto de partida, el griego (22 a\u00f1os) aguanta perfectamente el tipo durante todo el primer parcial. A diferencia de la mayor\u00eda de sus compa\u00f1eros de generaci\u00f3n y de las nuevas hornadas de j\u00f3venes, respeta, pero no teme. No puede, no debe. Es el \u00fanico camino. No le intimida la alargad\u00edsima sombra de los tres gigantes, a los que ha tumbado \u2014en m\u00e1s de una ocasi\u00f3n a todos ellos\u2014 ofreciendo serios indicios de que un d\u00eda u otro puede dar el gran golpe.Volte\u00f3 a Nadal (35) este a\u00f1o en Melbourne, remont\u00e1ndole dos sets, y tanto Federer (39) \u2014inclinado hace dos cursos en Australia y en las semifinales de un Masters\u2014 como Djokovic (34) \u2014Shangh\u00e1i y Canad\u00e1, parajes nada menores\u2014 saben perfectamente de sus condiciones. No se arruga Tsitsipas. Valent\u00eda por delante.Salta a la pista sabiendo que entra en un laberinto, y que dar con la llave de salida pasa exclusivamente por mantener la cabeza fr\u00eda y saber apretar los dientes cuando el fuego apriete. Djokovic camina intimidatorio, neg\u00e1ndole cualquier hueco al resto; no le cede un solo punto hasta el octavo turno de servicio, cuando el serbio descubre que la tarde no va a ser especialmente agradable. El sol cae con dureza en la central, sopla un vientecillo que desestabiliza la trayectoria de la bola y al intentar cazar una dejada, Nole se da de bruces contra la arena.No est\u00e1 c\u00f3modo el n\u00famero uno, que delante encuentra un front\u00f3n que repele y escupe la bola con much\u00edsima determinaci\u00f3n. Luz roja: con 5-4 y 30-40 se ve obligado a levantar una bola de set. Y aun as\u00ed, picando piedra encuentra una v\u00eda para extraer petr\u00f3leo, porque al ateniense le puede la precipitaci\u00f3n y con una derecha larga habilita la primera rotura; sin embargo, recibe una respuesta fulminante. 6-6. El rev\u00e9s de Tsitsipas, ni un mal adem\u00e1n ni una sola queja, resiste y conduce hacia el tie-break, en el que el chico, delicioso reverso a una mano, lanza un \u00f3rdago a la grande.Aunque Djokovic se pone el traje de escapista y le quita el caramelo de la boca, recort\u00e1ndole un 4-0 de arranque y el 5-2 posterior, a dos puntos de la recompensa, persiste y enfila al balc\u00e1nico con todo: despu\u00e9s de negarle la oportunidad de llevarse el set, con 5-6 adverso, le suelta tres latigazos seguidos y abre el primer interrogante: \u00bfrealidad o espejismo? \u00bfTiene cimientos s\u00f3lidos la afrenta del griego? As\u00ed lo demuestra. Todav\u00eda m\u00e1s rocoso y con la misma decisi\u00f3n, desborda en el segundo set, cerrando las dos primeras mangas con solo 12 errores y planteando otro Everest para Nole, que ven\u00eda de escalar al mism\u00edsimo Nadal en su fort\u00edn de la Chatrier.\u00bfQu\u00e9 le ocurre al de Belgrado? \u00bfEst\u00e1 o no est\u00e1? \u00bfSe vaci\u00f3 por completo la noche del viernes, hip\u00f3tesis nada descartable dado el peaje que suele acompa\u00f1ar a la faena de batir al espa\u00f1ol?Tsitsipas, durante la final contra Djokovic.ANNE-CHRISTINE POUJOULAT \/ AFPDos sets abajo, le empujan sus paisanos: \u201c\u00a1Idemo, idemo, idemo!\u201d. Y el tigre despierta porque Djokovic, parezca lo que parezca, siempre est\u00e1 ah\u00ed, nunca desiste. Jam\u00e1s se le debe dar por muerto, por muy ausente que pueda parecer o muy destemplado que se le vea. El eterno trampantojo. Se las sabe todas, Nole. Se oye desde la grada un \u201c\u00a1vamos, Rafa!\u201d que tiene un efecto contraproducente al pretendido por el autor del grito; no hay mejor acicate para el serbio que recordarle hacia d\u00f3nde va, qu\u00e9 persigue. Entonces, su juego se multiplica y recupera el color, toda su expresi\u00f3n. Pero de manera controlada.No hay aspavientos ni signos de sobreexcitaci\u00f3n, no hacia afuera. Pelotea de modo rob\u00f3tico, dicta, abre con el rev\u00e9s y va desplegando sus cartas. Se viene Djokovic, entra en trance. Acosa y acosa en el cuarto juego del tercer parcial, en el que Tsitsipas aguanta cuatro empellones, que no el quinto. Y el break, para 3-1, tiene un efecto desestabilizador, cat\u00e1rtico para el balc\u00e1nico. A partir de ah\u00ed, navega a placer y al griego empieza a pesarle demasiado el duelo y le duelen las lumbares, extenuante exigencia la de seguir ese ritmo militar, esa zozobra permanente. Es la impronta de la vieja guardia: competir al l\u00edmite, de la primera a la \u00faltima pelota. Sin tregua.El ejercicio mental para el griego es tremendo. Dos sets iguales ya, Djokovic le roe como si fuera un ej\u00e9rcito de termitas y la grada se pronuncia intentando reanimarle, y \u00e9l resiste a los embates hasta que su coraza (rotura para 2-1) termina saltando por los aires. El n\u00famero uno, un Maquiavelo de la raqueta, ha guiado el partido exactamente hacia donde le interesaba, a esa falsa ilusi\u00f3n que tantos y tantos \u00e9xitos le ha reportado. El aspirante guerrea hasta el final con dignidad y cabeza dura, pero no hay marcha atr\u00e1s: por segunda vez, cinco a\u00f1os despu\u00e9s, Djokovic festeja en Par\u00eds, completando una jugada maestra y aplicando otro brusco giro a la historia. Son ya 19 para \u00e9l.Puedes seguir a EL PA\u00cdS DEPORTES en Facebook y <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/elpais_deportes\">Twitter<\/a>, o apuntarte aqu\u00ed para recibir nuestra newsletter semanal.<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/deportes\/2021-06-13\/djokovic-19-grandes-completa-una-jugada-maestra.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brazos en cruz y dedo \u00edndice al cielo, el ilusionista de las mil y una vidas atrapa la recompensa que redondea un plan perfecto. Pese a que Stefanos Tsitsipas se ha revuelto como una mangosta, Novak Djokovic cierra con una volea, celebra la remontada (6-7(6), 2-6, 6-3, 6-2 y 6-4) y saborea su segundo trofeo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con 19 grandes, Djokovic redobla su amenaza - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con 19 grandes, Djokovic redobla su amenaza - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Brazos en cruz y dedo \u00edndice al cielo, el ilusionista de las mil y una vidas atrapa la recompensa que redondea un plan perfecto. Pese a que Stefanos Tsitsipas se ha revuelto como una mangosta, Novak Djokovic cierra con una volea, celebra la remontada (6-7(6), 2-6, 6-3, 6-2 y 6-4) y saborea su segundo trofeo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-14T01:24:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T01:24:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Con 19 grandes, Djokovic redobla su amenaza\",\"datePublished\":\"2021-06-14T01:24:14+00:00\",\"dateModified\":\"2021-06-14T01:24:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/\"},\"wordCount\":1164,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/\",\"name\":\"Con 19 grandes, Djokovic redobla su amenaza - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg\",\"datePublished\":\"2021-06-14T01:24:14+00:00\",\"dateModified\":\"2021-06-14T01:24:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Con 19 grandes, Djokovic redobla su amenaza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/con-19-grandes-djokovic-redobla-su-amenaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con 19 grandes, Djokovic redobla su amenaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con 19 grandes, Djokovic redobla su amenaza - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/","og_locale":"es_ES","og_type":"article","og_title":"Con 19 grandes, Djokovic redobla su amenaza - Hot News in World","og_description":"Brazos en cruz y dedo \u00edndice al cielo, el ilusionista de las mil y una vidas atrapa la recompensa que redondea un plan perfecto. Pese a que Stefanos Tsitsipas se ha revuelto como una mangosta, Novak Djokovic cierra con una volea, celebra la remontada (6-7(6), 2-6, 6-3, 6-2 y 6-4) y saborea su segundo trofeo [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/","og_site_name":"Hot News in World","article_published_time":"2021-06-14T01:24:14+00:00","article_modified_time":"2021-06-14T01:24:21+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Con 19 grandes, Djokovic redobla su amenaza","datePublished":"2021-06-14T01:24:14+00:00","dateModified":"2021-06-14T01:24:21+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/"},"wordCount":1164,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/","url":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/","name":"Con 19 grandes, Djokovic redobla su amenaza - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg","datePublished":"2021-06-14T01:24:14+00:00","dateModified":"2021-06-14T01:24:21+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Con-19-grandes-Djokovic-redobla-su-amenaza-scaled.jpg","width":2560,"height":1707,"caption":"Con 19 grandes, Djokovic redobla su amenaza"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/con-19-grandes-djokovic-redobla-su-amenaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Con 19 grandes, Djokovic redobla su amenaza"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2802"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2802\/revisions"}],"predecessor-version":[{"id":2804,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2802\/revisions\/2804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2803"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}