{"id":2859,"date":"2021-06-18T21:47:25","date_gmt":"2021-06-18T18:47:25","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/"},"modified":"2021-06-18T21:47:36","modified_gmt":"2021-06-18T18:47:36","slug":"al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/","title":{"rendered":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa"},"content":{"rendered":"<p>La carretera panamericana en el desierto de Nasca, 400 kil\u00f3metros al sur de Lima.Yuriko Nakao \/ Getty ImagesAl menos 17 personas han muerto y otras 14 resultaron heridas este viernes tras la ca\u00edda de un autob\u00fas por un precipicio en la cordillera de los Andes, en Per\u00fa. El accidente ocurri\u00f3 alrededor de las 4:00 de la madrugada a la altura del kil\u00f3metro 37 de la carretera entre los municipios de Nazca y Puquio, en un sector monta\u00f1oso y de geograf\u00eda accidentada perteneciente a la sure\u00f1a regi\u00f3n andina de Ayacucho, al sureste de Lima.En el lugar del accidente fueron hallados al menos 17 cad\u00e1veres, seg\u00fan recoge la agencia EFE. El autob\u00fas interprovincial trasladaba a 50 trabajadores de una compa\u00f1\u00eda minera con destino al sur del pa\u00eds, a la ciudad de Arequipa, seg\u00fan ha informado la emisora Radio Programas del Per\u00fa. Seg\u00fan el parte policial, 14 personas habr\u00edan resultado heridas, algunas de gravedad. Estas fueron trasladadas al Hospital de la ciudad de Nazca para recibir atenci\u00f3n de emergencia.<a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Comunicado?src=hash&amp;ref_src=twsrc%5Etfw\">#Comunicado<\/a> | La Sutran informa lo siguiente con relaci\u00f3n al accidente ocurrido esta madrugada en la V\u00eda Nasca-Puquio-Chalhuanca-Abancay (distrito Vista Alegre, provincia Nasca, Ica) y que involucra a un \u00f3mnibus de la Empresa de Transportes Expreso Internacional Palomino S.A.C. <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/t.co\/GCVSnMNwYo\">pic.twitter.com\/GCVSnMNwYo<\/a>\u2014 SUTRAN PER\u00da (@sutranperu) <a rel=\"nofollow noopener noreferrer\" target=\"_blank\" href=\"https:\/\/twitter.com\/sutranperu\/status\/1405922552762019847?ref_src=twsrc%5Etfw\">June 18, 2021<\/a><\/p>\n<p>Seg\u00fan las primeras versiones del accidente, el veh\u00edculo trasladaba al grupo cuando se despist\u00f3 de la carretera por razones a\u00fan indeterminadas. El autob\u00fas dio varias vueltas de campana a lo largo de una pronunciada pendiente de m\u00e1s de 200 metros. La Superintendencia de Transporte Terrestre de Per\u00e9 (SUTRAN) ha activado los protocolos de investigaci\u00f3n para determinar las causas del accidente. \u201cEs importante indicar que la unidad se encontraba realizando un servicio especial de traslado de trabajadores para una empresa privada y contaba con autorizaci\u00f3n para dicho servicio\u201d, ha difundido la SUTRAN en un comunicado.M\u00e1s informaci\u00f3nPer\u00fa es uno de los pa\u00edses con una de las tasas de muertes por accidentes de tr\u00e1fico m\u00e1s altas de Am\u00e9rica Latina. El pa\u00eds andino tiene una tasa estimada de 15,9 por cada 100.000 habitantes, por encima de M\u00e9xico (14,7 y con un parque automotor mucho mayor), y por debajo de Venezuela, con una tasa de 37,2. Sin embargo, la OMS apunta que Per\u00fa es uno de los 77 pa\u00edses \u2014y uno de los cinco de Am\u00e9rica Latina junto con Bolivia, Honduras, Rep\u00fablica Dominicana y Nicaragua\u2014 que no cuenta con cifras fiables sobre las causas de las muertes registradas. Al a\u00f1o mueren en Per\u00fa alrededor de 3.000 personas en accidentes de tr\u00e1fico, la mayor\u00eda por atropellos, y unos 55.000 son heridos, seg\u00fan cifras del Consejo Nacional de Seguridad Vial.Suscr\u00edbase aqu\u00ed a la newsletter de EL PA\u00cdS Am\u00e9rica y reciba todas las claves informativas de la actualidad de la regi\u00f3n<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2021-06-18\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carretera panamericana en el desierto de Nasca, 400 kil\u00f3metros al sur de Lima.Yuriko Nakao \/ Getty ImagesAl menos 17 personas han muerto y otras 14 resultaron heridas este viernes tras la ca\u00edda de un autob\u00fas por un precipicio en la cordillera de los Andes, en Per\u00fa. El accidente ocurri\u00f3 alrededor de las 4:00 de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"La carretera panamericana en el desierto de Nasca, 400 kil\u00f3metros al sur de Lima.Yuriko Nakao \/ Getty ImagesAl menos 17 personas han muerto y otras 14 resultaron heridas este viernes tras la ca\u00edda de un autob\u00fas por un precipicio en la cordillera de los Andes, en Per\u00fa. El accidente ocurri\u00f3 alrededor de las 4:00 de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T18:47:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-18T18:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa\",\"datePublished\":\"2021-06-18T18:47:25+00:00\",\"dateModified\":\"2021-06-18T18:47:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/\"},\"wordCount\":506,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/\",\"name\":\"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg\",\"datePublished\":\"2021-06-18T18:47:25+00:00\",\"dateModified\":\"2021-06-18T18:47:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World","og_description":"La carretera panamericana en el desierto de Nasca, 400 kil\u00f3metros al sur de Lima.Yuriko Nakao \/ Getty ImagesAl menos 17 personas han muerto y otras 14 resultaron heridas este viernes tras la ca\u00edda de un autob\u00fas por un precipicio en la cordillera de los Andes, en Per\u00fa. El accidente ocurri\u00f3 alrededor de las 4:00 de [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/","og_site_name":"Hot News in World","article_published_time":"2021-06-18T18:47:25+00:00","article_modified_time":"2021-06-18T18:47:36+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa","datePublished":"2021-06-18T18:47:25+00:00","dateModified":"2021-06-18T18:47:36+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/"},"wordCount":506,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/","url":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/","name":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg","datePublished":"2021-06-18T18:47:25+00:00","dateModified":"2021-06-18T18:47:36+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2021\/06\/Al-menos-17-muertos-y-14-heridos-tras-caer-un-scaled.jpeg","width":2560,"height":1707,"caption":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/al-menos-17-muertos-y-14-heridos-tras-caer-un-autobus-por-un-precipicio-en-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Al menos 17 muertos y 14 heridos tras caer un autob\u00fas por un precipicio en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=2859"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2859\/revisions"}],"predecessor-version":[{"id":2861,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/2859\/revisions\/2861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/2860"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=2859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=2859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=2859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}