{"id":922,"date":"2020-11-30T22:34:41","date_gmt":"2020-11-30T19:34:41","guid":{"rendered":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/"},"modified":"2020-11-30T22:34:47","modified_gmt":"2020-11-30T19:34:47","slug":"la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/","title":{"rendered":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas"},"content":{"rendered":"<p>El escritor cubano Carlos Manuel \u00c1lvarez (c), junto a Maykel Castillo (i) y Luis Manuel Otero Alc\u00e1ntara (d), tres de los opositores en huelga de hambre.Movimiento San Isidro \/ EFELa polic\u00eda cubana irrumpi\u00f3 la noche de este jueves en la sede el Movimiento San Isidro, una red de activistas que lleva diez d\u00edas de encierro en La Habana para exigir la liberaci\u00f3n del rapero Denis Sol\u00eds, y mantuvo bajo arresto durante horas a una quincena de personas. Entre ellas se encuentran periodistas, artistas y profesores, algunos de los cuales se declararon en huelga de hambre y sed para protestar contra la represi\u00f3n y las pol\u00edticas del Gobierno, que, denuncian, cada vez m\u00e1s cercenan la libertad de expresi\u00f3n. Varios de los arrestados fueron puestos en libertad horas despu\u00e9s.Entre los desalojados est\u00e1 Carlos Manuel \u00c1lvarez, periodista y escritor, director de El Estornudo y colaborador de EL PA\u00cdS. \u00c1lvarez lleg\u00f3 el martes a la isla para unirse al grupo de activistas que se hab\u00eda encerrado en la sede del Movimiento San Isidro, en el hom\u00f3nimo barrio de La Habana. Las autoridades justificaron el operativo esgrimiendo el protocolo de salud adoptado por la pandemia de coronavirus. Primero, relata \u00c1lvarez por tel\u00e9fono desde La Habana, llegaron \u201cunos agentes de la Seguridad del Estado disfrazados de m\u00e9dicos\u201d. \u201cYo no ced\u00ed\u201d, contin\u00faa. Despu\u00e9s se sum\u00f3 un grupo de uniformados, que tras las advertencias \u201crompieron la puerta a golpes, la echaron abajo\u201d. \u201cNosotros est\u00e1bamos serenos y no ofrecimos resistencia. Eran como fiera reparti\u00e9ndose la presa. Parec\u00edan incluso tener m\u00e1s miedo que nosotros.\u201d, recuerda el reportero.No hubo golpes, pero s\u00ed confusi\u00f3n y empujones para introducir a los detenidos en los furgones policiales. \u201cA los hombres nos llevaron a la estaci\u00f3n de Cuba y Chac\u00f3n [en La Habana Vieja] y ah\u00ed estuvimos dos horas en el carro\u201d. \u00c1lvarez sinti\u00f3 \u201cun ambiente de mucha camarader\u00eda\u201d. De alguna manera, como ocurre en las circunstancias excepcionales, \u201cse puso el cu\u00f1o a la hermandad que se hab\u00eda creado all\u00e1 adentro\u201d en el encierro del Movimiento San Isidro. \u201cEs raro, parec\u00eda que no est\u00e1bamos ah\u00ed: hacinados, muertos de risa, bromeando\u201d. Sentido del humor para vencer el miedo. Pero en cuanto los separaron todo cambi\u00f3. \u201cYo fui la segunda persona a la que llamaron para hacer una prueba PCR y despu\u00e9s me trajeron a una casa de una amiga muy cercana, de M\u00f3nica [Bar\u00f3, reportera de El Estornudo]. En cuanto me separaron ese sentimiento comenz\u00f3 a transformarse sobre todo en soledad, pesar, tristeza, mucha confusi\u00f3n tambi\u00e9n. Hubiera dicho que rabia, pero es una sensaci\u00f3n m\u00e1s seca, no es ira. Eso fue lo que sent\u00ed y eso a medida que han ido pasando las horas se est\u00e1 asentando como tristeza, como soledad\u201d.\u00c1lvarez, que por la ma\u00f1ana hab\u00eda denunciado a trav\u00e9s de las redes sociales un intento del Gobierno de construir un caso pol\u00edtico con el argumento de su llegada del extranjero y los riesgos para la salud p\u00fablica, deber\u00e1 permanecer confinado unos d\u00edas. \u201cQuer\u00edamos hacernos compa\u00f1\u00eda ahora, pero me aislaron hasta el domingo\u201d. Asegura que las reivindicaciones del colectivo no se acaban esta noche. A\u00fan no saben qu\u00e9 estrategias seguir, llevan d\u00edas pensando en posibles variantes, pero \u00c1lvarez no tiene dudas: \u201cEso no se termina\u201d.El periodista fue liberado antes de las doce de la noche tras permanecer unas horas bajo arresto. Su decisi\u00f3n de sumarse a la protesta del Movimiento San Isidro se produjo despu\u00e9s de que las fuerzas de seguridad detuvieran, a principios de mes, a Denis Sol\u00eds sin orden policial en medio de un altercado que fue difundido en las redes sociales. El rapero fue condenado a ocho meses de prisi\u00f3n con la acusaci\u00f3n de desacato a las autoridades.El Movimiento San Isidro es una red nacida en 2018 precisamente para luchar contra las restricciones a la libertad de expresi\u00f3n impuestas por el Gobierno de Miguel D\u00edaz-Canel. A pesar de las protestas de varios miembros del colectivo, que llegaron a acudir a una comisar\u00eda de la ciudad para tener noticias de Sol\u00eds, conocer los detalles del juicio y saber d\u00f3nde se encuentra, varios manifestantes fueron detenidos durante horas y entonces la polic\u00eda redobl\u00f3 el hostigamiento en contra de esta red y su sede.Entre quienes se declararon en huelga de hambre el pasado 18 de noviembre est\u00e1n el bioqu\u00edmico \u00d3scar Casanella, antiguo profesor de la Universidad de La Habana y los periodistas Iliana Hern\u00e1ndez y Esteban Rodr\u00edguez. D\u00edas m\u00e1s tarde, se sum\u00f3 a ellos la poeta Katherine Bisquet. A partir de esa decisi\u00f3n, agentes de las fuerzas de seguridad intensificaron los controles en la calle en la que est\u00e1 ubicada la sede del colectivo. Seg\u00fan denunci\u00f3 el periodista Dar\u00edo Alem\u00e1n, los uniformados prohibieron incluso a una vecina llevarles alimentos y productos de aseo.Tambi\u00e9n Maykel Gonz\u00e1lez Vivero, director de la revista Tremenda Nota, relat\u00f3 por Whatsapp las circunstancias del desalojo despu\u00e9s de salir de la sede del movimiento. \u201cUn vecino me explic\u00f3 que se los llevaron violentamente, que rompieron la puerta, que hab\u00eda fuera el t\u00edpico acto de repudio, gente aliada del Gobierno citada para dar vivas\u201d. Este periodista, que se tuvo que alejar debido al gran despliegue policial y resguardarse en un lugar seguro, fue el primero en informar del operativo, que en un primer momento incluy\u00f3 la interrupci\u00f3n de las conexiones a Internet en la zona, a trav\u00e9s de las redes sociales. \u201cEstuve conversando con Abraham L\u00f3pez, un vecino, que conoce perfectamente a los activistas ah\u00ed sitiados\u201d, afirm\u00f3. Tras conocerse las detenciones, escritores y periodistas de todo Am\u00e9rica Latina denunciaron el desalojo de la sede y exigieron la liberaci\u00f3n de los detenidos, que comenz\u00f3 a producirse horas m\u00e1s tarde.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/elpais.com\/internacional\/2020-11-27\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El escritor cubano Carlos Manuel \u00c1lvarez (c), junto a Maykel Castillo (i) y Luis Manuel Otero Alc\u00e1ntara (d), tres de los opositores en huelga de hambre.Movimiento San Isidro \/ EFELa polic\u00eda cubana irrumpi\u00f3 la noche de este jueves en la sede el Movimiento San Isidro, una red de activistas que lleva diez d\u00edas de encierro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-medios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"El escritor cubano Carlos Manuel \u00c1lvarez (c), junto a Maykel Castillo (i) y Luis Manuel Otero Alc\u00e1ntara (d), tres de los opositores en huelga de hambre.Movimiento San Isidro \/ EFELa polic\u00eda cubana irrumpi\u00f3 la noche de este jueves en la sede el Movimiento San Isidro, una red de activistas que lleva diez d\u00edas de encierro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-30T19:34:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-30T19:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas\",\"datePublished\":\"2020-11-30T19:34:41+00:00\",\"dateModified\":\"2020-11-30T19:34:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/\"},\"wordCount\":1025,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/11\\\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg\",\"articleSection\":[\"NOTICIAS DE MEDIOS SOCIALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/\",\"name\":\"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/11\\\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg\",\"datePublished\":\"2020-11-30T19:34:41+00:00\",\"dateModified\":\"2020-11-30T19:34:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/11\\\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/11\\\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg\",\"width\":2560,\"height\":1778,\"caption\":\"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Spain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/","og_locale":"es_ES","og_type":"article","og_title":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World","og_description":"El escritor cubano Carlos Manuel \u00c1lvarez (c), junto a Maykel Castillo (i) y Luis Manuel Otero Alc\u00e1ntara (d), tres de los opositores en huelga de hambre.Movimiento San Isidro \/ EFELa polic\u00eda cubana irrumpi\u00f3 la noche de este jueves en la sede el Movimiento San Isidro, una red de activistas que lleva diez d\u00edas de encierro [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/","og_site_name":"Hot News in World","article_published_time":"2020-11-30T19:34:41+00:00","article_modified_time":"2020-11-30T19:34:47+00:00","og_image":[{"width":2560,"height":1778,"url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas","datePublished":"2020-11-30T19:34:41+00:00","dateModified":"2020-11-30T19:34:47+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/"},"wordCount":1025,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg","articleSection":["NOTICIAS DE MEDIOS SOCIALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/","url":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/","name":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg","datePublished":"2020-11-30T19:34:41+00:00","dateModified":"2020-11-30T19:34:47+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/es\/wp-content\/uploads\/sites\/4\/2020\/11\/La-policia-cubana-desaloja-la-sede-del-Movimiento-San-Isidro-scaled.jpg","width":2560,"height":1778,"caption":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/es\/la-policia-cubana-desaloja-la-sede-del-movimiento-san-isidro-y-detiene-a-varios-integrantes-durante-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"La polic\u00eda cubana desaloja la sede del Movimiento San Isidro y detiene a varios integrantes durante horas"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/es\/#website","url":"https:\/\/hotnewsinworld.com\/es\/","name":"Hot News in World","description":"Hot News in World from Spain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/es\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/922\/revisions"}],"predecessor-version":[{"id":924,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/posts\/922\/revisions\/924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media\/923"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/media?parent=922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/categories?post=922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/es\/wp-json\/wp\/v2\/tags?post=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}