{"id":2478,"date":"2019-09-07T14:44:57","date_gmt":"2019-09-07T11:44:57","guid":{"rendered":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/"},"modified":"2019-09-07T14:44:59","modified_gmt":"2019-09-07T11:44:59","slug":"chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/","title":{"rendered":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox"},"content":{"rendered":"<p><\/p>\n<div>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_1 --><\/p>\n<p>Para General Motors se ha vuelto una tendencia incluir variantes Midnight entre su alineaci\u00f3n, pues es algo que ya vimos en el pasado, pero esta f\u00f3rmula parece funcionar para Chevrolet, pues una de sus SUVs llevar\u00e1 este tratamiento. Se trata de la Equinox Midnight que tendr\u00e1 a la venta 185 unidades en territorio nacional.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/INF_intext_1 --><\/p>\n<p>Es a nivel exterior donde se reflejan los cambios propios de esta edici\u00f3n, ya que se abusa del color negro para transmitir una apariencia y personalidad \u00fanica. Entre los detalles espec\u00edficos se encuentra un tono de carrocer\u00eda especial, seguido por el logotipo oscurecido, al igual que los rines de 19 pulgadas, parrilla, molduras e incluso los interiores.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/1x1Desktop --><\/p>\n<p>El resto del equipo se basa en la versi\u00f3n LT de la Chevrolet Equinox, por lo que a nivel de amenidades esta SUV ofrece una pantalla de entretenimiento de ocho pulgadas; aire acondicionado autom\u00e1tico de doble zona; panel de instrumentos con pantalla a color de 4.2 pulgadas: port\u00f3n trasero el\u00e9ctrico y vestiduras en cuero. A nivel de seguridad hay elementos como: c\u00e1mara de reversa de alta definici\u00f3n; monitor de punto ciego y alerta de tr\u00e1fico cruzado, entre los asistentes m\u00e1s destacados.<\/p>\n<p>El tren motor es el mismo que en toda la alineaci\u00f3n de este producto, es decir, un propulsor turbocargado de 1.5 litros, con 170 caballos de fuerza y 203 lb-pie de par. El conjunto finaliza con una caja autom\u00e1tica de seis velocidades, que env\u00eda la fuerza a las ruedas frontales de este veh\u00edculo familiar.<\/p>\n<p>Ser\u00e1 a mediados de este mismo mes cuando esta versi\u00f3n llegue a los concesionarios de la marca en M\u00e9xico, cada unidad tendr\u00e1 un costo de 555 mil 700 pesos, y como se mencion\u00f3 anteriormente, contar\u00e1 con una producci\u00f3n limitada para el territorio nacional.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_3 --><\/p>\n<section class=\"mod mod-tags\">\n<\/section>\n<section class=\"mod mod-list\">\n\t\t\t\t<\/section>\n<\/div>\n<p><script>\n!function(f,b,e,v,n,t,s)\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\nn.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];\ns.parentNode.insertBefore(t,s)}(window,document,'script',\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n fbq('init', '938504263008026'); \nfbq('track', 'PageView');\n<\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.informador.mx\/economia\/Chevrolet-lanza-en-Mexico-una-edicion-limitada-de-la-Equinox-20190903-0080.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para General Motors se ha vuelto una tendencia incluir variantes Midnight entre su alineaci\u00f3n, pues es algo que ya vimos en el pasado, pero esta f\u00f3rmula parece funcionar para Chevrolet, pues una de sus SUVs llevar\u00e1 este tratamiento. Se trata de la Equinox Midnight que tendr\u00e1 a la venta 185 unidades en territorio nacional. Es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Para General Motors se ha vuelto una tendencia incluir variantes Midnight entre su alineaci\u00f3n, pues es algo que ya vimos en el pasado, pero esta f\u00f3rmula parece funcionar para Chevrolet, pues una de sus SUVs llevar\u00e1 este tratamiento. Se trata de la Equinox Midnight que tendr\u00e1 a la venta 185 unidades en territorio nacional. Es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T11:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-07T11:44:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox\",\"datePublished\":\"2019-09-07T11:44:57+00:00\",\"dateModified\":\"2019-09-07T11:44:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/\"},\"wordCount\":315,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/\",\"name\":\"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg\",\"datePublished\":\"2019-09-07T11:44:57+00:00\",\"dateModified\":\"2019-09-07T11:44:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/","og_locale":"es_MX","og_type":"article","og_title":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World","og_description":"Para General Motors se ha vuelto una tendencia incluir variantes Midnight entre su alineaci\u00f3n, pues es algo que ya vimos en el pasado, pero esta f\u00f3rmula parece funcionar para Chevrolet, pues una de sus SUVs llevar\u00e1 este tratamiento. Se trata de la Equinox Midnight que tendr\u00e1 a la venta 185 unidades en territorio nacional. Es [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/","og_site_name":"Hot News in World","article_published_time":"2019-09-07T11:44:57+00:00","article_modified_time":"2019-09-07T11:44:59+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox","datePublished":"2019-09-07T11:44:57+00:00","dateModified":"2019-09-07T11:44:59+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/"},"wordCount":315,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/","url":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/","name":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg","datePublished":"2019-09-07T11:44:57+00:00","dateModified":"2019-09-07T11:44:59+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/Chevrolet-lanza-en-M\u00e9xico-una-edici\u00f3n-limitada-de-la-Equinox.jpg","width":1200,"height":900,"caption":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/mx\/chevrolet-lanza-en-mexico-una-edicion-limitada-de-la-equinox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Chevrolet lanza en M\u00e9xico una edici\u00f3n limitada de la Equinox"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/mx\/#website","url":"https:\/\/hotnewsinworld.com\/mx\/","name":"Hot News in World","description":"Hot News in World from Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/mx\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/comments?post=2478"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2478\/revisions"}],"predecessor-version":[{"id":2480,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2478\/revisions\/2480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media\/2479"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media?parent=2478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/categories?post=2478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/tags?post=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}