{"id":2502,"date":"2019-09-08T15:23:48","date_gmt":"2019-09-08T12:23:48","guid":{"rendered":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/"},"modified":"2019-09-08T15:23:49","modified_gmt":"2019-09-08T12:23:49","slug":"carlos-bremer-el-tiburon-caza-talentos","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/","title":{"rendered":"Carlos Bremer, &#8220;el tibur\u00f3n&#8221; caza talentos"},"content":{"rendered":"<div>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_1 --><\/p>\n<p>Si algo conoce Carlos Bremer es la voluntad, y desde esta trinchera ha sabido encaminarse en el sendero del apoyo social y empresarial. Adem\u00e1s de ser reconocido como uno de los l\u00edderes financieros m\u00e1s importantes de M\u00e9xico con Value Grupo Financiero, tambi\u00e9n destaca por impulsar las causas sociales.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/INF_intext_1 --><\/p>\n<p>Carlos Bremer puntualiza que siempre ha tratado de encontrar el lado positivo de las cosas, en especial, cuando hay talento de por medio. Aunque los n\u00fameros son su fuerte, este empresario tambi\u00e9n ha tenido que aprender con detalle c\u00f3mo funciona la industria deportiva y la cinematogr\u00e1fica, en las que ha echado a andar proyectos que potencialicen el valor de M\u00e9xico m\u00e1s all\u00e1 de sus fronteras.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/1x1Desktop --><\/p>\n<p>Tras la subasta emprendida por la presidencia de M\u00e9xico para vender la mansi\u00f3n decomisada a Zhenli Ye Gon, Carlos Bremer valor\u00f3 las posibilidades de jugar este partido -destinando 102 millones de pesos- que hoy lo hace acreedor de la finca que dejar\u00e1 atr\u00e1s su pol\u00e9mica y pasar\u00e1 a tener un uso en beneficio de su fundaci\u00f3n Butaca Enlace.<\/p>\n<p>\u201cAdquirimos esta casa con la idea de dedicarla en cosas buenas para M\u00e9xico. No quiero tomar ninguna decisi\u00f3n precipitada, quiero ver ideas en este momento y hasta enero, para ver c\u00f3mo podemos eficientar su uso, que el esquema que visualizamos sea exitoso hasta donde se pueda. Me est\u00e1n diciendo ideas de m\u00e1s instituciones deportivas y cosas por el estilo, pero necesito ver c\u00f3mo puede ser m\u00e1s \u00fatil. No la quiero para m\u00ed, no me interesa\u201d.<\/p>\n<p>Agrega que \u201cfaltaban dos d\u00edas para la subasta, pensamos hasta donde yo pod\u00eda apoyar porque s\u00ed es una cantidad muy elevada para m\u00ed, concurs\u00e9 por tel\u00e9fono en la subasta. S\u00ed sent\u00ed felicidad el poder poner un granito de arena, son cosas que se presentan una vez en la vida y no me gusta dejarlas pasar\u201d.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_3 --><\/p>\n<p>Bremer puntualiza que no ha tenido oportunidad de conocer personalmente la mansi\u00f3n, pero a trav\u00e9s de una puja telef\u00f3nica consider\u00f3 sus posibilidades financieras teniendo el objetivo en mente: que el dinero destinado a la compra del inmueble se entregar\u00e1 a los deportistas participantes en los pasados Juegos Panamericanos de Lima 2019.<\/p>\n<p>\u201cDesde el inicio de los Juegos Panamericanos, fue sobresaliente la actuaci\u00f3n de los deportistas mexicanos, y cuando comenzaron a acercarse al r\u00e9cord de medallas, m\u00e1s gente les prest\u00f3 atenci\u00f3n. Vino una iniciativa hist\u00f3rica por parte de presidencia para dar un apoyo muy grande a cada uno de todos los deportistas participantes, creo que es un esfuerzo importante para premiar a los atletas. Yo no sab\u00eda c\u00f3mo apoyar, pens\u00e9 que pod\u00eda sumarme a la subasta para que esta iniciativa se cumpliera\u201d.<\/p>\n<h4>Ayudar, la prioridad<\/h4>\n<p>Desde ni\u00f1o aprendi\u00f3 c\u00f3mo trabajar con capital y sobre todo c\u00f3mo encausarlo para ayudar a quienes requieran de un empuj\u00f3n, es por ello que cuando un proyecto llega a sus manos no duda en sacar la calculadora y empezar a ver las posibilidades que beneficien a los sectores productivos de M\u00e9xico, generar m\u00e1s fuentes de empleo y hacerle ver a los emprendedores y empresarios que nuestro pa\u00eds siempre ser\u00e1 un buen lugar para echar ra\u00edces.<\/p>\n<p>\u201cQuiero mucho a mi pa\u00eds, estoy orgulloso de M\u00e9xico, le tengo fe. Quiero tratar de regresarle algo de todo lo que me ha dado, no tengo otra motivaci\u00f3n m\u00e1s que esa, de ver c\u00f3mo los atletas, por ejemplo, cada vez son m\u00e1s exitosos, son h\u00e9roes del pueblo, y los j\u00f3venes eso necesitamos, m\u00e1s ejemplos a seguir. Para m\u00ed son mis h\u00e9roes, me emociono igual que la gente\u201d.<\/p>\n<p>La relaci\u00f3n de Carlos Bremer con el deporte no es nueva, y apoyar a deportistas profesionales lo ha llevado a explorar el cine desde la producci\u00f3n, hermanando dos tem\u00e1ticas que han dado frutos en la pantalla grande con pel\u00edculas como \u201cSomos campeones\u201d y \u201c108 costuras\u201d, historia beisbolera protagonizada por Kuno Becker y Ximena Navarrete, que recuerda el campeonato de la selecci\u00f3n Mexicana en la Serie del Caribe. El filme llegar\u00e1 a cartelera nacional el 4 de octubre en 800 salas.<\/p>\n<p>Carlos Bremer tambi\u00e9n se alista para apoyar al boxeador campe\u00f3n de peso completo Andy Ruiz Jr., en su revancha contra Anthony Joshua a celebrarse en diciembre pr\u00f3ximo en Arabia Saudita; a la espera tambi\u00e9n del anuncio del pr\u00f3ximo encuentro del tapat\u00edo Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, no sin antes regresar a Guadalajara para sumarse a las celebraciones del Premier 12, torneo que funge como parte del Preol\u00edmpico de beisbol para los Juegos de Tokio 2020.<\/p>\n<p>\u201cPara m\u00ed puede ser hist\u00f3rico, porque por primera vez el beisbol participar\u00e1 en la Olimpiada de Jap\u00f3n 2020 y la eliminatoria para ver qui\u00e9nes califican ser\u00e1 en Guadalajara, ah\u00ed vamos a eliminar a Estados Unidos, Rep\u00fablica Dominicana y Holanda. Tengo mucha fe en que se armar\u00e1 a un equipo fuert\u00edsimo y daremos la sorpresa. Yo estar\u00e9 en Guadalajara desde el 1 de noviembre hasta el cierre. Vamos por todo\u201d.<\/p>\n<h4>Fuera de cuadro<\/h4>\n<p>Una de las facetas m\u00e1s populares de Carlos Bremer es como tibur\u00f3n en \u201cShark Tank M\u00e9xico\u201d, en donde conoce a talentos empresariales que buscan capital para emprender o fortalecer proyectos comerciales y de servicio, experiencia que ahora se ve reflejada en puntos de venta reales en el pa\u00eds.<\/p>\n<p>\u201cEmpec\u00e9 como emprendedor a los 13 a\u00f1os de edad, siempre tuve apoyo de gente que crey\u00f3 en m\u00ed y eso quiero hacer. Adem\u00e1s de apoyar a los que van al programa, trato de transmitir consejos para la audiencia. Yo veo c\u00f3mo encontrar el s\u00ed y no el no, hay gente muy buena a la que veo como brazos clave para M\u00e9xico, que van a crear empleo y apoyar a artesanos y campesinos con apoyo digno\u201d.<\/p>\n<p>Actualmente, Carlos Bremer trabaja con grupos de emprendedores para reunirlos en un punto de venta \u201cEmpresarios de M\u00e9xico\u201d, en una reconocida plaza comercial de Monterrey y colocar ah\u00ed semestralmente a talentos como Mayaca, productores de hamacas que da empleo a mil artesanos mayas, as\u00ed como a la empresa tapat\u00eda Tuluminati, una boutique de sombreros de alta moda.<br \/>\u00a0<\/p>\n<section class=\"mod mod-tags\">\n<\/section>\n<section class=\"mod mod-list\">\n\t\t\t\t<\/section>\n<\/div>\n<p><script>\n!function(f,b,e,v,n,t,s)\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\nn.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];\ns.parentNode.insertBefore(t,s)}(window,document,'script',\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n fbq('init', '938504263008026'); \nfbq('track', 'PageView');\n<\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.informador.mx\/economia\/Carlos-Bremer-el-tiburon-caza-talentos-20190907-0082.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si algo conoce Carlos Bremer es la voluntad, y desde esta trinchera ha sabido encaminarse en el sendero del apoyo social y empresarial. Adem\u00e1s de ser reconocido como uno de los l\u00edderes financieros m\u00e1s importantes de M\u00e9xico con Value Grupo Financiero, tambi\u00e9n destaca por impulsar las causas sociales. Carlos Bremer puntualiza que siempre ha tratado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carlos Bremer, &quot;el tibur\u00f3n&quot; caza talentos - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos Bremer, &quot;el tibur\u00f3n&quot; caza talentos - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"Si algo conoce Carlos Bremer es la voluntad, y desde esta trinchera ha sabido encaminarse en el sendero del apoyo social y empresarial. Adem\u00e1s de ser reconocido como uno de los l\u00edderes financieros m\u00e1s importantes de M\u00e9xico con Value Grupo Financiero, tambi\u00e9n destaca por impulsar las causas sociales. Carlos Bremer puntualiza que siempre ha tratado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-08T12:23:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-08T12:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Carlos Bremer, &#8220;el tibur\u00f3n&#8221; caza talentos\",\"datePublished\":\"2019-09-08T12:23:48+00:00\",\"dateModified\":\"2019-09-08T12:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/\"},\"wordCount\":1064,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/\",\"name\":\"Carlos Bremer, \\\"el tibur\u00f3n\\\" caza talentos - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg\",\"datePublished\":\"2019-09-08T12:23:48+00:00\",\"dateModified\":\"2019-09-08T12:23:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg\",\"width\":770,\"height\":300,\"caption\":\"Tapat\u00edo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/carlos-bremer-el-tiburon-caza-talentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlos Bremer, &#8220;el tibur\u00f3n&#8221; caza talentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlos Bremer, \"el tibur\u00f3n\" caza talentos - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/","og_locale":"es_MX","og_type":"article","og_title":"Carlos Bremer, \"el tibur\u00f3n\" caza talentos - Hot News in World","og_description":"Si algo conoce Carlos Bremer es la voluntad, y desde esta trinchera ha sabido encaminarse en el sendero del apoyo social y empresarial. Adem\u00e1s de ser reconocido como uno de los l\u00edderes financieros m\u00e1s importantes de M\u00e9xico con Value Grupo Financiero, tambi\u00e9n destaca por impulsar las causas sociales. Carlos Bremer puntualiza que siempre ha tratado [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/","og_site_name":"Hot News in World","article_published_time":"2019-09-08T12:23:48+00:00","article_modified_time":"2019-09-08T12:23:49+00:00","og_image":[{"width":770,"height":300,"url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Carlos Bremer, &#8220;el tibur\u00f3n&#8221; caza talentos","datePublished":"2019-09-08T12:23:48+00:00","dateModified":"2019-09-08T12:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/"},"wordCount":1064,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/","url":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/","name":"Carlos Bremer, \"el tibur\u00f3n\" caza talentos - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg","datePublished":"2019-09-08T12:23:48+00:00","dateModified":"2019-09-08T12:23:49+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/La-trepidante-carrera-en-la-banca-de-inversi\u00f3n.jpg","width":770,"height":300,"caption":"Tapat\u00edo"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/mx\/carlos-bremer-el-tiburon-caza-talentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Carlos Bremer, &#8220;el tibur\u00f3n&#8221; caza talentos"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/mx\/#website","url":"https:\/\/hotnewsinworld.com\/mx\/","name":"Hot News in World","description":"Hot News in World from Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/mx\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/comments?post=2502"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2502\/revisions"}],"predecessor-version":[{"id":2503,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2502\/revisions\/2503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media\/729"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media?parent=2502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/categories?post=2502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/tags?post=2502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}