{"id":2555,"date":"2019-09-10T13:49:20","date_gmt":"2019-09-10T10:49:20","guid":{"rendered":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/"},"modified":"2019-09-10T13:49:21","modified_gmt":"2019-09-10T10:49:21","slug":"cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/","title":{"rendered":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020"},"content":{"rendered":"<p><\/p>\n<p>                    La L\u00ednea 4 del Tren Ligero y el Perib\u00fas no est\u00e1n considerados entre las obras que recibir\u00e1n recursos del Gobierno federal durante el pr\u00f3ximo a\u00f1o.<\/p>\n<p>                    El Presupuesto de Egresos de la Federaci\u00f3n (PEF) 2020 no los incluye entre los proyectos de inversi\u00f3n de la Secretar\u00eda de Comunicaciones y Transportes (SCT).<\/p>\n<p>                    Lo que s\u00ed aparece es una bolsa de 120 millones de pesos para infraestructura y equipamiento de la L\u00ednea 3, que tendr\u00e1 un costo final de 32 mil 762 millones.<\/p>\n<p>                    Adem\u00e1s, se propone etiquetar 247 millones 374 mil pesos para continuar con el proyecto de la Presa El Zapotillo. El dinero se destinar\u00eda a acciones como el acueducto a Le\u00f3n, el pago de indemnizaciones, la reubicaci\u00f3n de localidades afectadas y la supervisi\u00f3n t\u00e9cnico-administrativa.<\/p>\n<p>                    Sin embargo, no se hace referencia al abasto de agua para municipios de la regi\u00f3n de Los Altos o al \u00c1rea Metropolitana de Guadalajara (AMG).<\/p>\n<p>                    R\u00edo Santiago tampoco recibir\u00e1 recursos<br \/>\nLos planes de saneamiento del r\u00edo Santiago tampoco est\u00e1n reflejados en la proyecci\u00f3n de gasto federal, al igual que los grandes proyectos de infraestructura de Jalisco como la L\u00ednea 4, la Presa El Zapotillo o el Perib\u00fas.<\/p>\n<p>                    Entre los programas de inversi\u00f3n de la Secretar\u00eda de Medio Ambiente y Recursos Naturales (Semarnat) s\u00f3lo se contemplan 28 millones de pesos para acciones de conservaci\u00f3n de distritos de riego en el Organismo de Cuenca Lerma Santiago Pac\u00edfico.<\/p>\n<p>                    En contraste, una obra a la que s\u00ed se le asignar\u00e1n recursos es a la continuaci\u00f3n de la ampliaci\u00f3n de la Carretera 15 Jiquilpan-Guadalajara, en el tramo Tizap\u00e1n El Alto-Jocotepec. Este camino recibir\u00e1 un presupuesto de 68.1 millones de pesos.<\/p>\n<p>   Los planes de saneamiento del r\u00edo Santiago tampoco est\u00e1n reflejados en la proyecci\u00f3n de gasto federal. EL INFORMADOR\/Archivo<\/p>\n<p>Presupuesto \u00a0alcanzar\u00e1 para apoyos sociales<br \/>\nEl Presidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO), afirm\u00f3 que su proyecto de Presupuesto de Egresos de la Federaci\u00f3n (PEF) mantendr\u00e1 los apoyos para los adultos mayores, personas con discapacidad, becas para estudiantes y los programas J\u00f3venes Construyendo El Futuro y Sembrando Vida.<\/p>\n<p>                    \u201cEst\u00e1n garantizados sus apoyos, todos los adultos mayores recibir\u00e1n permanentemente su pensi\u00f3n; a todos los capacitados, pobres, ni\u00f1as y ni\u00f1os, su pensi\u00f3n est\u00e1 garantizada para todo el a\u00f1o pr\u00f3ximo y para este\u201d.<\/p>\n<p>                    Tambi\u00e9n afirm\u00f3 que el presupuesto para 2020 ser\u00e1 suficiente para cumplir las metas planteadas porque ahora existe un Gobierno austero y no se permiten los actos de corrupci\u00f3n.<\/p>\n<p>                    \u201cYa no hay lujos en el Gobierno, ya no hay sueldos de 700 mil pesos mensuales, el Presidente ya no tiene una guardia de ocho mil elementos del Estado Mayor Presidencial, imag\u00ednese cuanto significa eso de ahorros\u201d, expres\u00f3 L\u00f3pez Obrador.<\/p>\n<p>                    A\u00f1adi\u00f3 que el presupuesto real para el sector salud aument\u00f3 40 mil millones de pesos y expres\u00f3 que se logr\u00f3 estabilizar la producci\u00f3n petrolera, situaci\u00f3n que no se hab\u00eda conseguido en 14 a\u00f1os.<\/p>\n<p>                    El Mandatario reiter\u00f3 que no habr\u00e1 aumento de impuestos, que el Gobierno va bien y pidi\u00f3 la confianza de los ciudadanos.<\/p>\n<p>                    Critican plan econ\u00f3mico<br \/>\nEl presidente de la Confederaci\u00f3n Patronal de la Rep\u00fablica Mexicana (Coparmex), Gustavo De Hoyos, dijo que la propuesta de paquete presupuestal para 2020 tiene un equilibrio precario, es ortodoxo y optimista.<\/p>\n<p>                    \u201cSer\u00e1 imperativo el monitoreo y ajuste oportuno. Preocupa la reducci\u00f3n del super\u00e1vit primario, disminuci\u00f3n de inversi\u00f3n f\u00edsica por gasto social y m\u00e1s retenciones y endurecimiento con los contribuyentes\u201d.<\/p>\n<p>                    El l\u00edder nacional del Partido Acci\u00f3n Nacional (PAN), Marko Cort\u00e9s, manifest\u00f3 preocupaci\u00f3n por la disminuci\u00f3n del super\u00e1vit primario, as\u00ed como por la insuficiencia de recursos para seguridad en estados y municipios.<\/p>\n<p>                    \u201cNo se est\u00e1n atendiendo sectores tan importantes como la seguridad\u201d, subray\u00f3 Cort\u00e9s.<\/p>\n<p>                    El senador por el Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD), Miguel \u00c1ngel Mancera, advirti\u00f3 que el paquete fiscal presentado por el Gobierno federal tiene deficiencias y advirti\u00f3 que revisar\u00e1n la Ley de Ingresos por algunas inconsistencias.<\/p>\n<p>                    Explic\u00f3 que en este paquete existe una carga del presupuesto a programas sociales y Pemex, pero olvida la inversi\u00f3n p\u00fablica.<\/p>\n<p>                    SUN<\/p>\n<p>   El proyecto de PEF mantendr\u00e1 los apoyos para los adultos mayores, personas con discapacidad, becas para estudiantes, J\u00f3venes Construyendo El Futuro y Sembrando Vida. NOTIMEX\/A. Guzm\u00e1n<\/p>\n<p>\u201cDesconectar\u00e1n\u201d a plataformas que no paguen sus impuestos \u00a0<br \/>\nA las plataformas digitales extranjeras sin oficinas en M\u00e9xico que se nieguen a pagar 16% del Impuesto al Valor Agregado (IVA) que cobran por sus servicios, y no se den de alta ante fisco, se les suspender\u00e1 la conexi\u00f3n a internet y se publicar\u00e1 su nombre en una lista negra en el Diario Oficial de la Federaci\u00f3n (DOF) y en el portal del Servicio de Administraci\u00f3n Tributaria (SAT), seg\u00fan se propone en la miscel\u00e1nea fiscal del Presupuesto de Egresos Federal (PEF).<\/p>\n<p>                    Se trata de empresas de servicios digitales para la descarga o acceso a im\u00e1genes, pel\u00edculas, texto, informaci\u00f3n, video, audio, m\u00fasica, juegos, incluyendo los de azar, as\u00ed como otros contenidos multimedia. Aqu\u00ed entran los servicios de streaming de audio o video para ver pel\u00edculas o escuchar m\u00fasica como Netflix o Spotify, entre otros.<\/p>\n<p>                    Se propone al Congreso de la Uni\u00f3n un criterio vinculativo para establecer obligaciones a los prestadores de servicios digitales residentes en el extranjero sin oficinas en M\u00e9xico. Se prev\u00e9 que el SAT publique en su p\u00e1gina web y en el DOF el nombre del proveedor y la fecha a partir de la cual se suspender\u00e1 la conexi\u00f3n, con el prop\u00f3sito de que los receptores de los servicios se abstengan de contratar a estas compa\u00f1\u00edas.<\/p>\n<p>                    Tambi\u00e9n proceder\u00e1 aplicar la misma sanci\u00f3n cuando el contribuyente omita realizar el pago del impuesto, el entero de las retenciones cuando se trate de servicios digitales de intermediaci\u00f3n entre terceros o la presentaci\u00f3n de declaraciones informativas durante tres meses consecutivos.<\/p>\n<p>                    El Gobierno pretende aplicar IVA e Impuesto \u00a0Sobre la Renta (ISR) a todos los servicios que se ofrezcan mediante plataformas digitales, tipo Uber, Netflix y Airbnb, empresas que posiblemente trasladar\u00e1n esta carga fiscal al consumidor final.<\/p>\n<p>                    SUN<\/p>\n<p>                    CLAVES<\/p>\n<p>                    Modificaciones a impuestos propuestos en el Paquete Econ\u00f3mico 2020<br \/>\nCigarros. El consumidor tendr\u00e1 que desembolsar m\u00e1s dinero para adquirirlos, porque ahora deber\u00e1 pagar una cuota del Impuesto Especial sobre Producci\u00f3n y Servicios (IEPS) de casi 50 centavos por cigarro a partir de 2020.<\/p>\n<p>                    Refrescos. Se propone una actualizaci\u00f3n de la cuota del IEPS que pagan las empresas, de 1.17 a 1.27 pesos por litro, cuota que tambi\u00e9n cambiar\u00e1 cada a\u00f1o.<\/p>\n<p>                    Renta de vivienda. Se propone pagar el Impusto Sobre la Renta (ISR) correspondiente a partir del siguiente a\u00f1o. La autoridad judicial pedir\u00e1 comprobantes fiscales digitales por la renta de un inmueble.<\/p>\n<p>                    Cat\u00e1logo. Los vendedores independientes de productos por cat\u00e1logo de empresas como Avon, Natura o Price Shoes, har\u00e1n pagos provisionales y anuales del ISR y definitivos de IVA y IEPS en su caso.<\/p>\n<p>   Se prev\u00e9 que Uber, Netflix, Airbnb y otras plataformes digitales trasladen la carga fiscal al consumidor final. AP\/Archivo<\/p>\n<p>No sepresionar\u00e1 a los Contribuyentes: SHCP<br \/>\nEl secretario de Hacienda, Arturo Herrera, asegur\u00f3 que no se presionar\u00e1 a los contribuyentes con la propuesta del Gobierno de L\u00f3pez Obrador de dotar de mayores facultades al Sistema de Administraci\u00f3n Tributaria (SAT) para evitar la evasi\u00f3n fiscal.<\/p>\n<p>                    \u201cLas razones por las que queremos asegurarnos que dotamos al SAT de recursos adecuados, no tiene ver por c\u00f3mo se encuentra el Presupuesto ni presionar a los contribuyentes\u201d, dijo.<\/p>\n<p>                    El funcionario explic\u00f3 que la intenci\u00f3n del Gobierno es asegurar que todos contribuyan en la forma en que la ley lo dispone, porque \u201chay niveles de evasi\u00f3n y elusi\u00f3n fiscal importantes, y como en el caso de las factureros, no son casos de elusi\u00f3n sino de defraudaci\u00f3n fiscal y eso es lo que queremos evitar\u201d.<\/p>\n<p>                    El Paquete Econ\u00f3mico para el Ejercicio Fiscal 2020 mantiene el compromiso de no incrementar impuestos y fortalecer la recaudaci\u00f3n fiscal, inform\u00f3 el secretario.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.informador.mx\/economia\/Cepillan-megaobras-para-Jalisco-en-presupuesto-federal-de-2020-20190910-0021.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La L\u00ednea 4 del Tren Ligero y el Perib\u00fas no est\u00e1n considerados entre las obras que recibir\u00e1n recursos del Gobierno federal durante el pr\u00f3ximo a\u00f1o. El Presupuesto de Egresos de la Federaci\u00f3n (PEF) 2020 no los incluye entre los proyectos de inversi\u00f3n de la Secretar\u00eda de Comunicaciones y Transportes (SCT). Lo que s\u00ed aparece es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"La L\u00ednea 4 del Tren Ligero y el Perib\u00fas no est\u00e1n considerados entre las obras que recibir\u00e1n recursos del Gobierno federal durante el pr\u00f3ximo a\u00f1o. El Presupuesto de Egresos de la Federaci\u00f3n (PEF) 2020 no los incluye entre los proyectos de inversi\u00f3n de la Secretar\u00eda de Comunicaciones y Transportes (SCT). Lo que s\u00ed aparece es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T10:49:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-10T10:49:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020\",\"datePublished\":\"2019-09-10T10:49:20+00:00\",\"dateModified\":\"2019-09-10T10:49:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/\"},\"wordCount\":1384,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/\",\"name\":\"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg\",\"datePublished\":\"2019-09-10T10:49:20+00:00\",\"dateModified\":\"2019-09-10T10:49:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/09\\\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg\",\"width\":1200,\"height\":900,\"caption\":\"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/","og_locale":"es_MX","og_type":"article","og_title":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World","og_description":"La L\u00ednea 4 del Tren Ligero y el Perib\u00fas no est\u00e1n considerados entre las obras que recibir\u00e1n recursos del Gobierno federal durante el pr\u00f3ximo a\u00f1o. El Presupuesto de Egresos de la Federaci\u00f3n (PEF) 2020 no los incluye entre los proyectos de inversi\u00f3n de la Secretar\u00eda de Comunicaciones y Transportes (SCT). Lo que s\u00ed aparece es [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/","og_site_name":"Hot News in World","article_published_time":"2019-09-10T10:49:20+00:00","article_modified_time":"2019-09-10T10:49:21+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020","datePublished":"2019-09-10T10:49:20+00:00","dateModified":"2019-09-10T10:49:21+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/"},"wordCount":1384,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/","url":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/","name":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020 - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg","datePublished":"2019-09-10T10:49:20+00:00","dateModified":"2019-09-10T10:49:21+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/09\/\u201cCepillan\u201d-megaobras-para-Jalisco-en-presupuesto-federal-de-2020.jpg","width":1200,"height":900,"caption":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/mx\/cepillan-megaobras-para-jalisco-en-presupuesto-federal-de-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/mx\/"},{"@type":"ListItem","position":2,"name":"\u201cCepillan\u201d megaobras para Jalisco en presupuesto federal de 2020"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/mx\/#website","url":"https:\/\/hotnewsinworld.com\/mx\/","name":"Hot News in World","description":"Hot News in World from Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/mx\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/comments?post=2555"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2555\/revisions"}],"predecessor-version":[{"id":2557,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/2555\/revisions\/2557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media\/2556"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media?parent=2555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/categories?post=2555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/tags?post=2555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}