{"id":494,"date":"2019-07-07T16:22:16","date_gmt":"2019-07-07T13:22:16","guid":{"rendered":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/"},"modified":"2019-07-07T16:22:17","modified_gmt":"2019-07-07T13:22:17","slug":"lee-iacocca-una-leyenda-de-la-industria","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/","title":{"rendered":"Lee Iacocca, una leyenda de la industria"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Pocos personajes marcaron de manera importante el rumbo de la industria automotriz, pero uno de ellos no solo lo hizo una, sino dos veces. Se trata de Lido \u201cLee\u201d Iacocca, mejor conocido como el padre del Ford Mustang y el ejecutivo que salv\u00f3 de la quiebra a Chrysler, que adem\u00e1s, cre\u00f3 un nuevo segmento en el mercado de los autom\u00f3viles.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_1 --><\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/INF_intext_1 --><\/p>\n<p>Lido Iacocca era hijo de inmigrantes italianos, pero hizo su vida en los Estados Unidos, donde estudi\u00f3 para convertirse en Ingeniero Industrial. Su historia en el ramo automotor comenz\u00f3 all\u00e1 por el a\u00f1o 1946, cuando Ford lo contrat\u00f3 como aprendiz de ingenier\u00eda, donde logr\u00f3 destacar y fue ganando importancia en la empresa.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/1x1Desktop --><\/p>\n<p>Su siguiente paso en la marca del \u00f3valo azul lo llev\u00f3 al departamento de ventas, donde contribuy\u00f3 con un programa de cr\u00e9ditos que coloc\u00f3 a Ford como el primer lugar en ventas entre las firmas con sede en Detroit. Este hecho llam\u00f3 la atenci\u00f3n de los altos ejecutivos de la marca, quienes decidieron que Lee estaba listo para el siguiente paso: convertirse en director general de Ford.<\/p>\n<p>Es bajo este nuevo cargo que Lee Iacocca hizo su primer gran logro, el cual consist\u00eda en crear un veh\u00edculo deportivo, con un rendimiento aceptable, pero con una apariencia \u00fanica, que adem\u00e1s, deb\u00eda ser asequible para la gran mayor\u00eda, el resultado: el Ford Mustang, que vio la luz del mundo en el Sal\u00f3n de Nueva York en abril de 1964.<\/p>\n<p>Adem\u00e1s de que ese autom\u00f3vil prevalece hoy d\u00eda como un \u00edcono para la firma, aquel novedoso producto logr\u00f3 colocarse como el coche que mejor se vendi\u00f3 durante su primer a\u00f1o en el mercado. Esto no pas\u00f3 desapercibido por los de \u201cpantal\u00f3n largo\u201d de Ford, quienes nombraron al ejecutivo italoamericano presidente de la compa\u00f1\u00eda en 1970.<\/p>\n<p>\t\t\t\t\t<!-- \/1001694\/IN_MR_DET_3 --><\/p>\n<p>Fue en este periodo que Estados Unidos enfrent\u00f3 una severa crisis petrolera, misma que llev\u00f3 a Lee y a otros ejecutivos a idear un autom\u00f3vil que contrarrestara los efectos de este problema. Es as\u00ed que el Ford Pinto sali\u00f3 al mercado, pero fue tan controversial en diversos aspectos, pues hubo varios reportes de incidentes de explosiones y fuego provocado por el mal dise\u00f1o del tanque de este autom\u00f3vil. Dicho error, aunado a una mala relaci\u00f3n con Henry Ford II, termin\u00f3 con la historia de Iacocca con los del \u00f3valo azul, quien fue destituido de su cargo como presidente en 1978.<\/p>\n<h4>Redenci\u00f3n automotriz<\/h4>\n<p>Poco importaron los logros de Lido. La firma que se benefici\u00f3 de la creaci\u00f3n del Mustang le dio las gracias al ejecutivo, quien a pesar de la estrepitosa y humillante manera de ser despedido, poco dur\u00f3 sin trabajo, ya que pronto fue contratado por otra armadora de coches.<\/p>\n<p>Se trataba de Chrysler que en paralelo de los logros de Iacocca atravesaban por el periodo m\u00e1s dif\u00edcil e incierto de toda su historia. Tan solo en el trimestre que \u201cLee\u201d fue reclutado, la marca de la estrella registraba p\u00e9rdidas por 160 millones de d\u00f3lares, esto debido a mala reputaci\u00f3n en calidad de sus productos y malos manejos de administraciones anteriores.<\/p>\n<p>El accionar de \u201cLee\u201d fue pronto e implacable, ya que se vio en la necesidad de cerrar diversas plantas productoras, despedir a miles de empleados, a sacar modelos obsoletos o no funcionales del mercado, y hasta vendi\u00f3 la fracci\u00f3n europea de Chrysler a Peugeot. La situaci\u00f3n era tan complicada que estas acciones no fueron suficientes, por lo que la armadora de autom\u00f3viles tuvo que pedir un rescate financiero al gobierno de Estados Unidos, por la cual tuvieron que adjudicarse una deuda total de m\u00e1s de 4.7 mil millones de d\u00f3lares.<\/p>\n<p>Aunque el panorama permanec\u00eda incierto, para revertir la mala racha, Lee Iacocca tuvo que dar paso a una segunda fase, misma que se realiz\u00f3 basada en su experiencia anterior en producto y ventas.<\/p>\n<p>Lido lo volvi\u00f3 a hacer. Esta ocasi\u00f3n innov\u00f3 creando un nuevo segmento en la industria cuando present\u00f3 a la nueva Plymouth Voyager (Dodge\/Chrysler Caravan), modelo que se convirti\u00f3 en la primera minivan en el mercado. El monovolumen fue todo un \u00e9xito rotundo en ventas, pero no ser\u00eda todo.<\/p>\n<p>Pese a que la crisis petrolera caus\u00f3 estragos entre los compradores, \u201cLee\u201d se las ide\u00f3 para gestar la Serie K de Chrysler, que eran veh\u00edculos de tracci\u00f3n delantera, con un bajo consumo de combustible, pero con espacio suficiente para una familia completa, adem\u00e1s, con precios de compra asequibles, lo que desencaden\u00f3 en un \u00e9xito m\u00e1s a la cuenta del ejecutivo italoamericano.<\/p>\n<p>Los triunfos fueron tales que Iacocca logr\u00f3 revertir los n\u00fameros rojos Chrysler, que en tan solo cinco a\u00f1os despu\u00e9s de la llegada de su nuevo presidente (1984), pudieron liquidar la deuda que ten\u00edan con el gobierno estadounidense.<\/p>\n<p>Despu\u00e9s de salvar a la firma de la estrella de la quiebra, la bonanza sigui\u00f3 para los dirigidos por Lido, y, bajo su r\u00e9gimen, Chrysler logr\u00f3 colaboraciones importantes, como la alianza con Mitsubishi. Despu\u00e9s, y ya con una relativa consolidaci\u00f3n financiera, pudieron comprar a otras marcas, como: Lamborghini y Maserati. Ya en 1987 adquirieron a AMC y Jeep, esta \u00faltima armadora trajo tranquilidad y n\u00fameros favorables para la d\u00e9cada siguiente, que adem\u00e1s contin\u00faa al d\u00eda de hoy como una marca importante dentro del grupo.<\/p>\n<p>Fue en 1992 cuando Lee Iacocca se jubil\u00f3 de Chrysler, que no solo ser\u00e1 conocido dentro de la marca como el hombre que los salv\u00f3 de la quiebra, sino tambi\u00e9n como el vendedor que hizo famosa la frase \u201csi encuentra un coche mejor, c\u00f3mprelo\u201d, misma que marc\u00f3 la historia del autom\u00f3vil, principalmente en los Estados Unidos.<\/p>\n<p>El pasado 2 de julio Lee Iaccoca dej\u00f3 de existir, pero no su legado, que va m\u00e1s all\u00e1 de lo tangible y prevalecer\u00e1 como uno de los ejecutivos m\u00e1s importante de la industria automotriz. Sin duda Lee Iacocca marc\u00f3 un parteaguas, adem\u00e1s de dejar una historia de superaci\u00f3n y \u00e9xito que pocos personajes podr\u00e1n replicar.<\/p>\n<\/p>\n<section class=\"mod mod-tags\">\n<\/section>\n<section class=\"mod mod-list\">\n\t\t\t\t<\/section>\n<\/div>\n<p><script>\n!function(f,b,e,v,n,t,s)\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\nn.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];\ns.parentNode.insertBefore(t,s)}(window,document,'script',\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n fbq('init', '938504263008026'); \nfbq('track', 'PageView');\n<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.informador.mx\/economia\/Lee-Iacocca-una-leyenda-de-la-industria-20190706-0102.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Pocos personajes marcaron de manera importante el rumbo de la industria automotriz, pero uno de ellos no solo lo hizo una, sino dos veces. Se trata de Lido \u201cLee\u201d Iacocca, mejor conocido como el padre del Ford Mustang y el ejecutivo que salv\u00f3 de la quiebra a Chrysler, que adem\u00e1s, cre\u00f3 un nuevo segmento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lee Iacocca, una leyenda de la industria - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lee Iacocca, una leyenda de la industria - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Pocos personajes marcaron de manera importante el rumbo de la industria automotriz, pero uno de ellos no solo lo hizo una, sino dos veces. Se trata de Lido \u201cLee\u201d Iacocca, mejor conocido como el padre del Ford Mustang y el ejecutivo que salv\u00f3 de la quiebra a Chrysler, que adem\u00e1s, cre\u00f3 un nuevo segmento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-07T13:22:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-07T13:22:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"Lee Iacocca, una leyenda de la industria\",\"datePublished\":\"2019-07-07T13:22:16+00:00\",\"dateModified\":\"2019-07-07T13:22:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/\"},\"wordCount\":1033,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/Lee-Iacocca-una-leyenda-de-la-industria.jpg\",\"articleSection\":[\"\u00daLTIMAS NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/\",\"name\":\"Lee Iacocca, una leyenda de la industria - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/Lee-Iacocca-una-leyenda-de-la-industria.jpg\",\"datePublished\":\"2019-07-07T13:22:16+00:00\",\"dateModified\":\"2019-07-07T13:22:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/Lee-Iacocca-una-leyenda-de-la-industria.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/Lee-Iacocca-una-leyenda-de-la-industria.jpg\",\"width\":770,\"height\":300,\"caption\":\"Suplemento Tapat\u00edo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/lee-iacocca-una-leyenda-de-la-industria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lee Iacocca, una leyenda de la industria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World from Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/mx\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lee Iacocca, una leyenda de la industria - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/","og_locale":"es_MX","og_type":"article","og_title":"Lee Iacocca, una leyenda de la industria - Hot News in World","og_description":"[ad_1] Pocos personajes marcaron de manera importante el rumbo de la industria automotriz, pero uno de ellos no solo lo hizo una, sino dos veces. Se trata de Lido \u201cLee\u201d Iacocca, mejor conocido como el padre del Ford Mustang y el ejecutivo que salv\u00f3 de la quiebra a Chrysler, que adem\u00e1s, cre\u00f3 un nuevo segmento [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/","og_site_name":"Hot News in World","article_published_time":"2019-07-07T13:22:16+00:00","article_modified_time":"2019-07-07T13:22:17+00:00","og_image":[{"width":770,"height":300,"url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"Lee Iacocca, una leyenda de la industria","datePublished":"2019-07-07T13:22:16+00:00","dateModified":"2019-07-07T13:22:17+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/"},"wordCount":1033,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg","articleSection":["\u00daLTIMAS NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/","url":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/","name":"Lee Iacocca, una leyenda de la industria - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg","datePublished":"2019-07-07T13:22:16+00:00","dateModified":"2019-07-07T13:22:17+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/Lee-Iacocca-una-leyenda-de-la-industria.jpg","width":770,"height":300,"caption":"Suplemento Tapat\u00edo"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/mx\/lee-iacocca-una-leyenda-de-la-industria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Lee Iacocca, una leyenda de la industria"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/mx\/#website","url":"https:\/\/hotnewsinworld.com\/mx\/","name":"Hot News in World","description":"Hot News in World from Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/mx\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/mx\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/comments?post=494"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/494\/revisions"}],"predecessor-version":[{"id":496,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/posts\/494\/revisions\/496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media\/495"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/media?parent=494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/categories?post=494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/mx\/wp-json\/wp\/v2\/tags?post=494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}