{"id":3606,"date":"2021-05-10T16:00:33","date_gmt":"2021-05-10T13:00:33","guid":{"rendered":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/"},"modified":"2021-05-10T16:00:37","modified_gmt":"2021-05-10T13:00:37","slug":"bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes","status":"publish","type":"post","link":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/","title":{"rendered":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es"},"content":{"rendered":"<p>JN\/Ag\u00eanciasHoje\u00a0\u00e0s\u00a011:18,\u00a0atualizado \u00e0s 13:00O BPI anunciou lucros de 60 milh\u00f5es de euros relativos ao primeiro trimestre, um aumento de dez vezes face aos seis milh\u00f5es reportados no mesmo per\u00edodo do ano passado.De acordo com um comunicado enviado \u00e0 Comiss\u00e3o do Mercado de Valores Mobili\u00e1rios (CMVM), o BPI registou um lucro consolidado de 60 milh\u00f5es de euros nos primeiros tr\u00eas meses do ano, 54 milh\u00f5es dos quais relativos \u00e0 atividade em Portugal.Segundo o banco, o produto banc\u00e1rio cresceu 17,1% face ao mesmo per\u00edodo do ano passado, e o r\u00e1cio de efici\u00eancia &#8216;core&#8217; melhorou para 57,1%, tendo tamb\u00e9m sido registados aumentos nos recursos totais de clientes e nos dep\u00f3sitos.4500 milh\u00f5es de euros em morat\u00f3rias O BPI tinha, no in\u00edcio de abril, cerca de 4500 milh\u00f5es de euros (ME) em morat\u00f3rias de cr\u00e9dito associadas \u00e0 pandemia de covid-19, representando 17% da carteira total de cr\u00e9dito do banco.&#8221;A 1 de abril permaneciam morat\u00f3rias ativas correspondentes a 4,5 mil ME (das quais apenas 1,8 mil ME de capital e juros), representando 17% da carteira de cr\u00e9dito&#8221;, pode ler-se no comunicado enviado pelo BPI \u00e0 CMVM.O BPI assinala que, em 31 de mar\u00e7o, 98% das morat\u00f3rias de cr\u00e9dito (5,6 mil ME) &#8220;estavam em situa\u00e7\u00e3o regular&#8221;.Desse valor, 2,5 mil milh\u00f5es de euros diziam respeito a cr\u00e9dito \u00e0 habita\u00e7\u00e3o, estando 98,8% em situa\u00e7\u00e3o regular, 0,3 mil milh\u00f5es de euros em cr\u00e9dito pessoal e autom\u00f3vel (97,8% em situa\u00e7\u00e3o regular) e 2,8 mil milh\u00f5es de euros em cr\u00e9dito a empresas (97,4% em situa\u00e7\u00e3o regular).Menos 25 trabalhadores e 18 ag\u00eancias O BPI perdeu 25 trabalhadores e 18 ag\u00eancias desde o in\u00edcio do ano at\u00e9 ao final do primeiro trimestre, contando atualmente com cerca de 4600 funcion\u00e1rios e 400 balc\u00f5es.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"http:\/\/feeds.jn.pt\/~r\/JN-ECONOMIA\/~3\/9Jw1dajmbSc\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes-13703057.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JN\/Ag\u00eanciasHoje\u00a0\u00e0s\u00a011:18,\u00a0atualizado \u00e0s 13:00O BPI anunciou lucros de 60 milh\u00f5es de euros relativos ao primeiro trimestre, um aumento de dez vezes face aos seis milh\u00f5es reportados no mesmo per\u00edodo do ano passado.De acordo com um comunicado enviado \u00e0 Comiss\u00e3o do Mercado de Valores Mobili\u00e1rios (CMVM), o BPI registou um lucro consolidado de 60 milh\u00f5es de euros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias-financeiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World\" \/>\n<meta property=\"og:description\" content=\"JN\/Ag\u00eanciasHoje\u00a0\u00e0s\u00a011:18,\u00a0atualizado \u00e0s 13:00O BPI anunciou lucros de 60 milh\u00f5es de euros relativos ao primeiro trimestre, um aumento de dez vezes face aos seis milh\u00f5es reportados no mesmo per\u00edodo do ano passado.De acordo com um comunicado enviado \u00e0 Comiss\u00e3o do Mercado de Valores Mobili\u00e1rios (CMVM), o BPI registou um lucro consolidado de 60 milh\u00f5es de euros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hot News in World\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-10T13:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-10T13:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hotnewsinworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hotnewsinworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/\"},\"author\":{\"name\":\"hotnewsinworld\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"headline\":\"BPI aumenta lucros em dez vezes para 60 milh\u00f5es\",\"datePublished\":\"2021-05-10T13:00:33+00:00\",\"dateModified\":\"2021-05-10T13:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/\"},\"wordCount\":310,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg\",\"articleSection\":[\"\u00daLTIMAS NOT\u00cdCIAS FINANCEIRAS\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/\",\"name\":\"BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg\",\"datePublished\":\"2021-05-10T13:00:33+00:00\",\"dateModified\":\"2021-05-10T13:00:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg\",\"contentUrl\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/05\\\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg\",\"width\":800,\"height\":420,\"caption\":\"BPI aumenta lucros em dez vezes para 60 milh\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BPI aumenta lucros em dez vezes para 60 milh\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/\",\"name\":\"Hot News in World\",\"description\":\"Hot News in World Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/#\\\/schema\\\/person\\\/fe61448b21c0d59086e75fcc1f9d8f6b\",\"name\":\"hotnewsinworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g\",\"caption\":\"hotnewsinworld\"},\"url\":\"https:\\\/\\\/hotnewsinworld.com\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/","og_locale":"pt_PT","og_type":"article","og_title":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World","og_description":"JN\/Ag\u00eanciasHoje\u00a0\u00e0s\u00a011:18,\u00a0atualizado \u00e0s 13:00O BPI anunciou lucros de 60 milh\u00f5es de euros relativos ao primeiro trimestre, um aumento de dez vezes face aos seis milh\u00f5es reportados no mesmo per\u00edodo do ano passado.De acordo com um comunicado enviado \u00e0 Comiss\u00e3o do Mercado de Valores Mobili\u00e1rios (CMVM), o BPI registou um lucro consolidado de 60 milh\u00f5es de euros [&hellip;]","og_url":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/","og_site_name":"Hot News in World","article_published_time":"2021-05-10T13:00:33+00:00","article_modified_time":"2021-05-10T13:00:37+00:00","og_image":[{"width":800,"height":420,"url":"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg","type":"image\/jpeg"}],"author":"hotnewsinworld","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hotnewsinworld","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#article","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/"},"author":{"name":"hotnewsinworld","@id":"https:\/\/hotnewsinworld.com\/pt\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"headline":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es","datePublished":"2021-05-10T13:00:33+00:00","dateModified":"2021-05-10T13:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/"},"wordCount":310,"commentCount":0,"image":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg","articleSection":["\u00daLTIMAS NOT\u00cdCIAS FINANCEIRAS"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/","url":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/","name":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es - Hot News in World","isPartOf":{"@id":"https:\/\/hotnewsinworld.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#primaryimage"},"image":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg","datePublished":"2021-05-10T13:00:33+00:00","dateModified":"2021-05-10T13:00:37+00:00","author":{"@id":"https:\/\/hotnewsinworld.com\/pt\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b"},"breadcrumb":{"@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#primaryimage","url":"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg","contentUrl":"https:\/\/hotnewsinworld.com\/pt\/wp-content\/uploads\/sites\/2\/2021\/05\/BPI-aumenta-lucros-em-dez-vezes-para-60-milhoes.jpg","width":800,"height":420,"caption":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/hotnewsinworld.com\/pt\/bpi-aumenta-lucros-em-dez-vezes-para-60-milhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/hotnewsinworld.com\/pt\/"},{"@type":"ListItem","position":2,"name":"BPI aumenta lucros em dez vezes para 60 milh\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/hotnewsinworld.com\/pt\/#website","url":"https:\/\/hotnewsinworld.com\/pt\/","name":"Hot News in World","description":"Hot News in World Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotnewsinworld.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/hotnewsinworld.com\/pt\/#\/schema\/person\/fe61448b21c0d59086e75fcc1f9d8f6b","name":"hotnewsinworld","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a09ac165600ce2e1c38fe593c63928eb1e6e7ba5c5a907d67787c41b3d00c14?s=96&d=mm&r=g","caption":"hotnewsinworld"},"url":"https:\/\/hotnewsinworld.com\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/posts\/3606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/comments?post=3606"}],"version-history":[{"count":1,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/posts\/3606\/revisions"}],"predecessor-version":[{"id":3608,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/posts\/3606\/revisions\/3608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/media\/3607"}],"wp:attachment":[{"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/media?parent=3606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/categories?post=3606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotnewsinworld.com\/pt\/wp-json\/wp\/v2\/tags?post=3606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}